{"id":2787,"date":"2017-12-29T13:03:32","date_gmt":"2017-12-29T12:03:32","guid":{"rendered":"http:\/\/www.asajacyl.com\/avila\/?p=2787"},"modified":"2018-02-05T14:43:33","modified_gmt":"2018-02-05T13:43:33","slug":"asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense","title":{"rendered":"ASAJA \u00c1vila denuncia un nuevo ataque de lobos a la caba\u00f1a abulense"},"content":{"rendered":"<p><strong>A un ganadero de San Mart\u00edn de la Vega del Alberche los lobos le matan un becerro de tres meses y siete d\u00edas. Cuando a punto est\u00e1 de acabar el a\u00f1o ha sufrido 8 ataques. Asaja contin\u00faa reclamando controles poblaciones reales y la dotaci\u00f3n de seguridad jur\u00eddica a la Administraci\u00f3n Regional<\/strong><\/p>\n<p>Javier Gonz\u00e1lez lleva nueve a\u00f1os dedicado al sector. Tiene a su ganado en San Mart\u00edn de la Vega del Alberche. Ayer, 28 de diciembre cuando fue a hacer su trabajo diario se encontr\u00f3 con el ganado nervioso. Se percat\u00f3 en ese momento de que pasaba algo, y tal es as\u00ed, que en breve recorrido, a tan solo 500 metros del resto de los animales, se percat\u00f3 de la existencia de un cad\u00e1ver. Era uno de sus becerros muerto. Los lobos hab\u00edan dejado su huella de nuevo en su explotaci\u00f3n. En lo que lleva de a\u00f1o lleva sufridos ocho ataques, , tres becerros de menos de tres meses, otros tres de cinco meses y otro de diez.<\/p>\n<p>Pero no solo el 2017 ha sido un a\u00f1o nefasto para Javier, el a\u00f1o 2016 lleg\u00f3 a contabilizar 16 ataques a su ganado. Y en el 2015 otra novilla de tres a\u00f1os. Es de ese animal, precisamente, del que no ha recibido a\u00fan ayuda por parte de la Administraci\u00f3n Regional.<\/p>\n<p>Apostilla Javier Gonz\u00e1lez, que por el becerro de tres meses y siete d\u00edas que han matado los c\u00e1nidos ayer, le pagar\u00e1n 650 euros, por no superar la barrera de los tres meses. Pero \u00e9l podr\u00eda obtener 750 por dicho animal. Por consiguiente, y para despedir el a\u00f1o tendr\u00e1 un nuevo pellizco a su inexistente n\u00f3mina.P\u00e9rdidas que se cuantifican hasta en el doble, si el becerro es de menos de tres meses.<\/p>\n<p>En palabras del socio de Asaja, las t\u00e9cnicas de manejo que reclaman desde Organizaciones Ecologistas, como el cierre del ganado o la existencia de mastines en las explotaciones, no es lo adecuado para el ganado extensivo.<\/p>\n<p>Entre lamentos esgrime que \u00abm\u00e1s vale que la Administraci\u00f3n Regional no pensara en otorgar subvenciones a los ganaderos para cercar al ganado, sino en controlar a una especie cineg\u00e9tica que est\u00e1 haciendo mucho da\u00f1o al sector. El caso de Javier Gonz\u00e1lez se suma al de muchos ganaderos de la zona. Recuerdan que se encuentran en l\u00ednea recta a 12 kil\u00f3metros del Parque Regional de Gredos. Lugar donde aseveran no llega el lobo, porque no les interesa a los pol\u00edticos.<\/p>\n<p>Desde Asaja \u00c1vila tienen claro que la Junta de Castilla y Le\u00f3n sigue sin atajar el problema del lobo siendo nuestro territorio uno de los m\u00e1s afectados por los ataques de los c\u00e1nidos.<\/p>\n<p>La soluci\u00f3n para este 2018 contin\u00faa siendo la reivindicaci\u00f3n que se arrastra desde hace a\u00f1os: efectuar nuevos controles poblacionales en la provincia, ante el incremento de ataques. El presidente de Asaja \u00c1vila, Joaqu\u00edn Antonio Pino no ceja en su empe\u00f1o de demandar una actualizaci\u00f3n de los baremos de las indemnizaciones por los da\u00f1os ocasionados por los lobos.<\/p>\n<p>Desde la organizaci\u00f3n agraria tienen claro que las instituciones europeas tienen que dar las herramientas jur\u00eddicas necesarias a la Consejer\u00eda de Medio Ambiente para que la palabra Norte, o Sur del Duero, no sea un quebradero de cabeza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A un ganadero de San Mart\u00edn de la Vega del Alberche los lobos le matan un becerro de tres meses y siete d\u00edas. Cuando a punto est\u00e1 de acabar el a\u00f1o ha sufrido 8 ataques. Asaja contin\u00faa reclamando controles poblaciones reales y la dotaci\u00f3n de seguridad jur\u00eddica a la Administraci\u00f3n Regional Javier Gonz\u00e1lez lleva nueve [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA \u00c1vila denuncia un nuevo ataque de lobos a la caba\u00f1a abulense - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"A un ganadero de San Mart\u00edn de la Vega del Alberche los lobos le matan un becerro de tres meses y siete d\u00edas. Cuando a punto est\u00e1 de acabar el a\u00f1o ha\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA \u00c1vila denuncia un nuevo ataque de lobos a la caba\u00f1a abulense - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"A un ganadero de San Mart\u00edn de la Vega del Alberche los lobos le matan un becerro de tres meses y siete d\u00edas. Cuando a punto est\u00e1 de acabar el a\u00f1o ha\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-29T12:03:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-05T13:43:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMG-20171228-WA0003.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense\",\"name\":\"ASAJA \u00c1vila denuncia un nuevo ataque de lobos a la caba\u00f1a abulense - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMG-20171228-WA0003.jpg\",\"datePublished\":\"2017-12-29T12:03:32+00:00\",\"dateModified\":\"2018-02-05T13:43:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"A un ganadero de San Mart\u00edn de la Vega del Alberche los lobos le matan un becerro de tres meses y siete d\u00edas. Cuando a punto est\u00e1 de acabar el a\u00f1o ha\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMG-20171228-WA0003.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMG-20171228-WA0003.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA \u00c1vila denuncia un nuevo ataque de lobos a la caba\u00f1a abulense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA \u00c1vila denuncia un nuevo ataque de lobos a la caba\u00f1a abulense - ASAJA \u00c1vila","description":"A un ganadero de San Mart\u00edn de la Vega del Alberche los lobos le matan un becerro de tres meses y siete d\u00edas. Cuando a punto est\u00e1 de acabar el a\u00f1o ha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense","og_locale":"es_ES","og_type":"article","og_title":"ASAJA \u00c1vila denuncia un nuevo ataque de lobos a la caba\u00f1a abulense - ASAJA \u00c1vila","og_description":"A un ganadero de San Mart\u00edn de la Vega del Alberche los lobos le matan un becerro de tres meses y siete d\u00edas. Cuando a punto est\u00e1 de acabar el a\u00f1o ha","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense","og_site_name":"ASAJA \u00c1vila","article_published_time":"2017-12-29T12:03:32+00:00","article_modified_time":"2018-02-05T13:43:33+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMG-20171228-WA0003.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense","name":"ASAJA \u00c1vila denuncia un nuevo ataque de lobos a la caba\u00f1a abulense - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMG-20171228-WA0003.jpg","datePublished":"2017-12-29T12:03:32+00:00","dateModified":"2018-02-05T13:43:33+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"A un ganadero de San Mart\u00edn de la Vega del Alberche los lobos le matan un becerro de tres meses y siete d\u00edas. Cuando a punto est\u00e1 de acabar el a\u00f1o ha","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMG-20171228-WA0003.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMG-20171228-WA0003.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-denuncia-nuevo-ataque-lobos-la-cabana-abulense#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA \u00c1vila denuncia un nuevo ataque de lobos a la caba\u00f1a abulense"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/2787"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=2787"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/2787\/revisions"}],"predecessor-version":[{"id":2789,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/2787\/revisions\/2789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/2788"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=2787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=2787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=2787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}