{"id":2861,"date":"2018-01-11T02:54:47","date_gmt":"2018-01-11T01:54:47","guid":{"rendered":"http:\/\/www.asajacyl.com\/avila\/?p=2861"},"modified":"2018-02-05T14:09:06","modified_gmt":"2018-02-05T13:09:06","slug":"la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante","title":{"rendered":"La mesa de la sequ\u00eda advierte que la falta de agua en el Duero sigue siendo preocupante"},"content":{"rendered":"<p><strong>Se constata un incremento en la suscripci\u00f3n del seguro ante el temor de los agricultores tras una campa\u00f1a catastr\u00f3fica<\/strong><\/p>\n<p>Se ha celebrado en la sede del Ministerio de Agricultura, en Madrid, la reuni\u00f3n del Grupo de Trabajo de la Sequ\u00eda, en el que participan adem\u00e1s de responsables del Ministerio, miembros de la AEMET, Enesa y Agroseguro, cooperativas y organizaciones agrarias, entre ellas ASAJA, y en concreto Donaciano Dujo, presidente de la OPA en Castilla y Le\u00f3n. En la reuni\u00f3n se ha constatado con datos actualizados, que, a pesar de las precipitaciones registradas los \u00faltimos d\u00edas, la falta de reservas de agua sigue preocupando en la cuenca del Duero, siendo mucho m\u00e1s grave en las provincias del norte de la Comunidad.<\/p>\n<p>En este sentido, el presidente de ASAJA de Castilla y Le\u00f3n ha advertido de la situaci\u00f3n de \u201ctotal incertidumbre que viven los regantes, tras una campa\u00f1a catastr\u00f3fica, y sin poder planificar cultivos para la pr\u00f3xima. Este a\u00f1o es m\u00e1s importante que nunca que las administraciones valoren c\u00f3mo avanzan las reservas y aporten estudios fiables sobre las disponibilidades de agua que pueda haber para el sector\u201d.<\/p>\n<p>El miedo de los agricultores ha quedado patente en las cifras de suscripci\u00f3n de seguros aportadas en la reuni\u00f3n. A nivel nacional, se ha constatado un incremento del 43% en la superficie asegurada, un 45% m\u00e1s de producci\u00f3n cubierta y un 52% m\u00e1s de p\u00f3lizas. En lo que se refiere a Castilla y Le\u00f3n, seg\u00fan los datos proporcionados por el subsecretario de Agricultura y Pesca, Alimentaci\u00f3n y Medio Ambiente, Jaime Haddad, se han asegurado cerca de 1,5 millones de hect\u00e1reas de herb\u00e1ceos de invierno, cuando lo habitual es algo m\u00e1s de un mill\u00f3n. ASAJA ha pedido a la administraci\u00f3n \u201cque ampl\u00ede sin demora el presupuesto dedicado a apoyar el aseguramiento, para que la buena noticia de la ampliaci\u00f3n del n\u00famero de p\u00f3lizas no quede empa\u00f1ada por una reducci\u00f3n de la subvenci\u00f3n que recibe cada una\u201d. En este sentido, Donaciano Dujo ha recordado que en los \u00faltimos tiempos se ha invertido el porcentaje que pone la administraci\u00f3n y el agricultor para financiar el seguro: \u201csi antes la administraci\u00f3n pon\u00eda el 60 por ciento y el agricultor el 40%, ahora es al rev\u00e9s, es el agricultor el que asume la mayor parte\u201d.<\/p>\n<p>Una vez m\u00e1s, ha habido en la reuni\u00f3n total disparidad respecto a la eficacia de las medidas aprobadas desde las administraciones para paliar las p\u00e9rdidas por sequ\u00eda. Tal como ya hab\u00eda denunciado ASAJA, solo se ha aprobado un 70 por ciento de los pr\u00e9stamos que el sector ha pedido, dejando fuera a los m\u00e1s j\u00f3venes y los que m\u00e1s necesitaban este apoyo. Se espera que pr\u00f3ximamente se apruebe la orden de reducci\u00f3n de m\u00f3dulos, algo que ASAJA juzga positivamente, al contrario que el aplazamiento del canon de la Seguridad Social, que resulta in\u00fatil. Tambi\u00e9n ha lamentado el presidente de la OPA que no se haya extendido la exenci\u00f3n de tarifas de riego a todas las cuencas de Castilla y Le\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se constata un incremento en la suscripci\u00f3n del seguro ante el temor de los agricultores tras una campa\u00f1a catastr\u00f3fica Se ha celebrado en la sede del Ministerio de Agricultura, en Madrid, la reuni\u00f3n del Grupo de Trabajo de la Sequ\u00eda, en el que participan adem\u00e1s de responsables del Ministerio, miembros de la AEMET, Enesa y [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La mesa de la sequ\u00eda advierte que la falta de agua en el Duero sigue siendo preocupante - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"Se constata un incremento en la suscripci\u00f3n del seguro ante el temor de los agricultores tras una campa\u00f1a catastr\u00f3fica Se ha celebrado en la sede del\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La mesa de la sequ\u00eda advierte que la falta de agua en el Duero sigue siendo preocupante - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"Se constata un incremento en la suscripci\u00f3n del seguro ante el temor de los agricultores tras una campa\u00f1a catastr\u00f3fica Se ha celebrado en la sede del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-11T01:54:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-05T13:09:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/sequia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante\",\"name\":\"La mesa de la sequ\u00eda advierte que la falta de agua en el Duero sigue siendo preocupante - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/sequia-1.jpg\",\"datePublished\":\"2018-01-11T01:54:47+00:00\",\"dateModified\":\"2018-02-05T13:09:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"Se constata un incremento en la suscripci\u00f3n del seguro ante el temor de los agricultores tras una campa\u00f1a catastr\u00f3fica Se ha celebrado en la sede del\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/sequia-1.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/sequia-1.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La mesa de la sequ\u00eda advierte que la falta de agua en el Duero sigue siendo preocupante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La mesa de la sequ\u00eda advierte que la falta de agua en el Duero sigue siendo preocupante - ASAJA \u00c1vila","description":"Se constata un incremento en la suscripci\u00f3n del seguro ante el temor de los agricultores tras una campa\u00f1a catastr\u00f3fica Se ha celebrado en la sede del","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante","og_locale":"es_ES","og_type":"article","og_title":"La mesa de la sequ\u00eda advierte que la falta de agua en el Duero sigue siendo preocupante - ASAJA \u00c1vila","og_description":"Se constata un incremento en la suscripci\u00f3n del seguro ante el temor de los agricultores tras una campa\u00f1a catastr\u00f3fica Se ha celebrado en la sede del","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante","og_site_name":"ASAJA \u00c1vila","article_published_time":"2018-01-11T01:54:47+00:00","article_modified_time":"2018-02-05T13:09:06+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/sequia-1.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante","name":"La mesa de la sequ\u00eda advierte que la falta de agua en el Duero sigue siendo preocupante - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/sequia-1.jpg","datePublished":"2018-01-11T01:54:47+00:00","dateModified":"2018-02-05T13:09:06+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"Se constata un incremento en la suscripci\u00f3n del seguro ante el temor de los agricultores tras una campa\u00f1a catastr\u00f3fica Se ha celebrado en la sede del","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/sequia-1.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/sequia-1.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/la-mesa-la-sequia-advierte-la-falta-agua-duero-sigue-siendo-preocupante#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"La mesa de la sequ\u00eda advierte que la falta de agua en el Duero sigue siendo preocupante"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/2861"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=2861"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/2861\/revisions"}],"predecessor-version":[{"id":2865,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/2861\/revisions\/2865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/2864"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=2861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=2861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=2861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}