{"id":2890,"date":"2018-01-17T12:51:55","date_gmt":"2018-01-17T11:51:55","guid":{"rendered":"http:\/\/www.asajacyl.com\/avila\/?p=2890"},"modified":"2018-02-05T14:07:26","modified_gmt":"2018-02-05T13:07:26","slug":"asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton","title":{"rendered":"ASAJA-\u00c1vila exige mayor compromiso con el sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n"},"content":{"rendered":"<p><strong>El sector agroganadero contribuye a crear riqueza y empleo en la provincia y es hora de comenzar a reconoc\u00e9rselo<\/strong><\/p>\n<p>Con motivo de la celebraci\u00f3n hoy mi\u00e9rcoles, 17 de enero, de la festividad de San Ant\u00f3n, santo protector de los animales y patr\u00f3n de los ganaderos, la Asociaci\u00f3n Agraria <em>J\u00f3venes Agricultores<\/em> (ASAJA) de \u00c1vila subraya las necesidades que soportan los profesionales del campo. Por este motivo la organizaci\u00f3n solicita a las administraciones un mayor compromiso con un sector, que aporta un importante porcentaje al PIB de la provincia, vertebra el territorio y mantiene las tradiciones y el medioambiente.<\/p>\n<p>El reci\u00e9n concluido 2017 ha sido un a\u00f1o nefasto para ganaderos y agricultores, que han visto como a consecuencia de la sequ\u00eda sus rentas han disminuido y la Junta de Castilla y Le\u00f3n ha vendido humo, dejando adem\u00e1s campar a sus anchas a la Banca y no poniendo en marcha ayudas directas que demandaba y sigue demandando ASAJA.<\/p>\n<p>Adem\u00e1s es necesario la puesta en marcha medidas de control que eviten los permanentes da\u00f1os causados por la fauna sobre el ganado (en especial el lobo) y la actualizaci\u00f3n de los baremos de indemnizaci\u00f3n, as\u00ed como la gesti\u00f3n de las campa\u00f1as de saneamiento, cuyos efectos, a veces desproporcionados, son uno de los principales temores de los profesionales del sector.<\/p>\n<p>Por otro lado, el sector sigue envuelto en cotizaciones desiguales, en una crisis de precios que no se resuelve, sirva como ejemplo en el sector de la leche en el que se est\u00e1 pagando muy por debajo de la media percibida por los productores europeos, o la situaci\u00f3n de cotizaciones de la leche de ovino y caprino.<\/p>\n<p>ASAJA exige a la administraci\u00f3n regional que empuje y ayude al sector ganadero que es soporte, asimismo, de la industria agroalimentaria, genera empleo y ocupa un territorio marginado y deprimido, a causa de los graves problemas de despoblaci\u00f3n del territorio.<\/p>\n<p>El presidente provincial de ASAJA-\u00c1vila, Joaqu\u00edn Antonio Pino, se\u00f1al\u00f3 que el d\u00eda de San Ant\u00f3n es una efem\u00e9ride para felicitar a un sector ganadero que sobrevive gracias a su propio empe\u00f1o y no porque se les ayude, exigiendo a las Administraciones un compromiso real, presupuesto y soluci\u00f3n a la crisis de precios para los profesionales del campo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sector agroganadero contribuye a crear riqueza y empleo en la provincia y es hora de comenzar a reconoc\u00e9rselo Con motivo de la celebraci\u00f3n hoy mi\u00e9rcoles, 17 de enero, de la festividad de San Ant\u00f3n, santo protector de los animales y patr\u00f3n de los ganaderos, la Asociaci\u00f3n Agraria J\u00f3venes Agricultores (ASAJA) de \u00c1vila subraya las [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA-\u00c1vila exige mayor compromiso con el sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"El sector agroganadero contribuye a crear riqueza y empleo en la provincia y es hora de comenzar a reconoc\u00e9rselo Con motivo de la celebraci\u00f3n hoy\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA-\u00c1vila exige mayor compromiso con el sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"El sector agroganadero contribuye a crear riqueza y empleo en la provincia y es hora de comenzar a reconoc\u00e9rselo Con motivo de la celebraci\u00f3n hoy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-17T11:51:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-05T13:07:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/GANADERIA3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton\",\"name\":\"ASAJA-\u00c1vila exige mayor compromiso con el sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/GANADERIA3.jpg\",\"datePublished\":\"2018-01-17T11:51:55+00:00\",\"dateModified\":\"2018-02-05T13:07:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"El sector agroganadero contribuye a crear riqueza y empleo en la provincia y es hora de comenzar a reconoc\u00e9rselo Con motivo de la celebraci\u00f3n hoy\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/GANADERIA3.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/GANADERIA3.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA-\u00c1vila exige mayor compromiso con el sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA-\u00c1vila exige mayor compromiso con el sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n - ASAJA \u00c1vila","description":"El sector agroganadero contribuye a crear riqueza y empleo en la provincia y es hora de comenzar a reconoc\u00e9rselo Con motivo de la celebraci\u00f3n hoy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton","og_locale":"es_ES","og_type":"article","og_title":"ASAJA-\u00c1vila exige mayor compromiso con el sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n - ASAJA \u00c1vila","og_description":"El sector agroganadero contribuye a crear riqueza y empleo en la provincia y es hora de comenzar a reconoc\u00e9rselo Con motivo de la celebraci\u00f3n hoy","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton","og_site_name":"ASAJA \u00c1vila","article_published_time":"2018-01-17T11:51:55+00:00","article_modified_time":"2018-02-05T13:07:26+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/GANADERIA3.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton","name":"ASAJA-\u00c1vila exige mayor compromiso con el sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/GANADERIA3.jpg","datePublished":"2018-01-17T11:51:55+00:00","dateModified":"2018-02-05T13:07:26+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"El sector agroganadero contribuye a crear riqueza y empleo en la provincia y es hora de comenzar a reconoc\u00e9rselo Con motivo de la celebraci\u00f3n hoy","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/GANADERIA3.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/01\/GANADERIA3.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-avila-exige-mayor-compromiso-sector-ganadero-dia-patron-san-anton#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA-\u00c1vila exige mayor compromiso con el sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/2890"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=2890"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/2890\/revisions"}],"predecessor-version":[{"id":2893,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/2890\/revisions\/2893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/2891"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=2890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=2890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=2890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}