{"id":3813,"date":"2018-05-30T13:33:19","date_gmt":"2018-05-30T11:33:19","guid":{"rendered":"http:\/\/www.asajacyl.com\/avila\/?p=3813"},"modified":"2018-06-04T09:04:31","modified_gmt":"2018-06-04T07:04:31","slug":"asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas","title":{"rendered":"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas"},"content":{"rendered":"<div class=\"td-full-screen-header-image-wrap\">\n<div class=\"td-container td-post-header\">\n<div class=\"td-post-header-holder\">\n<header class=\"td-post-title\">\n<h1 class=\"entry-title\">ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas, con verdadero peso en la cadena agroalimentaria.<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11628 alignright td-animation-stack-type0-2\" src=\"http:\/\/www.asajacyl.com\/wp-content\/uploads\/2018\/05\/face-cortes1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/h1>\n<\/header>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"td-container\">\n<div class=\"td-pb-row\">\n<div class=\"td-pb-span12 td-main-content\" role=\"main\">\n<div class=\"td-ss-main-content\">\n<div class=\"td-post-content\">\n<p>Hoy se espera que las Cortes de Castilla y Le\u00f3n refrenden la modificaci\u00f3n de la Ley de Cooperativas, con especial incidencia en las del sector agrario y ganadero, que suponen aproximadamente 570 del total de 2.092 cooperativas registradas en la Comunidad Aut\u00f3noma.<\/p>\n<p>ASAJA subraya que para el sector agrario y ganadero las cooperativas son un elemento vertebrador imprescindible, fundamentalmente por su labor en la comercializaci\u00f3n, la m\u00e1s compleja para la explotaci\u00f3n agroganadera y en la que el profesional del campo est\u00e1 m\u00e1s indefenso al tener que competir en un mercado cada vez m\u00e1s agresivo, dominado por multinacionales y grandes superficies.<\/p>\n<p>\u201cHay que esperar que estos cambios en la normativa sirvan de acicate para que las cooperativas tengan mayor peso en la cadena alimentaria, lo que es un objetivo posible sobre todo en sectores como la leche de ovino, en los que la parte fundamental de la producci\u00f3n pasa por cooperativa\u201d, se\u00f1ala ASAJA. Las cooperativas tienen que ser, por fin, motor en las operaciones comerciales del sector agroganadero, y no conformarse con ser un mero intermediario de compras y ventas, a cambio de un margen. Del \u00e9xito de las cooperativas en la obtenci\u00f3n de precios rentables para los productos agroganaderos depende que los cooperativistas logren a su vez mayores beneficios, lo que redundar\u00e1 en un aumento de la rentabilidad de las explotaciones agr\u00edcolas y ganaderas de Castilla y Le\u00f3n.<\/p>\n<p>El sector demanda de sus cooperativas un redimensionamiento que les fortaleza y les permita ser competitivas, as\u00ed como una profesionalizaci\u00f3n de sus estructuras y rejuvenecimiento de sus equipos directivos para afrontar con \u00e9xito los retos presentes y futuros, optimizando costes, innovando, aprovechando las posibilidades de la exportaci\u00f3n, hoy por hoy fundamental para nuestro sector, etc.<\/p>\n<p>Cooperativas y organizaciones agrarias constituyen dos herramientas imprescindibles en la defensa de la agricultura y ganader\u00eda, y en Europa est\u00e1n bien definidos los papeles, muy diferentes, que tienen que desempe\u00f1ar. Tienen ambas partes la obligaci\u00f3n de tener unas buenas relaciones, como se ha logrado en los pa\u00edses m\u00e1s punteros de la agricultura de la UE, respetando el papel que cada parte ha de cumplir, porque ese trabajo arm\u00f3nico es lo m\u00e1s fruct\u00edfero para defender a los agricultores y ganaderos.<\/p>\n<p>El hecho de que esta renovada Ley nazca con un importante consenso, similar al logrado cuando las Cortes aprobaron la Ley Agraria, \u201cnos hace desear que en adelante los responsables pol\u00edticos aporten todos los elementos necesarios para que esta normativa sea correctamente desarrollada para que su ejecuci\u00f3n sea un \u00e9xito\u201d, apunta ASAJA, que pide a la Junta que se vuelque en el apoyo a f\u00f3rmulas, cooperativas o de otro tipo, que promuevan proyectos colectivos en el sector agroganadero.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas, con verdadero peso en la cadena agroalimentaria. Hoy se espera que las Cortes de Castilla y Le\u00f3n refrenden la modificaci\u00f3n de la Ley de Cooperativas, con especial incidencia en las del sector agrario y ganadero, que suponen aproximadamente 570 del total de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":3814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas, con verdadero peso en la cadena agroalimentaria. Hoy se\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas, con verdadero peso en la cadena agroalimentaria. Hoy se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-30T11:33:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-04T07:04:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/05\/ICAL389990.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas\",\"name\":\"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/05\/ICAL389990.jpg\",\"datePublished\":\"2018-05-30T11:33:19+00:00\",\"dateModified\":\"2018-06-04T07:04:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas, con verdadero peso en la cadena agroalimentaria. Hoy se\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/05\/ICAL389990.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/05\/ICAL389990.jpg\",\"width\":2500,\"height\":1325},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas - ASAJA \u00c1vila","description":"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas, con verdadero peso en la cadena agroalimentaria. Hoy se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas","og_locale":"es_ES","og_type":"article","og_title":"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas - ASAJA \u00c1vila","og_description":"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas, con verdadero peso en la cadena agroalimentaria. Hoy se","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas","og_site_name":"ASAJA \u00c1vila","article_published_time":"2018-05-30T11:33:19+00:00","article_modified_time":"2018-06-04T07:04:31+00:00","og_image":[{"width":2500,"height":1325,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/05\/ICAL389990.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas","name":"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/05\/ICAL389990.jpg","datePublished":"2018-05-30T11:33:19+00:00","dateModified":"2018-06-04T07:04:31+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas, con verdadero peso en la cadena agroalimentaria. Hoy se","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/05\/ICAL389990.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/05\/ICAL389990.jpg","width":2500,"height":1325},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-considera-la-renovada-ley-propiciar-unas-cooperativas-modernas-competitivas#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA considera que la renovada ley debe propiciar unas cooperativas modernas y competitivas"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/3813"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=3813"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/3813\/revisions"}],"predecessor-version":[{"id":3815,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/3813\/revisions\/3815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/3814"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=3813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=3813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=3813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}