{"id":3970,"date":"2018-07-18T16:45:56","date_gmt":"2018-07-18T14:45:56","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=3970"},"modified":"2018-07-18T16:45:56","modified_gmt":"2018-07-18T14:45:56","slug":"ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios","title":{"rendered":"Ayudas a la afiliaci\u00f3n de mujeres del medio rural al r\u00e9gimen especial para trabajadores por cuenta propia agrarios"},"content":{"rendered":"<p><strong>El plazo de presentaci\u00f3n de solicitudes ser\u00e1 del 1 al 29 de octubre.<\/strong><\/p>\n<div class=\"td-container\">\n<div class=\"td-pb-row\">\n<div class=\"td-pb-span12 td-main-content\" role=\"main\">\n<div class=\"td-ss-main-content\">\n<div class=\"td-post-content\">\n<p>Este a\u00f1o, la Consejer\u00eda de Empleo de la Junta de Castilla y Le\u00f3n ha modificado la normativa que regular\u00e1 las subvenciones para el a\u00f1o 2018 dirigidas a promover la afiliaci\u00f3n de las mujeres del medio rural en el r\u00e9gimen especial de trabajadores por cuenta propia o aut\u00f3nomos, a trav\u00e9s del sistema especial para trabajadores por cuenta propia agrarios. A partir de esta convocatoria, no habr\u00e1 l\u00edmites por edad.<\/p>\n<p>De esta l\u00ednea, que consiste en un porcentaje de ayuda sobre las cuotas de la Seguridad Social, podr\u00e1n ser beneficiarias las mujeres del medio rural que se den de alta en el R\u00e9gimen Especial de los Trabajadores por Cuenta Propia o Aut\u00f3nomos durante el periodo interanual 2017-2018 que se marque en la pr\u00f3xima convocatoria.<\/p>\n<p><strong>En esta nueva convocatoria han quitado el requisito de tener 45 a\u00f1os o menos en el momento de la incorporaci\u00f3n al Sistema Especial para Trabajadores por Cuenta Propia Agrarios de la Seguridad Social.<\/strong> Debido a esto han creado un nuevo grupo, para las mujeres con 55 a\u00f1os o m\u00e1s y aquellas que tengan la condici\u00f3n de v\u00edctimas del terrorismo o de violencia de g\u00e9nero, independientemente de su edad, que se subvenciona con un 75%. El segundo grupo, que tiene un 50% de ayuda, incluye a las mujeres de 41 hasta 54 a\u00f1os.<\/p>\n<p>El plazo de presentaci\u00f3n de solicitudes ser\u00e1 del 1 al 29 de octubre.<\/p>\n<p><a href=\"http:\/\/bocyl.jcyl.es\/boletines\/2018\/06\/27\/pdf\/BOCYL-D-27062018-6.pdf\">Ver bolet\u00edn<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El plazo de presentaci\u00f3n de solicitudes ser\u00e1 del 1 al 29 de octubre. Este a\u00f1o, la Consejer\u00eda de Empleo de la Junta de Castilla y Le\u00f3n ha modificado la normativa que regular\u00e1 las subvenciones para el a\u00f1o 2018 dirigidas a promover la afiliaci\u00f3n de las mujeres del medio rural en el r\u00e9gimen especial de trabajadores [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,46,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ayudas a la afiliaci\u00f3n de mujeres del medio rural al r\u00e9gimen especial para trabajadores por cuenta propia agrarios - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"El plazo de presentaci\u00f3n de solicitudes ser\u00e1 del 1 al 29 de octubre. Este a\u00f1o, la Consejer\u00eda de Empleo de la Junta de Castilla y Le\u00f3n ha modificado la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ayudas a la afiliaci\u00f3n de mujeres del medio rural al r\u00e9gimen especial para trabajadores por cuenta propia agrarios - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"El plazo de presentaci\u00f3n de solicitudes ser\u00e1 del 1 al 29 de octubre. Este a\u00f1o, la Consejer\u00eda de Empleo de la Junta de Castilla y Le\u00f3n ha modificado la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-18T14:45:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios\",\"name\":\"Ayudas a la afiliaci\u00f3n de mujeres del medio rural al r\u00e9gimen especial para trabajadores por cuenta propia agrarios - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2018-07-18T14:45:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"El plazo de presentaci\u00f3n de solicitudes ser\u00e1 del 1 al 29 de octubre. Este a\u00f1o, la Consejer\u00eda de Empleo de la Junta de Castilla y Le\u00f3n ha modificado la\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA \u00c1vila\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ayudas a la afiliaci\u00f3n de mujeres del medio rural al r\u00e9gimen especial para trabajadores por cuenta propia agrarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ayudas a la afiliaci\u00f3n de mujeres del medio rural al r\u00e9gimen especial para trabajadores por cuenta propia agrarios - ASAJA \u00c1vila","description":"El plazo de presentaci\u00f3n de solicitudes ser\u00e1 del 1 al 29 de octubre. Este a\u00f1o, la Consejer\u00eda de Empleo de la Junta de Castilla y Le\u00f3n ha modificado la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios","og_locale":"es_ES","og_type":"article","og_title":"Ayudas a la afiliaci\u00f3n de mujeres del medio rural al r\u00e9gimen especial para trabajadores por cuenta propia agrarios - ASAJA \u00c1vila","og_description":"El plazo de presentaci\u00f3n de solicitudes ser\u00e1 del 1 al 29 de octubre. Este a\u00f1o, la Consejer\u00eda de Empleo de la Junta de Castilla y Le\u00f3n ha modificado la","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios","og_site_name":"ASAJA \u00c1vila","article_published_time":"2018-07-18T14:45:56+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios","name":"Ayudas a la afiliaci\u00f3n de mujeres del medio rural al r\u00e9gimen especial para trabajadores por cuenta propia agrarios - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2018-07-18T14:45:56+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"El plazo de presentaci\u00f3n de solicitudes ser\u00e1 del 1 al 29 de octubre. Este a\u00f1o, la Consejer\u00eda de Empleo de la Junta de Castilla y Le\u00f3n ha modificado la","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA \u00c1vila"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/ayudas-la-afiliacion-mujeres-del-medio-rural-al-regimen-especial-trabajadores-cuenta-agrarios#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"Ayudas a la afiliaci\u00f3n de mujeres del medio rural al r\u00e9gimen especial para trabajadores por cuenta propia agrarios"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/3970"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=3970"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/3970\/revisions"}],"predecessor-version":[{"id":3971,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/3970\/revisions\/3971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/794"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=3970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=3970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=3970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}