{"id":3981,"date":"2018-07-20T15:40:34","date_gmt":"2018-07-20T13:40:34","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=3981"},"modified":"2018-08-08T16:06:40","modified_gmt":"2018-08-08T14:06:40","slug":"primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon","title":{"rendered":"Primera reuni\u00f3n de la delegada del gobierno con la directiva de ASAJA de Castilla y Le\u00f3n"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>ASAJA pide a Virginia Barcones que ejerza como \u201ccorreo y altavoz\u201d de las demandas del campo de Castilla y Le\u00f3n para que se escuchen en Madrid<\/strong><\/p>\n<div class=\"td-container\">\n<div class=\"td-pb-row\">\n<div class=\"td-pb-span12 td-main-content\" role=\"main\">\n<div class=\"td-ss-main-content\">\n<div class=\"td-post-content\">\n<figure id=\"attachment_11866\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11866 td-animation-stack-type0-2\" src=\"https:\/\/www.asajacyl.com\/wp-content\/uploads\/2018\/07\/foto-delegada-0-300x209.jpg\" alt=\"\" width=\"300\" height=\"209\" \/><figcaption class=\"wp-caption-text\">La delegada del Gobierno, con ASAJA<\/figcaption><\/figure>\n<p>La Junta Directiva de ASAJA de Castilla y Le\u00f3n, constituida por los responsables de la organizaci\u00f3n en las diferentes provincias m\u00e1s el presidente y secretario regionales, Donaciano Dujo y Jos\u00e9 Antonio Turrado, ha celebrado hoy un primer encuentro institucional con la nueva responsable de la Delegaci\u00f3n del Gobierno en la Comunidad Aut\u00f3noma, Virginia Barcones.<\/p>\n<p>En un momento clave en el que se est\u00e1 negociando la futura PAC, ASAJA considera clave el papel de la delegada del Gobierno para que tenga siempre en cuenta sus or\u00edgenes rurales y se constituya en \u201ccorreo y altavoz\u201d eficaz que transmita las demandas de los agricultores y ganaderos de Castilla y Le\u00f3n, demandas que pasan en primer lugar por el mantenimiento del presupuesto que Europa destina al sector agroganadero.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11868 alignleft td-animation-stack-type0-2\" src=\"https:\/\/www.asajacyl.com\/wp-content\/uploads\/2018\/07\/foto-delegada-1-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" \/>Adem\u00e1s, ASAJA ha defendido una estrategia hidr\u00e1ulica que pase por modernizar el regad\u00edo y tambi\u00e9n por aumentar las reservas, invirtiendo en nuevas capacidades de almacenamiento all\u00ed donde haya posibilidades y exista demanda. Tambi\u00e9n ha pedido la OPA a Virginia Barcones que propicie la interlocuci\u00f3n con el nuevo Ministerio para la Transici\u00f3n Ecol\u00f3gica, \u201cporque es fundamental que se entienda el compromiso del sector agroganadero con el medioambiente y la biodiversidad. Y en concreto, desde ASAJA estamos trabajando para impulsar iniciativas que frenen el cambio clim\u00e1tico, puesto que nuestro sector es el primer perjudicado\u201d, ha indicado Donaciano Dujo.<\/p>\n<p>ASAJA ha expresado a Barcones su preocupaci\u00f3n por la posibilidad de que se graven con m\u00e1s impuestos a los carburantes, as\u00ed como por las limitaciones en el uso del di\u00e9sel, que hoy por hoy mueve todos los motores de maquinaria agr\u00edcola. Para la OPA, \u201ccualquier cambio de ese calado exige un consenso a nivel europeo o incluso mundial, no se trata de tomar caminos precipitados que solo nos gravar\u00edan a nosotros y no lograr\u00edan avances significativos en la mejora de las emisiones\u201d, ha manifestado Donaciano Dujo. <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11867 alignright td-animation-stack-type0-2\" src=\"https:\/\/www.asajacyl.com\/wp-content\/uploads\/2018\/07\/foto-delegada-2-300x219.jpg\" alt=\"\" width=\"300\" height=\"219\" \/><\/p>\n<p>En otro de los cap\u00edtulos que dependen de la Administraci\u00f3n central, el de las pensiones, ASAJA ha pedido que desde Castilla y Le\u00f3n se defiendan las especificidades y necesidades del sector agroganadero, que percibe pensiones muy inferiores a la media. Tal como ha recalcado ASAJA, contar con una jubilaci\u00f3n digna es imprescindible para que haya una correcta transmisi\u00f3n de las explotaciones y derechos PAC, lo que favorece la entrada de j\u00f3venes y tambi\u00e9n de mujeres al sector, vital para mantener un medio rural vivo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3982 alignright\" src=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-grupo-240x300.jpg\" alt=\"\" width=\"152\" height=\"190\" srcset=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-grupo-240x300.jpg 240w, https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-grupo-768x960.jpg 768w, https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-grupo-820x1024.jpg 820w, https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-grupo-696x870.jpg 696w, https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-grupo-1068x1334.jpg 1068w, https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-grupo-336x420.jpg 336w, https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-grupo-1920x2399.jpg 1920w, https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-grupo.jpg 2001w\" sizes=\"(max-width: 152px) 100vw, 152px\" \/>A parte de otros temas netamente profesionales, los responsables de ASAJA han transmitido a Virginia Barcones su preocupaci\u00f3n por la inseguridad en el medio rural. \u201cEn los pueblos reside sobre todo gente mayor para la que es muy importante saber que no est\u00e1n solos, saber que los agentes de la Guardia Civil est\u00e1 cerca y les protege. Y lo mismo ocurre en las zonas de regad\u00edo, donde los robos son continuos\u201d.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; ASAJA pide a Virginia Barcones que ejerza como \u201ccorreo y altavoz\u201d de las demandas del campo de Castilla y Le\u00f3n para que se escuchen en Madrid La delegada del Gobierno, con ASAJA La Junta Directiva de ASAJA de Castilla y Le\u00f3n, constituida por los responsables de la organizaci\u00f3n en las diferentes provincias m\u00e1s el [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":3985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Primera reuni\u00f3n de la delegada del gobierno con la directiva de ASAJA de Castilla y Le\u00f3n - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"&nbsp; ASAJA pide a Virginia Barcones que ejerza como \u201ccorreo y altavoz\u201d de las demandas del campo de Castilla y Le\u00f3n para que se escuchen en Madrid La\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primera reuni\u00f3n de la delegada del gobierno con la directiva de ASAJA de Castilla y Le\u00f3n - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"&nbsp; ASAJA pide a Virginia Barcones que ejerza como \u201ccorreo y altavoz\u201d de las demandas del campo de Castilla y Le\u00f3n para que se escuchen en Madrid La\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-20T13:40:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-08T14:06:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-delegada-0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1743\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon\",\"name\":\"Primera reuni\u00f3n de la delegada del gobierno con la directiva de ASAJA de Castilla y Le\u00f3n - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-delegada-0.jpg\",\"datePublished\":\"2018-07-20T13:40:34+00:00\",\"dateModified\":\"2018-08-08T14:06:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"&nbsp; ASAJA pide a Virginia Barcones que ejerza como \u201ccorreo y altavoz\u201d de las demandas del campo de Castilla y Le\u00f3n para que se escuchen en Madrid La\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-delegada-0.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-delegada-0.jpg\",\"width\":2500,\"height\":1743},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primera reuni\u00f3n de la delegada del gobierno con la directiva de ASAJA de Castilla y Le\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primera reuni\u00f3n de la delegada del gobierno con la directiva de ASAJA de Castilla y Le\u00f3n - ASAJA \u00c1vila","description":"&nbsp; ASAJA pide a Virginia Barcones que ejerza como \u201ccorreo y altavoz\u201d de las demandas del campo de Castilla y Le\u00f3n para que se escuchen en Madrid La","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon","og_locale":"es_ES","og_type":"article","og_title":"Primera reuni\u00f3n de la delegada del gobierno con la directiva de ASAJA de Castilla y Le\u00f3n - ASAJA \u00c1vila","og_description":"&nbsp; ASAJA pide a Virginia Barcones que ejerza como \u201ccorreo y altavoz\u201d de las demandas del campo de Castilla y Le\u00f3n para que se escuchen en Madrid La","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon","og_site_name":"ASAJA \u00c1vila","article_published_time":"2018-07-20T13:40:34+00:00","article_modified_time":"2018-08-08T14:06:40+00:00","og_image":[{"width":2500,"height":1743,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-delegada-0.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon","name":"Primera reuni\u00f3n de la delegada del gobierno con la directiva de ASAJA de Castilla y Le\u00f3n - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-delegada-0.jpg","datePublished":"2018-07-20T13:40:34+00:00","dateModified":"2018-08-08T14:06:40+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"&nbsp; ASAJA pide a Virginia Barcones que ejerza como \u201ccorreo y altavoz\u201d de las demandas del campo de Castilla y Le\u00f3n para que se escuchen en Madrid La","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-delegada-0.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/foto-delegada-0.jpg","width":2500,"height":1743},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/primera-reunion-la-delegada-del-gobierno-la-directiva-asaja-castilla-leon#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"Primera reuni\u00f3n de la delegada del gobierno con la directiva de ASAJA de Castilla y Le\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/3981"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=3981"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/3981\/revisions"}],"predecessor-version":[{"id":3984,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/3981\/revisions\/3984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/3985"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=3981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=3981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=3981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}