{"id":3986,"date":"2018-07-23T20:39:07","date_gmt":"2018-07-23T18:39:07","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=3986"},"modified":"2018-08-08T16:07:48","modified_gmt":"2018-08-08T14:07:48","slug":"manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos","title":{"rendered":"Se abre el plazo para pedir las ayudas a la reestructuraci\u00f3n y reconversi\u00f3n de vi\u00f1edos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>ASAJA asesora a los viticultores para presentar sus solicitudes antes del 23 de agosto.<\/strong><\/p>\n<div class=\"td-container\">\n<div class=\"td-pb-row\">\n<div class=\"td-pb-span12 td-main-content\" role=\"main\">\n<div class=\"td-ss-main-content\">\n<div class=\"td-post-content\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11877 alignright td-animation-stack-type0-2\" src=\"https:\/\/www.asajacyl.com\/wp-content\/uploads\/2018\/07\/DSC_0051-2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/>Ma\u00f1ana martes 24 de julio se abre la esperada convocatoria de ayudas a la reestructuraci\u00f3n y reconversi\u00f3n de vi\u00f1edos de Castilla y Le\u00f3n para la campa\u00f1a vit\u00edcola 2018\/19. ASAJA, que asesora desde sus oficinas a los agricultores que desean solicitar las ayudas, \u00a0llevaba tiempo pidiendo insistentemente esta convocatoria, transcurridos casi dos a\u00f1os desde la \u00faltima.<\/p>\n<p>El plazo de presentaci\u00f3n de las solicitudes finaliza el d\u00eda 23 de agosto y deben describir todas las operaciones a realizar as\u00ed como la fecha prevista de finalizaci\u00f3n de ejecuci\u00f3n.<\/p>\n<p>Aquellos viticultores que deseen plantar vi\u00f1edo y optar a estas ayudas podr\u00e1n realizar la conversi\u00f3n de sus derechos vigentes hasta 31 de diciembre de 2020 en autorizaciones de plantaci\u00f3n, o bien, tendr\u00e1n la opci\u00f3n de arrancar vi\u00f1edo viejo propio para as\u00ed obtener la autorizaci\u00f3n de replantaci\u00f3n para la nueva plantaci\u00f3n.<\/p>\n<p>A continuaci\u00f3n, extractamos las principales novedades de las ayudas que a partir de ma\u00f1ana pueden solicitarse. Para cualquier duda, los interesados pueden acudir a las oficinas de ASAJA.<\/p>\n<p><strong>Prioridades<\/strong><\/p>\n<p>Se dar\u00e1 prioridad, para todo el territorio nacional, a los solicitantes menores de 40 a\u00f1os; a las solicitudes colectivas y a las procedentes de explotaciones de titularidad compartida. Tambi\u00e9n habr\u00e1 prioridad para mujeres, explotaciones ecol\u00f3gicas, cooperativas y SAT.<\/p>\n<p><strong>Operaciones subvencionables<\/strong><\/p>\n<p>Dentro de la medida de <strong><u>reimplantaci\u00f3n de vi\u00f1edo<\/u><\/strong> son subvencionables el arranque (incluida la recogida de cepas), la preparaci\u00f3n del suelo, la desinfecci\u00f3n del terreno, la nivelaci\u00f3n del terreno, la adquisici\u00f3n de planta y plantaci\u00f3n, la protecci\u00f3n individual de plantas contra conejos en el momento de la plantaci\u00f3n (incluida la colocaci\u00f3n) y la espaldera (incluida la colocaci\u00f3n), conforme a las caracter\u00edsticas descritas en la orden.<\/p>\n<p>Dentro de \u00a0la medida de <strong><u>mejora de las t\u00e9cnicas de gesti\u00f3n<\/u><\/strong> se ayuda la operaci\u00f3n de transformaci\u00f3n de vaso en espaldera y solo tendr\u00e1n derecho a la ayuda, la superficie de las plantaciones de vi\u00f1edo inscritas en la secci\u00f3n vit\u00edcola del REACYL\u00a0 antes del 1 de agosto de 2016 a nombre del viticultor solicitante.<\/p>\n<p>Tambi\u00e9n se apoya la <strong><u>reconversi\u00f3n varietal de vi\u00f1edo<\/u><\/strong> consider\u00e1ndose los costes reflejados como sobreinjertado, que se compone de un coste por unidad de injerto. Se considera la unidad de injerto como el practicado sobre una cepa, independientemente del n\u00famero de p\u00faas a injertar en la misma.<\/p>\n<p><strong>Cuant\u00eda de las ayudas y l\u00edmites<\/strong><\/p>\n<p>El presupuesto global para estas ayudas en Castilla y Le\u00f3n, para el a\u00f1o 2019, es de 7 millones de euros.<\/p>\n<p>La ayuda para participar en los costes de la reestructuraci\u00f3n y reconversi\u00f3n de vi\u00f1edos ser\u00e1 el resultado de aplicar el 50 por ciento para las solicitudes colectivas, y un 15 por ciento inferior para las solicitudes individuales, a los importes m\u00e1ximos establecidos:<\/p>\n<table width=\"663\">\n<tbody>\n<tr>\n<td colspan=\"2\" width=\"829\"><strong>OPERACIONES SUBVENCIONABLES EN LA CAMPA\u00d1A VIT\u00cdCOLA 2018\/2019<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"508\"><strong>Operaci\u00f3n<\/strong><\/td>\n<td width=\"321\"><strong>Importe m\u00e1ximo subvencionable<\/strong><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" width=\"829\"><strong>A) Reimplantaci\u00f3n de vi\u00f1edos<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"508\">1. Arranque (incluida la recogida de cepas)<\/td>\n<td width=\"321\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 430\u00a0\u00a0\u00a0\u00a0 \u20ac\/ha<\/td>\n<\/tr>\n<tr>\n<td width=\"508\">2. Nivelaci\u00f3n del terreno<\/td>\n<td width=\"321\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 800\u00a0\u00a0\u00a0\u00a0 \u20ac\/ha<\/td>\n<\/tr>\n<tr>\n<td width=\"508\">3. Preparaci\u00f3n del suelo<\/td>\n<td width=\"321\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1.400\u00a0 \u20ac\/ha<\/td>\n<\/tr>\n<tr>\n<td width=\"508\">4. Desinfecci\u00f3n<\/td>\n<td width=\"321\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2.000\u00a0 \u20ac\/ha<\/td>\n<\/tr>\n<tr>\n<td width=\"508\">5. Planta y plantaci\u00f3n<\/td>\n<td width=\"321\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1,69\u00a0\u00a0\u00a0 \u20ac\/planta<\/td>\n<\/tr>\n<tr>\n<td width=\"508\">6. Protecci\u00f3n individual de plantas contra conejos en el momento de la plantaci\u00f3n (incluida la colocaci\u00f3n)<\/td>\n<td width=\"321\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0,5\u00a0\u00a0\u00a0\u00a0\u00a0 \u20ac\/unidad<\/td>\n<\/tr>\n<tr>\n<td width=\"508\">7. Sistema de conducci\u00f3n: Espaldera (incluida colocaci\u00f3n)<\/td>\n<td width=\"321\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3.400\u00a0 \u20ac\/ha<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" width=\"829\"><strong>B) Reconversi\u00f3n de vi\u00f1edos<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"508\">1. Sobreinjertado.<\/td>\n<td width=\"321\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0,9\u00a0\u00a0\u00a0\u00a0\u00a0 \u20ac\/unidad<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" width=\"829\"><strong>C) Mejora de t\u00e9cnicas de gesti\u00f3n de vi\u00f1edos<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"508\">1. Cambio de vaso a espaldera.<\/td>\n<td width=\"321\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 4.000\u00a0 \u20ac\/ha<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>La ayuda para compensar a los viticultores por la p\u00e9rdida de ingresos para cada una de las zonas productivas de Castilla y Le\u00f3n var\u00eda seg\u00fan las provincias:<\/p>\n<table width=\"561\">\n<tbody>\n<tr>\n<td colspan=\"2\" width=\"561\"><strong>CAMPA\u00d1A VIT\u00cdCOLA 2018 \/2019<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"159\"><strong>PROVINCIA<\/strong><\/td>\n<td width=\"402\"><strong>COMPENSACI\u00d3N POR P\u00c9RDIDA DE INGRESOS<\/strong><strong>(\u20ac\/ha y campa\u00f1a)<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"159\">\u00c1vila<\/td>\n<td width=\"402\">113,29 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"159\">Burgos<\/td>\n<td width=\"402\">1.034,15 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"159\">Le\u00f3n<\/td>\n<td width=\"402\">329,29 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"159\">Palencia<\/td>\n<td width=\"402\">527,41 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"159\">Salamanca<\/td>\n<td width=\"402\">137,81 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"159\">Segovia<\/td>\n<td width=\"402\">801,70 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"159\">Soria<\/td>\n<td width=\"402\">506,44 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"159\">Valladolid<\/td>\n<td width=\"402\">982,52 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"159\">Zamora<\/td>\n<td width=\"402\">369,74 \u20ac<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Los solicitantes podr\u00e1n solicitar un anticipo de hasta el 50 por cien del importe de la ayuda inicialmente aprobada, cuando hayan constituido una garant\u00eda por un importe de al menos el 120 por cien del importe del anticipo.<\/p>\n<blockquote><p>el equipo t\u00e9cnico de asaja asesora a todos los interesados<\/p><\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; ASAJA asesora a los viticultores para presentar sus solicitudes antes del 23 de agosto. Ma\u00f1ana martes 24 de julio se abre la esperada convocatoria de ayudas a la reestructuraci\u00f3n y reconversi\u00f3n de vi\u00f1edos de Castilla y Le\u00f3n para la campa\u00f1a vit\u00edcola 2018\/19. ASAJA, que asesora desde sus oficinas a los agricultores que desean solicitar [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":3987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se abre el plazo para pedir las ayudas a la reestructuraci\u00f3n y reconversi\u00f3n de vi\u00f1edos - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"&nbsp; ASAJA asesora a los viticultores para presentar sus solicitudes antes del 23 de agosto. Ma\u00f1ana martes 24 de julio se abre la esperada convocatoria\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se abre el plazo para pedir las ayudas a la reestructuraci\u00f3n y reconversi\u00f3n de vi\u00f1edos - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"&nbsp; ASAJA asesora a los viticultores para presentar sus solicitudes antes del 23 de agosto. Ma\u00f1ana martes 24 de julio se abre la esperada convocatoria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-23T18:39:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-08T14:07:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/700x420_Milajornadavino.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos\",\"name\":\"Se abre el plazo para pedir las ayudas a la reestructuraci\u00f3n y reconversi\u00f3n de vi\u00f1edos - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/700x420_Milajornadavino.jpeg\",\"datePublished\":\"2018-07-23T18:39:07+00:00\",\"dateModified\":\"2018-08-08T14:07:48+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"&nbsp; ASAJA asesora a los viticultores para presentar sus solicitudes antes del 23 de agosto. Ma\u00f1ana martes 24 de julio se abre la esperada convocatoria\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/700x420_Milajornadavino.jpeg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/700x420_Milajornadavino.jpeg\",\"width\":700,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se abre el plazo para pedir las ayudas a la reestructuraci\u00f3n y reconversi\u00f3n de vi\u00f1edos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se abre el plazo para pedir las ayudas a la reestructuraci\u00f3n y reconversi\u00f3n de vi\u00f1edos - ASAJA \u00c1vila","description":"&nbsp; ASAJA asesora a los viticultores para presentar sus solicitudes antes del 23 de agosto. Ma\u00f1ana martes 24 de julio se abre la esperada convocatoria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos","og_locale":"es_ES","og_type":"article","og_title":"Se abre el plazo para pedir las ayudas a la reestructuraci\u00f3n y reconversi\u00f3n de vi\u00f1edos - ASAJA \u00c1vila","og_description":"&nbsp; ASAJA asesora a los viticultores para presentar sus solicitudes antes del 23 de agosto. Ma\u00f1ana martes 24 de julio se abre la esperada convocatoria","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos","og_site_name":"ASAJA \u00c1vila","article_published_time":"2018-07-23T18:39:07+00:00","article_modified_time":"2018-08-08T14:07:48+00:00","og_image":[{"width":700,"height":420,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/700x420_Milajornadavino.jpeg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos","name":"Se abre el plazo para pedir las ayudas a la reestructuraci\u00f3n y reconversi\u00f3n de vi\u00f1edos - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/700x420_Milajornadavino.jpeg","datePublished":"2018-07-23T18:39:07+00:00","dateModified":"2018-08-08T14:07:48+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"&nbsp; ASAJA asesora a los viticultores para presentar sus solicitudes antes del 23 de agosto. Ma\u00f1ana martes 24 de julio se abre la esperada convocatoria","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/700x420_Milajornadavino.jpeg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/07\/700x420_Milajornadavino.jpeg","width":700,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/manana-se-abre-plazo-pedir-las-ayudas-la-reestructuracion-reconversion-vinedos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"Se abre el plazo para pedir las ayudas a la reestructuraci\u00f3n y reconversi\u00f3n de vi\u00f1edos"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/3986"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=3986"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/3986\/revisions"}],"predecessor-version":[{"id":4026,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/3986\/revisions\/4026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/3987"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=3986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=3986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=3986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}