{"id":4023,"date":"2018-08-03T16:00:08","date_gmt":"2018-08-03T14:00:08","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=4023"},"modified":"2018-09-03T16:33:36","modified_gmt":"2018-09-03T14:33:36","slug":"asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha","title":{"rendered":"ASAJA pide apoyos para que una mala comercializaci\u00f3n no arruine las expectativas de una buena cosecha"},"content":{"rendered":"<h2>ASAJA de Castilla y Le\u00f3n manifiesta su preocupaci\u00f3n por el arranque de la campa\u00f1a de comercializaci\u00f3n de cereales con unos precios llamativamente bajos en comparaci\u00f3n con los que se mueven en los mercados internacionales, tanto en el mercado f\u00edsico como de futuros.<\/h2>\n<p>En un mercado globalizado como es el de los cereales,\u00a0 no parece razonable que en Castilla y Le\u00f3n se est\u00e9n pagando los cereales hasta diez euros por tonelada menos que en el resto de pa\u00edses europeos, con el agravante de que esos pa\u00edses con mejores precios son excedentarios y exportadores de cereal, mientras que Espa\u00f1a es deficitaria \u2013 incluso en 2018 con buenas cosechas- y por lo tanto importadora neta.\u00a0 ASAJA considera que se dan las circunstancias para que el arranque de la campa\u00f1a de comercializaci\u00f3n 2018\/2019 lo haga en cotizaciones a partir de 180 euros tonelada para los cereales m\u00e1s demandados como son el trigo y la cebada. Precios inferiores a los 180 euros la tonelada de grano, que por ahora son todav\u00eda mayoritarios, responden a una mala estrategia de ventas , a la situaci\u00f3n de dominancia de los almacenistas de cereales, y a la escasa colaboraci\u00f3n de las cooperativas para que se revalorice el producto.<\/p>\n<p>La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n considera que est\u00e1n en juego\u00a0 al menos 110 millones de euros, que se pueden quedar en el bolsillo de los intermediarios o en el de los agricultores, seg\u00fan c\u00f3mo se desarrolle la campa\u00f1a de comercializaci\u00f3n. Este importe es la diferencia entre el valor de la cosecha que inicialmente dio la consejera de Agricultura, Milagros Marcos, \u00a0de 1.200 millones de euros, y el que deber\u00eda de valer en estos momentos de respetarse las cotizaciones internacionales. Esa cifra de 110 millones de euros se mover\u00e1 al alza ya que las cotizaciones del cereal siguen subiendo.<\/p>\n<p>ASAJA considera que se est\u00e1 produciendo una precipitaci\u00f3n en las ventas motivada por la presi\u00f3n de los intermediarios,\u00a0 por la falta de liquidez de los agricultores que no se recuperan de las consecuencias de la mala cosecha del pasado a\u00f1o, as\u00ed como por la necesidad de atender los primeros vencimientos de amortizaci\u00f3n de capital de los pr\u00e9stamos de la sequ\u00eda suscritos el pasado a\u00f1o. Con el fin de que los agricultores no se vean tan obligados a precipitar las ventas, ASAJA de Castilla y Le\u00f3n \u00a0solicita a la consejer\u00eda de Agricultura que gestione el anticipo del cincuenta por ciento de las ayudas de la PAC a partir del 15 de octubre, como le permite la normativa europea. Tambi\u00e9n, la organizaci\u00f3n agraria \u00a0pide a Milagros Marcos que se involucre en la comercializaci\u00f3n del producto, y que aporte informaci\u00f3n puntual que pueda servir a los agricultores para tomar las decisiones m\u00e1s acertadas, haciendo que el mercado de verdad sea libre y transparente y regulado por la oferta y la demanda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ASAJA de Castilla y Le\u00f3n manifiesta su preocupaci\u00f3n por el arranque de la campa\u00f1a de comercializaci\u00f3n de cereales con unos precios llamativamente bajos en comparaci\u00f3n con los que se mueven en los mercados internacionales, tanto en el mercado f\u00edsico como de futuros. En un mercado globalizado como es el de los cereales,\u00a0 no parece razonable [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA pide apoyos para que una mala comercializaci\u00f3n no arruine las expectativas de una buena cosecha - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"ASAJA de Castilla y Le\u00f3n manifiesta su preocupaci\u00f3n por el arranque de la campa\u00f1a de comercializaci\u00f3n de cereales con unos precios llamativamente bajos en\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA pide apoyos para que una mala comercializaci\u00f3n no arruine las expectativas de una buena cosecha - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"ASAJA de Castilla y Le\u00f3n manifiesta su preocupaci\u00f3n por el arranque de la campa\u00f1a de comercializaci\u00f3n de cereales con unos precios llamativamente bajos en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-03T14:00:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-03T14:33:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/08\/20140702_132645.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha\",\"name\":\"ASAJA pide apoyos para que una mala comercializaci\u00f3n no arruine las expectativas de una buena cosecha - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/08\/20140702_132645.jpg\",\"datePublished\":\"2018-08-03T14:00:08+00:00\",\"dateModified\":\"2018-09-03T14:33:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"ASAJA de Castilla y Le\u00f3n manifiesta su preocupaci\u00f3n por el arranque de la campa\u00f1a de comercializaci\u00f3n de cereales con unos precios llamativamente bajos en\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/08\/20140702_132645.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/08\/20140702_132645.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA pide apoyos para que una mala comercializaci\u00f3n no arruine las expectativas de una buena cosecha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA pide apoyos para que una mala comercializaci\u00f3n no arruine las expectativas de una buena cosecha - ASAJA \u00c1vila","description":"ASAJA de Castilla y Le\u00f3n manifiesta su preocupaci\u00f3n por el arranque de la campa\u00f1a de comercializaci\u00f3n de cereales con unos precios llamativamente bajos en","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha","og_locale":"es_ES","og_type":"article","og_title":"ASAJA pide apoyos para que una mala comercializaci\u00f3n no arruine las expectativas de una buena cosecha - ASAJA \u00c1vila","og_description":"ASAJA de Castilla y Le\u00f3n manifiesta su preocupaci\u00f3n por el arranque de la campa\u00f1a de comercializaci\u00f3n de cereales con unos precios llamativamente bajos en","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha","og_site_name":"ASAJA \u00c1vila","article_published_time":"2018-08-03T14:00:08+00:00","article_modified_time":"2018-09-03T14:33:36+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/08\/20140702_132645.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha","name":"ASAJA pide apoyos para que una mala comercializaci\u00f3n no arruine las expectativas de una buena cosecha - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/08\/20140702_132645.jpg","datePublished":"2018-08-03T14:00:08+00:00","dateModified":"2018-09-03T14:33:36+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"ASAJA de Castilla y Le\u00f3n manifiesta su preocupaci\u00f3n por el arranque de la campa\u00f1a de comercializaci\u00f3n de cereales con unos precios llamativamente bajos en","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/08\/20140702_132645.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/08\/20140702_132645.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-apoyos-una-mala-comercializacion-no-arruine-las-expectativas-una-buena-cosecha#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA pide apoyos para que una mala comercializaci\u00f3n no arruine las expectativas de una buena cosecha"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4023"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=4023"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4023\/revisions"}],"predecessor-version":[{"id":4025,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4023\/revisions\/4025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/4024"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=4023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=4023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=4023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}