{"id":4076,"date":"2018-09-19T12:23:13","date_gmt":"2018-09-19T10:23:13","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=4076"},"modified":"2018-09-21T13:19:39","modified_gmt":"2018-09-21T11:19:39","slug":"asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais","title":{"rendered":"ASAJA de Castilla y Le\u00f3n pide medidas para evitar que la peste porcina africana vuelva a nuestro pa\u00eds"},"content":{"rendered":"<h1>La enfermedad se erradic\u00f3 a principios de los a\u00f1os noventa con un gran coste para los ganaderos y para las administraciones p\u00fablicas.<\/h1>\n<div class=\"td-container\">\n<div class=\"td-pb-row\">\n<div class=\"td-pb-span12 td-main-content\" role=\"main\">\n<div class=\"td-ss-main-content\">\n<div class=\"td-post-content\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12160 alignright td-animation-stack-type0-2\" src=\"https:\/\/www.asajacyl.com\/wp-content\/uploads\/2018\/09\/porcino-seguro-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" \/>La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n comparte la preocupaci\u00f3n de las autoridades sanitarias y del mundo de la ciencia veterinaria por el riesgo de que los focos de Peste Porcina Africana, detectados en Centroeuropa, se propaguen a nuestro pa\u00eds. Esta enfermedad, altamente contagiosa y sin riesgo alguno para el ser humano, provocar\u00eda aut\u00e9nticos estragos en la caba\u00f1a ganadera porcina con consecuencias devastadoras para la econom\u00eda agraria, la industria agroalimentaria y la balanza comercial exterior de nuestro pa\u00eds.<\/p>\n<p>ASAJA de Castilla y Le\u00f3n, que se reunir\u00e1 ma\u00f1ana con la Direcci\u00f3n General de Producci\u00f3n Agropecuaria de la Junta de Castilla y Le\u00f3n para abordar esta cuesti\u00f3n, pide a las autoridades con competencias en sanidad animal que extremen los controles en la entrada de animales y productos c\u00e1rnicos que supongan el m\u00e1s m\u00ednimo riesgo de difusi\u00f3n de la enfermedad, y particularmente exige que se garantice que ninguna pieza de jabal\u00ed, viva o muerta, atraviese nuestras fronteras, como s\u00ed ha ocurrido hasta fechas recientes.<\/p>\n<p>ASAJA de Castilla y Le\u00f3n pide a las empresas ganaderas del sector porcino que paralicen las importaciones de lechones procedentes de otros pa\u00edses europeos con destino al cebo en nuestro pa\u00eds, y m\u00e1s en concreto en Castilla y Le\u00f3n, pues el sector del porcino espa\u00f1ol tiene la suficiente dimensi\u00f3n como para no depender de la compra de animales ni de material gen\u00e9tico de otros pa\u00edses. A la vez, la organizaci\u00f3n agraria insta a los ganaderos a que de la mano de sus veterinarios y de las autoridades sanitarias de la Junta, extremen todas las medidas de bioseguridad hasta que de nuevo se minimice el riesgo de epizootia.<\/p>\n<p>ASAJA recuerda que el sector porcino espa\u00f1ol est\u00e1 entre los tres m\u00e1s competitivos del mundo y que en Castilla y Le\u00f3n, donde est\u00e1 en claro crecimiento, tiene un peso importante tanto en la producci\u00f3n como en la industrializaci\u00f3n y comercializaci\u00f3n de la carne de cerdo y sus derivados.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La enfermedad se erradic\u00f3 a principios de los a\u00f1os noventa con un gran coste para los ganaderos y para las administraciones p\u00fablicas. La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n comparte la preocupaci\u00f3n de las autoridades sanitarias y del mundo de la ciencia veterinaria por el riesgo de que los focos de Peste Porcina Africana, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA de Castilla y Le\u00f3n pide medidas para evitar que la peste porcina africana vuelva a nuestro pa\u00eds - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"La enfermedad se erradic\u00f3 a principios de los a\u00f1os noventa con un gran coste para los ganaderos y para las administraciones p\u00fablicas. La organizaci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA de Castilla y Le\u00f3n pide medidas para evitar que la peste porcina africana vuelva a nuestro pa\u00eds - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"La enfermedad se erradic\u00f3 a principios de los a\u00f1os noventa con un gran coste para los ganaderos y para las administraciones p\u00fablicas. La organizaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-19T10:23:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-21T11:19:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/09\/IMGP5338.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais\",\"name\":\"ASAJA de Castilla y Le\u00f3n pide medidas para evitar que la peste porcina africana vuelva a nuestro pa\u00eds - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/09\/IMGP5338.jpg\",\"datePublished\":\"2018-09-19T10:23:13+00:00\",\"dateModified\":\"2018-09-21T11:19:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"La enfermedad se erradic\u00f3 a principios de los a\u00f1os noventa con un gran coste para los ganaderos y para las administraciones p\u00fablicas. La organizaci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/09\/IMGP5338.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/09\/IMGP5338.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA de Castilla y Le\u00f3n pide medidas para evitar que la peste porcina africana vuelva a nuestro pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA de Castilla y Le\u00f3n pide medidas para evitar que la peste porcina africana vuelva a nuestro pa\u00eds - ASAJA \u00c1vila","description":"La enfermedad se erradic\u00f3 a principios de los a\u00f1os noventa con un gran coste para los ganaderos y para las administraciones p\u00fablicas. La organizaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais","og_locale":"es_ES","og_type":"article","og_title":"ASAJA de Castilla y Le\u00f3n pide medidas para evitar que la peste porcina africana vuelva a nuestro pa\u00eds - ASAJA \u00c1vila","og_description":"La enfermedad se erradic\u00f3 a principios de los a\u00f1os noventa con un gran coste para los ganaderos y para las administraciones p\u00fablicas. La organizaci\u00f3n","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais","og_site_name":"ASAJA \u00c1vila","article_published_time":"2018-09-19T10:23:13+00:00","article_modified_time":"2018-09-21T11:19:39+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/09\/IMGP5338.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais","name":"ASAJA de Castilla y Le\u00f3n pide medidas para evitar que la peste porcina africana vuelva a nuestro pa\u00eds - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/09\/IMGP5338.jpg","datePublished":"2018-09-19T10:23:13+00:00","dateModified":"2018-09-21T11:19:39+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"La enfermedad se erradic\u00f3 a principios de los a\u00f1os noventa con un gran coste para los ganaderos y para las administraciones p\u00fablicas. La organizaci\u00f3n","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/09\/IMGP5338.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/09\/IMGP5338.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-castilla-leon-pide-medidas-evitar-la-peste-porcina-africana-vuelva-pais#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA de Castilla y Le\u00f3n pide medidas para evitar que la peste porcina africana vuelva a nuestro pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4076"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=4076"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4076\/revisions"}],"predecessor-version":[{"id":4078,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4076\/revisions\/4078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/4077"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=4076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=4076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=4076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}