{"id":4282,"date":"2018-12-18T12:32:28","date_gmt":"2018-12-18T11:32:28","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=4282"},"modified":"2018-12-19T17:56:14","modified_gmt":"2018-12-19T16:56:14","slug":"navidad-compra-lo-mejor-compra-lo","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo","title":{"rendered":"En Navidad compra lo mejor, compra lo nuestro"},"content":{"rendered":"<div class=\"td-post-content\">\n<h1>ASAJA anima a los consumidores a que den preferencia a los alimentos aut\u00f3ctonos<\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12509 alignright td-animation-stack-type0-2\" src=\"https:\/\/www.asajacyl.com\/wp-content\/uploads\/2018\/12\/felicitaci\u00f3n-navidad-219x300.jpg\" alt=\"\" width=\"219\" height=\"300\" \/>Coincidiendo con las fechas navide\u00f1as, y como ya es habitual, ASAJA solicita a los consumidores que apoyen al sector agroganadero de Castilla y Le\u00f3n pidiendo en sus puntos de distribuci\u00f3n habituales productos aut\u00f3ctonos. Esta petici\u00f3n se refuerza con el mensaje\u00a0\u201cEn Navidad compra lo mejor, compra lo nuestro\u201d, que centra la felicitaci\u00f3n que la organizaci\u00f3n agraria env\u00eda y transmite estos d\u00edas por las\u00a0redes sociales (Twitter, Facebook e Instagram) y publicaciones propias, con el \u00e1nimo de involucrar\u00a0\u201cen estas fechas navide\u00f1as, y tambi\u00e9n a lo largo de todo el a\u00f1o\u201d,\u00a0al mayor n\u00famero posible de consumidores en la defensa del producto local, que re\u00fane las mejores cualidades de calidad y sabor, adem\u00e1s de ser una excelente oportunidad de apoyar al sector agr\u00edcola y ganadero de Castilla y Le\u00f3n. Por ello, este a\u00f1o la organizaci\u00f3n agraria insiste en la\u00a0importancia de leer el etiquetado\u00a0de los alimentos que se compran, para verificar su origen.<\/p>\n<p>Muy especialmente, ASAJA invita a los ciudadanos, a los consumidores de Castilla y Le\u00f3n, a\u00a0que pidan lechazo criado en la regi\u00f3n, no solo sacrificado aqu\u00ed, ya que podr\u00eda ser importado; as\u00ed tienen garantizado un producto de m\u00e1xima y probada calidad. Como se\u00f1ala la campa\u00f1a de Interovic, la interprofesional del ovino, en la que participa activamente ASAJA, cuando hablamos de alimentos, \u201cm\u00e1s cerca es mejor\u201d.<\/p>\n<p>Adem\u00e1s del lechazo, ASAJA recuerda que hay otros muchos productos de m\u00e1xima calidad que no pueden faltar en estas fechas navide\u00f1as, como el cochinillo, la excelente ternera, l\u00e1cteos y quesos, embutidos de primera calidad, mieles y dulces\u2026 y por supuesto, los vinos, bandera de la regi\u00f3n, y los estupendos espumosos, muchos de ellos amparados por el gran trabajo de las denominaciones de origen y sellos de calidad, adem\u00e1s de por el \u201ccoraz\u00f3n amarillo\u201d de Tierra de Sabor.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ASAJA anima a los consumidores a que den preferencia a los alimentos aut\u00f3ctonos Coincidiendo con las fechas navide\u00f1as, y como ya es habitual, ASAJA solicita a los consumidores que apoyen al sector agroganadero de Castilla y Le\u00f3n pidiendo en sus puntos de distribuci\u00f3n habituales productos aut\u00f3ctonos. Esta petici\u00f3n se refuerza con el mensaje\u00a0\u201cEn Navidad compra [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En Navidad compra lo mejor, compra lo nuestro - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"ASAJA anima a los consumidores a que den preferencia a los alimentos aut\u00f3ctonos Coincidiendo con las fechas navide\u00f1as, y como ya es habitual, ASAJA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Navidad compra lo mejor, compra lo nuestro - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"ASAJA anima a los consumidores a que den preferencia a los alimentos aut\u00f3ctonos Coincidiendo con las fechas navide\u00f1as, y como ya es habitual, ASAJA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-18T11:32:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-19T16:56:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/12\/felicitaci\u00f3n-navidad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"1232\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo\",\"name\":\"En Navidad compra lo mejor, compra lo nuestro - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/12\/felicitaci\u00f3n-navidad.jpg\",\"datePublished\":\"2018-12-18T11:32:28+00:00\",\"dateModified\":\"2018-12-19T16:56:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"ASAJA anima a los consumidores a que den preferencia a los alimentos aut\u00f3ctonos Coincidiendo con las fechas navide\u00f1as, y como ya es habitual, ASAJA\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/12\/felicitaci\u00f3n-navidad.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/12\/felicitaci\u00f3n-navidad.jpg\",\"width\":900,\"height\":1232},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Navidad compra lo mejor, compra lo nuestro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Navidad compra lo mejor, compra lo nuestro - ASAJA \u00c1vila","description":"ASAJA anima a los consumidores a que den preferencia a los alimentos aut\u00f3ctonos Coincidiendo con las fechas navide\u00f1as, y como ya es habitual, ASAJA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo","og_locale":"es_ES","og_type":"article","og_title":"En Navidad compra lo mejor, compra lo nuestro - ASAJA \u00c1vila","og_description":"ASAJA anima a los consumidores a que den preferencia a los alimentos aut\u00f3ctonos Coincidiendo con las fechas navide\u00f1as, y como ya es habitual, ASAJA","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo","og_site_name":"ASAJA \u00c1vila","article_published_time":"2018-12-18T11:32:28+00:00","article_modified_time":"2018-12-19T16:56:14+00:00","og_image":[{"width":900,"height":1232,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/12\/felicitaci\u00f3n-navidad.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo","name":"En Navidad compra lo mejor, compra lo nuestro - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/12\/felicitaci\u00f3n-navidad.jpg","datePublished":"2018-12-18T11:32:28+00:00","dateModified":"2018-12-19T16:56:14+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"ASAJA anima a los consumidores a que den preferencia a los alimentos aut\u00f3ctonos Coincidiendo con las fechas navide\u00f1as, y como ya es habitual, ASAJA","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/12\/felicitaci\u00f3n-navidad.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2018\/12\/felicitaci\u00f3n-navidad.jpg","width":900,"height":1232},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/navidad-compra-lo-mejor-compra-lo#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"En Navidad compra lo mejor, compra lo nuestro"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4282"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=4282"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4282\/revisions"}],"predecessor-version":[{"id":4284,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4282\/revisions\/4284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/4283"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=4282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=4282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=4282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}