{"id":435,"date":"2017-10-23T18:58:03","date_gmt":"2017-10-23T16:58:03","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=435"},"modified":"2018-02-05T14:37:09","modified_gmt":"2018-02-05T13:37:09","slug":"asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada","title":{"rendered":"ASAJA pide a los responsables europeos soluciones ante una poblaci\u00f3n de lobo \u201cdesbordada\u201d"},"content":{"rendered":"<h2>La OPA se\u00f1ala que \u201choy por hoy, sin una caza controlada, es una quimera pensar que lobo y ganado puedan ser compatible\u201d.<\/h2>\n<p>Hoy y ma\u00f1ana una delegaci\u00f3n de representantes de la Uni\u00f3n Europea, del Ministerio y de la Consejer\u00eda de Fomento y Medio Ambiente de la Junta de Castilla y Le\u00f3n est\u00e1 visitando las zonas de la regi\u00f3n m\u00e1s castigadas por los ataques de lobos para comprobar in situ la magnitud del problema. Esta ma\u00f1ana se reun\u00edan con las organizaciones agrarias \u2013ASAJA estuvo representada por Donaciano Dujo, presidente regional, y Juan Luis Delgado y Joaqu\u00edn Antonio Pino, presidentes de Salamanca y \u00c1vila\u2013, as\u00ed como con alcaldes de municipios afectados y grupos ecologistas.<\/p>\n<p>Desde ASAJA se han puesto cifras sobre la mesa: cerca de 2.000 ataques a la ganader\u00eda y 4.000 cabezas muertas cada a\u00f1o. Estas cifras prueban que las medidas preventivas no son eficaces, por lo que la OPA reclama el control de las manadas, que cada vez ampl\u00edan m\u00e1s su territorio. Para ASAJA, hoy por hoy, sin una caza controlada \u2013para lo que habr\u00eda que modificar la normativa actual\u2013, \u201ces una quimera pensar que lobo y ganado puedan ser compatible\u201d.<\/p>\n<p>Humberto Delgado Rosa, director de Capital Natural de la Direcci\u00f3n General de Medio Ambiente de la Comisi\u00f3n Europea, se ha manifestado receptivo a las demandas del sector, reconociendo el papel ecol\u00f3gico no solo el lobo, sino tambi\u00e9n de la ganader\u00eda de extensivo, puesto que contribuye a la limpieza sostenible del medio natural. El caso espa\u00f1ol, y en concreto el de Castilla y Le\u00f3n, no es comparable al franc\u00e9s, con un n\u00famero de lobos muy inferior al que existe en nuestra regi\u00f3n.<\/p>\n<p>Aunque Delgado Rosa ha sostenido que el lobo seguir\u00e1 estando protegido en Castilla y Le\u00f3n, lo que implica que se mantendr\u00e1n medidas de compensaci\u00f3n de da\u00f1os, ha admitido que en situaciones excepcionales han de buscarse alternativas tanto en la prevenci\u00f3n como en el control sostenible de la especie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La OPA se\u00f1ala que \u201choy por hoy, sin una caza controlada, es una quimera pensar que lobo y ganado puedan ser compatible\u201d. Hoy y ma\u00f1ana una delegaci\u00f3n de representantes de la Uni\u00f3n Europea, del Ministerio y de la Consejer\u00eda de Fomento y Medio Ambiente de la Junta de Castilla y Le\u00f3n est\u00e1 visitando las zonas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA pide a los responsables europeos soluciones ante una poblaci\u00f3n de lobo \u201cdesbordada\u201d - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"La OPA se\u00f1ala que \u201choy por hoy, sin una caza controlada, es una quimera pensar que lobo y ganado puedan ser compatible\u201d. Hoy y ma\u00f1ana una delegaci\u00f3n de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA pide a los responsables europeos soluciones ante una poblaci\u00f3n de lobo \u201cdesbordada\u201d - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"La OPA se\u00f1ala que \u201choy por hoy, sin una caza controlada, es una quimera pensar que lobo y ganado puedan ser compatible\u201d. Hoy y ma\u00f1ana una delegaci\u00f3n de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-23T16:58:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-05T13:37:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/lobo2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada\",\"name\":\"ASAJA pide a los responsables europeos soluciones ante una poblaci\u00f3n de lobo \u201cdesbordada\u201d - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/lobo2.jpg\",\"datePublished\":\"2017-10-23T16:58:03+00:00\",\"dateModified\":\"2018-02-05T13:37:09+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"La OPA se\u00f1ala que \u201choy por hoy, sin una caza controlada, es una quimera pensar que lobo y ganado puedan ser compatible\u201d. Hoy y ma\u00f1ana una delegaci\u00f3n de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/lobo2.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/lobo2.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"ASAJA pide a los responsables europeos soluciones ante una poblaci\u00f3n de lobo \u201cdesbordada\u201d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA pide a los responsables europeos soluciones ante una poblaci\u00f3n de lobo \u201cdesbordada\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA pide a los responsables europeos soluciones ante una poblaci\u00f3n de lobo \u201cdesbordada\u201d - ASAJA \u00c1vila","description":"La OPA se\u00f1ala que \u201choy por hoy, sin una caza controlada, es una quimera pensar que lobo y ganado puedan ser compatible\u201d. Hoy y ma\u00f1ana una delegaci\u00f3n de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada","og_locale":"es_ES","og_type":"article","og_title":"ASAJA pide a los responsables europeos soluciones ante una poblaci\u00f3n de lobo \u201cdesbordada\u201d - ASAJA \u00c1vila","og_description":"La OPA se\u00f1ala que \u201choy por hoy, sin una caza controlada, es una quimera pensar que lobo y ganado puedan ser compatible\u201d. Hoy y ma\u00f1ana una delegaci\u00f3n de","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada","og_site_name":"ASAJA \u00c1vila","article_published_time":"2017-10-23T16:58:03+00:00","article_modified_time":"2018-02-05T13:37:09+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/lobo2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada","name":"ASAJA pide a los responsables europeos soluciones ante una poblaci\u00f3n de lobo \u201cdesbordada\u201d - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/lobo2.jpg","datePublished":"2017-10-23T16:58:03+00:00","dateModified":"2018-02-05T13:37:09+00:00","author":{"@id":""},"description":"La OPA se\u00f1ala que \u201choy por hoy, sin una caza controlada, es una quimera pensar que lobo y ganado puedan ser compatible\u201d. Hoy y ma\u00f1ana una delegaci\u00f3n de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/lobo2.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/lobo2.jpg","width":1920,"height":1080,"caption":"ASAJA pide a los responsables europeos soluciones ante una poblaci\u00f3n de lobo \u201cdesbordada\u201d"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-los-responsables-europeos-soluciones-ante-una-poblacion-lobo-desbordada#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA pide a los responsables europeos soluciones ante una poblaci\u00f3n de lobo \u201cdesbordada\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"","url":"https:\/\/www.asajacyl.com\/avila\/author"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/435"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=435"}],"version-history":[{"count":3,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/435\/revisions"}],"predecessor-version":[{"id":3145,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/435\/revisions\/3145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/439"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}