{"id":4385,"date":"2019-01-16T14:55:27","date_gmt":"2019-01-16T13:55:27","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=4385"},"modified":"2019-01-23T10:05:32","modified_gmt":"2019-01-23T09:05:32","slug":"asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton","title":{"rendered":"Asaja reivindica como motor econ\u00f3mico y social del medio rural al sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n"},"content":{"rendered":"<p>Con motivo de la celebraci\u00f3n ma\u00f1ana jueves 17 de enero de la festividad de San Ant\u00f3n, santo protector de los animales y patrono de los ganaderos, ASAJA quiere subrayar la importancia de un sector que aporta el cincuenta por ciento de la Producci\u00f3n Final Agraria regional, que requiere de muchos sacrificios por parte de los profesionales que se dedican a \u00e9l, que soporta una gran parte de las inversiones que se hacen en el campo, que genera mano de obra asalariada, y que lucha cada d\u00eda contra infinidad de trabas administrativas.<\/p>\n<p>Este sector, el ganadero, sufre quiz\u00e1s en mayor medida los efectos de la competitividad y la globalizaci\u00f3n, por lo que cada a\u00f1o muchas explotaciones que no est\u00e1n bien dimensionadas y gestionadas se cierran de forma definitiva, aunque es cierto que por ahora los censos se mantienen o incrementan a costa del crecimiento de las m\u00e1s eficientes. El sector ganadero, m\u00e1s que el agrario, ocupa todo el territorio de Castilla y Le\u00f3n siendo casi el \u00fanico en zonas m\u00e1s desfavorecidas o de monta\u00f1a, y fija poblaci\u00f3n al medio rural al ser una actividad que requiere la presencia f\u00edsica del ganadero los trescientos sesenta y cinco d\u00edas del a\u00f1o.<\/p>\n<p>ASAJA quiere recordar en este d\u00eda la reivindicaci\u00f3n del sector de recuperar unos precios por la leche de oveja, y tambi\u00e9n de vaca, que permitan cubrir los costes y un leg\u00edtimo margen de beneficio. Tambi\u00e9n, la organizaci\u00f3n agraria llama a una reflexi\u00f3n a quienes, desde las ciudades, y sin tener intereses directos en el campo, se oponen a la implantaci\u00f3n de nuevas granjas, descalific\u00e1ndolas por su tama\u00f1o o por unas pr\u00e1cticas que, seg\u00fan ellos, perjudican al medio ambiente o al bienestar animal. En este sentido, ASAJA recuerda que todos los proyectos que se aprueban cumplen con una legislaci\u00f3n vigente, que es de las m\u00e1s exigentes del mundo.<\/p>\n<p>En una regi\u00f3n como Castilla y Le\u00f3n, dedicada mayoritariamente a una agricultura de cultivos herb\u00e1ceos extensivos, ASAJA quiere poner en valor un sector ganadero al que va destinado casi el cien por cien de nuestros cereales y forrajes, transform\u00e1ndolos en productos de m\u00e1s valor, como son la carne y los l\u00e1cteos, que est\u00e1n abri\u00e9ndose importantes mercados dentro y fuera de la Uni\u00f3n Europea. Castilla y Le\u00f3n es ya claramente una comunidad exportadora de productos alimenticios de origen animal, siendo el principal exponente el porcino.<\/p>\n<p>ASAJA pide a las administraciones que se siga avanzando en la sanidad animal, que se apoye a los ganaderos que modernizan sus explotaciones, que se flexibilicen ciertas normas administrativas relacionadas con la el medio ambiente y la gesti\u00f3n de las explotaciones, que se controle las poblaciones de lobos y otras especies salvajes, que se identifique el origen de los productos que llegan al consumidor, y que se reforme la \u201cnorma del Ib\u00e9rico\u201d para adaptarla a las demandas de productores e industriales. Tambi\u00e9n, ASAJA pide a la industria agroalimentaria y a la gran distribuci\u00f3n que remuneren a los ganaderos con precios justos, que establezcan compromisos a largo plazo, y que apuesten por la producci\u00f3n local en vez de por las importaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo de la celebraci\u00f3n ma\u00f1ana jueves 17 de enero de la festividad de San Ant\u00f3n, santo protector de los animales y patrono de los ganaderos, ASAJA quiere subrayar la importancia de un sector que aporta el cincuenta por ciento de la Producci\u00f3n Final Agraria regional, que requiere de muchos sacrificios por parte de los [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4386,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Asaja reivindica como motor econ\u00f3mico y social del medio rural al sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"Con motivo de la celebraci\u00f3n ma\u00f1ana jueves 17 de enero de la festividad de San Ant\u00f3n, santo protector de los animales y patrono de los ganaderos, ASAJA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asaja reivindica como motor econ\u00f3mico y social del medio rural al sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"Con motivo de la celebraci\u00f3n ma\u00f1ana jueves 17 de enero de la festividad de San Ant\u00f3n, santo protector de los animales y patrono de los ganaderos, ASAJA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-16T13:55:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-23T09:05:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/GANADERIA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3072\" \/>\n\t<meta property=\"og:image:height\" content=\"2304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton\",\"name\":\"Asaja reivindica como motor econ\u00f3mico y social del medio rural al sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/GANADERIA.jpg\",\"datePublished\":\"2019-01-16T13:55:27+00:00\",\"dateModified\":\"2019-01-23T09:05:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"Con motivo de la celebraci\u00f3n ma\u00f1ana jueves 17 de enero de la festividad de San Ant\u00f3n, santo protector de los animales y patrono de los ganaderos, ASAJA\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/GANADERIA.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/GANADERIA.jpg\",\"width\":3072,\"height\":2304},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asaja reivindica como motor econ\u00f3mico y social del medio rural al sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asaja reivindica como motor econ\u00f3mico y social del medio rural al sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n - ASAJA \u00c1vila","description":"Con motivo de la celebraci\u00f3n ma\u00f1ana jueves 17 de enero de la festividad de San Ant\u00f3n, santo protector de los animales y patrono de los ganaderos, ASAJA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton","og_locale":"es_ES","og_type":"article","og_title":"Asaja reivindica como motor econ\u00f3mico y social del medio rural al sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n - ASAJA \u00c1vila","og_description":"Con motivo de la celebraci\u00f3n ma\u00f1ana jueves 17 de enero de la festividad de San Ant\u00f3n, santo protector de los animales y patrono de los ganaderos, ASAJA","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton","og_site_name":"ASAJA \u00c1vila","article_published_time":"2019-01-16T13:55:27+00:00","article_modified_time":"2019-01-23T09:05:32+00:00","og_image":[{"width":3072,"height":2304,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/GANADERIA.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton","name":"Asaja reivindica como motor econ\u00f3mico y social del medio rural al sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/GANADERIA.jpg","datePublished":"2019-01-16T13:55:27+00:00","dateModified":"2019-01-23T09:05:32+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"Con motivo de la celebraci\u00f3n ma\u00f1ana jueves 17 de enero de la festividad de San Ant\u00f3n, santo protector de los animales y patrono de los ganaderos, ASAJA","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/GANADERIA.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/GANADERIA.jpg","width":3072,"height":2304},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reivindica-motor-economico-social-del-medio-rural-al-sector-ganadero-dia-patron-san-anton#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"Asaja reivindica como motor econ\u00f3mico y social del medio rural al sector ganadero, en el d\u00eda de su patr\u00f3n, San Ant\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4385"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=4385"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4385\/revisions"}],"predecessor-version":[{"id":4387,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4385\/revisions\/4387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/4386"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=4385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=4385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=4385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}