{"id":4484,"date":"2019-01-25T11:11:22","date_gmt":"2019-01-25T10:11:22","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=4484"},"modified":"2019-01-31T17:42:37","modified_gmt":"2019-01-31T16:42:37","slug":"asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos","title":{"rendered":"ASAJA exige a la Junta que ponga en marcha una inspecci\u00f3n espec\u00edfica sobre el etiquetado de leche y l\u00e1cteos dirigida a los distintos establecimientos de las cadenas de distribuci\u00f3n de alimentos."},"content":{"rendered":"<p>Ante una aplicaci\u00f3n desigual del Real Decreto 1181\/2018, de 21 de septiembre, relativo a la indicaci\u00f3n del origen de la leche utilizada como ingrediente en el etiquetado de la leche y los productos l\u00e1cteos, ASAJA exige a la Junta de Castilla y Le\u00f3n que ponga en marcha una inspecci\u00f3n espec\u00edfica dirigida a los distintos establecimientos de las cadenas de distribuci\u00f3n de alimentos.<\/p>\n<p>Si bien el pasado d\u00eda 22 de enero, d\u00eda de entrada en vigor de la normativa, en muchos establecimientos se pod\u00eda adquirir ya leche correctamente etiquetada indicando el origen del producto, esto no se ha generalizado a todas las marcas ni a todos los puntos de venta, pues en una parte importante de los tetra brik, y a\u00fan m\u00e1s en los productos l\u00e1cteos (quesos, yogures, mantequillas, etc.) no hay ninguna referencia que identifique correctamente el origen de la leche.<\/p>\n<p>Siendo cierto que el Real Decreto admite la coexistencia de leche con la identificaci\u00f3n del origen y otra que no lo tenga, hasta agotar las existencias de partidas fabricadas antes del 22 de enero, la entrada en vigor de la normativa se conoc\u00eda desde meses atr\u00e1s, y trat\u00e1ndose de unos productos perecederos y de no excesivo plazo de caducidad lo l\u00f3gico es que pr\u00e1cticamente no hubiera ya remanentes sin identificar.<\/p>\n<p>En este momento, ASAJA subraya que ha de ser la Junta de Castilla y Le\u00f3n la que, ejerciendo sus competencias de inspecci\u00f3n de alimentos, determine los incumplimientos de esta importante norma y establezca las correspondientes sanciones.<\/p>\n<p>Por otra parte, ASAJA pide a las cooperativas que den ejemplo y que sean las primeras en identificar el origen de la leche en todas las referencias que venden a la gran distribuci\u00f3n, algo que por ahora en la mayor\u00eda de sus marcas no lo est\u00e1n haciendo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante una aplicaci\u00f3n desigual del Real Decreto 1181\/2018, de 21 de septiembre, relativo a la indicaci\u00f3n del origen de la leche utilizada como ingrediente en el etiquetado de la leche y los productos l\u00e1cteos, ASAJA exige a la Junta de Castilla y Le\u00f3n que ponga en marcha una inspecci\u00f3n espec\u00edfica dirigida a los distintos establecimientos [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA exige a la Junta que ponga en marcha una inspecci\u00f3n espec\u00edfica sobre el etiquetado de leche y l\u00e1cteos dirigida a los distintos establecimientos de las cadenas de distribuci\u00f3n de alimentos. - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"Ante una aplicaci\u00f3n desigual del Real Decreto 1181\/2018, de 21 de septiembre, relativo a la indicaci\u00f3n del origen de la leche utilizada como ingrediente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA exige a la Junta que ponga en marcha una inspecci\u00f3n espec\u00edfica sobre el etiquetado de leche y l\u00e1cteos dirigida a los distintos establecimientos de las cadenas de distribuci\u00f3n de alimentos. - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"Ante una aplicaci\u00f3n desigual del Real Decreto 1181\/2018, de 21 de septiembre, relativo a la indicaci\u00f3n del origen de la leche utilizada como ingrediente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-25T10:11:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-31T16:42:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/VACA-PREMIADA-BLACHA-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1875\" \/>\n\t<meta property=\"og:image:height\" content=\"2500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos\",\"name\":\"ASAJA exige a la Junta que ponga en marcha una inspecci\u00f3n espec\u00edfica sobre el etiquetado de leche y l\u00e1cteos dirigida a los distintos establecimientos de las cadenas de distribuci\u00f3n de alimentos. - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/VACA-PREMIADA-BLACHA-6.jpg\",\"datePublished\":\"2019-01-25T10:11:22+00:00\",\"dateModified\":\"2019-01-31T16:42:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"Ante una aplicaci\u00f3n desigual del Real Decreto 1181\/2018, de 21 de septiembre, relativo a la indicaci\u00f3n del origen de la leche utilizada como ingrediente\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/VACA-PREMIADA-BLACHA-6.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/VACA-PREMIADA-BLACHA-6.jpg\",\"width\":1875,\"height\":2500,\"caption\":\"All-focus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA exige a la Junta que ponga en marcha una inspecci\u00f3n espec\u00edfica sobre el etiquetado de leche y l\u00e1cteos dirigida a los distintos establecimientos de las cadenas de distribuci\u00f3n de alimentos.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA exige a la Junta que ponga en marcha una inspecci\u00f3n espec\u00edfica sobre el etiquetado de leche y l\u00e1cteos dirigida a los distintos establecimientos de las cadenas de distribuci\u00f3n de alimentos. - ASAJA \u00c1vila","description":"Ante una aplicaci\u00f3n desigual del Real Decreto 1181\/2018, de 21 de septiembre, relativo a la indicaci\u00f3n del origen de la leche utilizada como ingrediente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos","og_locale":"es_ES","og_type":"article","og_title":"ASAJA exige a la Junta que ponga en marcha una inspecci\u00f3n espec\u00edfica sobre el etiquetado de leche y l\u00e1cteos dirigida a los distintos establecimientos de las cadenas de distribuci\u00f3n de alimentos. - ASAJA \u00c1vila","og_description":"Ante una aplicaci\u00f3n desigual del Real Decreto 1181\/2018, de 21 de septiembre, relativo a la indicaci\u00f3n del origen de la leche utilizada como ingrediente","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos","og_site_name":"ASAJA \u00c1vila","article_published_time":"2019-01-25T10:11:22+00:00","article_modified_time":"2019-01-31T16:42:37+00:00","og_image":[{"width":1875,"height":2500,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/VACA-PREMIADA-BLACHA-6.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos","name":"ASAJA exige a la Junta que ponga en marcha una inspecci\u00f3n espec\u00edfica sobre el etiquetado de leche y l\u00e1cteos dirigida a los distintos establecimientos de las cadenas de distribuci\u00f3n de alimentos. - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/VACA-PREMIADA-BLACHA-6.jpg","datePublished":"2019-01-25T10:11:22+00:00","dateModified":"2019-01-31T16:42:37+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"Ante una aplicaci\u00f3n desigual del Real Decreto 1181\/2018, de 21 de septiembre, relativo a la indicaci\u00f3n del origen de la leche utilizada como ingrediente","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/VACA-PREMIADA-BLACHA-6.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/VACA-PREMIADA-BLACHA-6.jpg","width":1875,"height":2500,"caption":"All-focus"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-exige-la-junta-ponga-marcha-una-inspeccion-especifica-etiquetado-leche-lacteos-dirigida-los-distintos-establecimientos-las-cadenas-distribucion-alimentos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA exige a la Junta que ponga en marcha una inspecci\u00f3n espec\u00edfica sobre el etiquetado de leche y l\u00e1cteos dirigida a los distintos establecimientos de las cadenas de distribuci\u00f3n de alimentos."}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4484"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=4484"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4484\/revisions"}],"predecessor-version":[{"id":4486,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4484\/revisions\/4486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/4485"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=4484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=4484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=4484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}