{"id":4514,"date":"2019-01-31T17:41:07","date_gmt":"2019-01-31T16:41:07","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=4514"},"modified":"2019-02-11T13:41:27","modified_gmt":"2019-02-11T12:41:27","slug":"asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector","title":{"rendered":"ASAJA anima a las mujeres agricultoras y ganaderas a que den un paso al frente y sean protagonistas del sector"},"content":{"rendered":"<h2>Jornada organizada por ASAJA de Castilla y Le\u00f3n para propiciar el liderazgo de las mujeres tanto en la profesi\u00f3n como en el \u00e1mbito representativo.<\/h2>\n<figure id=\"attachment_12690\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12690 td-animation-stack-type0-2\" src=\"https:\/\/www.asajacyl.com\/wp-content\/uploads\/2019\/01\/Jos\u00e9-C.-Castillo-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><figcaption class=\"wp-caption-text\">Las mujeres de ASAJA, en Agraria<\/figcaption><\/figure>\n<p>M\u00e1s de cien mujeres, agricultoras y ganaderas en activo de las nueve provincias de Castilla y Le\u00f3n y socias de ASAJA han participado hoy en la jornada \u201cPROMOVIENDO EL LIDERAZGO DE LA MUJER EN EL CAMPO\u201d, celebrada en el marco de la feria Agraria, en Valladolid.<\/p>\n<p>El objetivo de la jornada era reunir a mujeres profesionales del sector con el objeto de subrayar su trabajo y tambi\u00e9n para propiciar su mayor presencia en los \u00f3rganos de decisi\u00f3n, \u201cdesde cooperativas hasta los ayuntamientos, pasando por las propias organizaciones agrarias. Las mujeres tenemos una enorme capacidad y tenemos que confiar en nuestras posibilidades y dar un paso adelante para ser protagonistas tambi\u00e9n en el sector agroganadero\u201d, ha subrayado Blanca Corroto, presidenta de ASAJA-Toledo, y una de las ponentes de la jornada de hoy.<\/p>\n<p>Donaciano Dujo, presidente de ASAJA de Castilla y Le\u00f3n, agradeci\u00f3 la asistencia de mujeres de toda la regi\u00f3n a este encuentro, \u201cmujeres netamente profesionales, que se suben a un tractor, que atienen el ganado, que deciden gastos y pelean para mejorar los ingresos de la explotaci\u00f3n\u201d. Dujo se\u00f1al\u00f3 que cerca del 30 por ciento de los asociados de ASAJA son mujeres, con los mismos derechos y obligaciones que el 70 por ciento restante, los hombres. Las agricultoras y ganaderas tienen las ideas muy claras y tienen que hacerse o\u00edr, defendiendo tantas cosas que preocupan al sector, desde los precios a los costes, pasando por los servicios que necesitan nuestros pueblos o el necesario reconocimiento social de la labor que desempe\u00f1amos\u201d. Reconociendo que el cambio en el sector es m\u00e1s lento que otros, \u201cno hay ning\u00fan motivo para que las mujeres no lleguen hasta donde ellas mismas quieran. Apostad por vosotras\u201d, subray\u00f3 ante las asistentes.<\/p>\n<p>En representaci\u00f3n de las mujeres agricultoras y ganaderas asistentes, cuatro de ellas han intervenido en un debate, moderado por la periodista Cristina Carro, responsable del programa referente para el sector Surcos, en RTCyL. En concreto, han intervenido Mari Carmen Qui\u00f1ones, agricultora de regad\u00edo en Zotes del P\u00e1ramo (Le\u00f3n), que lleva ya 34 a\u00f1os en activo; Luc\u00eda L\u00f3pez, con solo 23 a\u00f1os y dos como ganadera de vacuno extensivo en Villacast\u00edn (Segovia); Silvia Gonz\u00e1lez, muy joven pero ya cinco a\u00f1os como titular de la explotaci\u00f3n agr\u00edcola familia en Villaconancio (Palencia), y Ana Pastor Soria, tambi\u00e9n joven e innovadora agricultora de Santa Mar\u00eda del Prado (Soria). Todas ellas han compartido sus distintas experiencias y tambi\u00e9n expresado su confianza en que, pese a las dificultades, principalmente la excesiva burocracia y malos precios, se trata de una profesi\u00f3n vocacional que reporta satisfacciones.<\/p>\n<p>Adem\u00e1s, el programa ha incluido una ponencia sobre \u201cL\u00edneas de actuaci\u00f3n del MAPA en mecanizaci\u00f3n agraria\u201d, a cargo de Victoria Montemayor, directora de la Estaci\u00f3n de Mec\u00e1nica Agr\u00edcola, y otra sobre liderazgo, a cargo de Susana Herrero, especialista en motivaci\u00f3n y empoderamiento.<\/p>\n<p>Hoy por hoy, de las cerca de 66.000 PAC de personas f\u00edsicas en Castilla y Le\u00f3n, de las que cerca de 19.000 corresponden a mujeres, es decir, cerca de un 29 por ciento. Aproximadamente en una de cuatro incorporaciones al sector las protagonistas son mujeres, titular y motor de su explotaci\u00f3n, que deciden inversiones y producciones. \u00a0Hoy, en la agricultura y ganader\u00eda moderna y mecanizada, hay que trabajar para que las mujeres desempe\u00f1en el papel, tanto personal, como profesional o representativo, que ellas mismas decidan. Con esta jornada, ASAJA Castilla y Le\u00f3n quiere contribuir a ello y a que se rompan los estereotipos en torno a las mujeres que en este siglo XXI viven en los pueblos, mujeres del siglo XXI con las mismas aspiraciones que el resto.<\/p>\n<p><em>Foto: Jos\u00e9 C. Castillo<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jornada organizada por ASAJA de Castilla y Le\u00f3n para propiciar el liderazgo de las mujeres tanto en la profesi\u00f3n como en el \u00e1mbito representativo. Las mujeres de ASAJA, en Agraria M\u00e1s de cien mujeres, agricultoras y ganaderas en activo de las nueve provincias de Castilla y Le\u00f3n y socias de ASAJA han participado hoy en [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA anima a las mujeres agricultoras y ganaderas a que den un paso al frente y sean protagonistas del sector - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"Jornada organizada por ASAJA de Castilla y Le\u00f3n para propiciar el liderazgo de las mujeres tanto en la profesi\u00f3n como en el \u00e1mbito representativo. Las\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA anima a las mujeres agricultoras y ganaderas a que den un paso al frente y sean protagonistas del sector - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"Jornada organizada por ASAJA de Castilla y Le\u00f3n para propiciar el liderazgo de las mujeres tanto en la profesi\u00f3n como en el \u00e1mbito representativo. Las\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-31T16:41:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-11T12:41:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/jose-c-castillo-peque.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector\",\"name\":\"ASAJA anima a las mujeres agricultoras y ganaderas a que den un paso al frente y sean protagonistas del sector - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/jose-c-castillo-peque.jpg\",\"datePublished\":\"2019-01-31T16:41:07+00:00\",\"dateModified\":\"2019-02-11T12:41:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"Jornada organizada por ASAJA de Castilla y Le\u00f3n para propiciar el liderazgo de las mujeres tanto en la profesi\u00f3n como en el \u00e1mbito representativo. Las\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/jose-c-castillo-peque.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/jose-c-castillo-peque.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA anima a las mujeres agricultoras y ganaderas a que den un paso al frente y sean protagonistas del sector\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA anima a las mujeres agricultoras y ganaderas a que den un paso al frente y sean protagonistas del sector - ASAJA \u00c1vila","description":"Jornada organizada por ASAJA de Castilla y Le\u00f3n para propiciar el liderazgo de las mujeres tanto en la profesi\u00f3n como en el \u00e1mbito representativo. Las","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector","og_locale":"es_ES","og_type":"article","og_title":"ASAJA anima a las mujeres agricultoras y ganaderas a que den un paso al frente y sean protagonistas del sector - ASAJA \u00c1vila","og_description":"Jornada organizada por ASAJA de Castilla y Le\u00f3n para propiciar el liderazgo de las mujeres tanto en la profesi\u00f3n como en el \u00e1mbito representativo. Las","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector","og_site_name":"ASAJA \u00c1vila","article_published_time":"2019-01-31T16:41:07+00:00","article_modified_time":"2019-02-11T12:41:27+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/jose-c-castillo-peque.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector","name":"ASAJA anima a las mujeres agricultoras y ganaderas a que den un paso al frente y sean protagonistas del sector - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/jose-c-castillo-peque.jpg","datePublished":"2019-01-31T16:41:07+00:00","dateModified":"2019-02-11T12:41:27+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"Jornada organizada por ASAJA de Castilla y Le\u00f3n para propiciar el liderazgo de las mujeres tanto en la profesi\u00f3n como en el \u00e1mbito representativo. Las","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/jose-c-castillo-peque.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/01\/jose-c-castillo-peque.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-anima-las-mujeres-agricultoras-ganaderas-den-paso-al-frente-sean-protagonistas-del-sector#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA anima a las mujeres agricultoras y ganaderas a que den un paso al frente y sean protagonistas del sector"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4514"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=4514"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4514\/revisions"}],"predecessor-version":[{"id":4516,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4514\/revisions\/4516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/4515"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=4514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=4514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=4514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}