{"id":460,"date":"2017-03-08T11:39:11","date_gmt":"2017-03-08T10:39:11","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=460"},"modified":"2017-11-07T11:41:25","modified_gmt":"2017-11-07T10:41:25","slug":"asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles","title":{"rendered":"ASAJA denuncia que los ganaderos del resto de Europa tienen un margen de 3 c\u00e9ntimos por litro de leche para competir con los espa\u00f1oles"},"content":{"rendered":"<h2>Los franceses, nuestros directos competidores, cobran 4,5 c\u00e9ntimos m\u00e1s el litro.<\/h2>\n<p>Desde el mes de octubre, cuando se rompi\u00f3 la tendencia contraria que hab\u00eda durado un periodo de tiempo de escasos nueve meses, la leche de vaca se paga al ganadero en Espa\u00f1a por debajo de la media de la Uni\u00f3n Europea y por debajo de los principales pa\u00edses competidores, como son Francia y Alemania. ASAJA no entiende que siendo Espa\u00f1a un pa\u00eds netamente importador, con un desfase entre producci\u00f3n y consumo de tres millones de toneladas, se produzca un estancamiento de los precios mientras en otros pa\u00edses excedentarios repuntan.<\/p>\n<p>Las cifras son datos objetivos puestos de manifiesto por el Observatorio del Mercado de la Leche de la Comisi\u00f3n Europea que constata una media de precios de 33,67 euros por cada cien kilos, en el mes de febrero, frente a los 30,68 de Espa\u00f1a. En ese mismo mes, en Francia se pag\u00f3 a 35,15 y en Alemania a 34,13 euros por cada 100 kilos (estos \u00faltimos similares tambi\u00e9n a los de B\u00e9lgica y Holanda), un diferencial suficientemente importante como para decidir si una explotaci\u00f3n levanta cabeza o se hunde en los n\u00fameros rojos. Los precios actuales de Francia, de algo m\u00e1s de 35 c\u00e9ntimos por litro, ser\u00edan suficientes como para que la mayor\u00eda de las explotaciones de Castilla y Le\u00f3n salieran de la situaci\u00f3n de p\u00e9rdidas.<\/p>\n<p>ASAJA considera que estos diferenciales de precios son los que necesita la industria l\u00e1ctea espa\u00f1ol, por ser altamente ineficiente, para competir con otras industrias europeas que tienen menos costes y pueden pagar, y de hecho pagan, m\u00e1s la materia prima a los ganaderos. La organizaci\u00f3n agraria culpa a la industria l\u00e1ctea espa\u00f1ola de no haber querido hacer su propia reestructuraci\u00f3n, entre otras la de ganar tama\u00f1o, y de cargar su ineficiencia a las espaldas de los ganaderos.<\/p>\n<p>ASAJA de Castilla y Le\u00f3n lamenta que ahora que hay tres c\u00e9ntimos de euro por litro de leche de diferencia en el menor precio que cobra el ganadero espa\u00f1ol con respecto al del resto de Europa, la ministra Garc\u00eda Tejerina no entre a valorar la situaci\u00f3n y sus causas, cuando por el contrario, el escaso periodo de tiempo que estuvo m\u00e1s alto en precio en Espa\u00f1a, se apresur\u00f3 a atribuirlo a los \u00e9xitos su pol\u00edtica ganadera.<\/p>\n<p>ASAJA critica que ni la Junta de Castilla y Le\u00f3n ni el Ministerio de Agricultura se tomen en serio el grave problema que existe en nuestro pa\u00eds por la injusta distribuci\u00f3n de los m\u00e1rgenes en la cadena de valor de la leche de vaca y otros productos alimenticios. La organizaci\u00f3n agraria considera que los distintos gobiernos se preocupan \u00fanicamente de las grandes cifras el sector -\u00faltimamente positivas gracias a la ola de la exportaci\u00f3n-, pero sean insensibles ante el grave deterioro de las rentas de las familias agricultoras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los franceses, nuestros directos competidores, cobran 4,5 c\u00e9ntimos m\u00e1s el litro. Desde el mes de octubre, cuando se rompi\u00f3 la tendencia contraria que hab\u00eda durado un periodo de tiempo de escasos nueve meses, la leche de vaca se paga al ganadero en Espa\u00f1a por debajo de la media de la Uni\u00f3n Europea y por debajo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":461,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA denuncia que los ganaderos del resto de Europa tienen un margen de 3 c\u00e9ntimos por litro de leche para competir con los espa\u00f1oles - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"Los franceses, nuestros directos competidores, cobran 4,5 c\u00e9ntimos m\u00e1s el litro. Desde el mes de octubre, cuando se rompi\u00f3 la tendencia contraria que\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA denuncia que los ganaderos del resto de Europa tienen un margen de 3 c\u00e9ntimos por litro de leche para competir con los espa\u00f1oles - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"Los franceses, nuestros directos competidores, cobran 4,5 c\u00e9ntimos m\u00e1s el litro. Desde el mes de octubre, cuando se rompi\u00f3 la tendencia contraria que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-08T10:39:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-07T10:41:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/vacunolecheweb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles\",\"name\":\"ASAJA denuncia que los ganaderos del resto de Europa tienen un margen de 3 c\u00e9ntimos por litro de leche para competir con los espa\u00f1oles - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/vacunolecheweb.jpg\",\"datePublished\":\"2017-03-08T10:39:11+00:00\",\"dateModified\":\"2017-11-07T10:41:25+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Los franceses, nuestros directos competidores, cobran 4,5 c\u00e9ntimos m\u00e1s el litro. Desde el mes de octubre, cuando se rompi\u00f3 la tendencia contraria que\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/vacunolecheweb.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/vacunolecheweb.jpg\",\"width\":1500,\"height\":1125,\"caption\":\"ASAJA denuncia que los ganaderos del resto de Europa tienen un margen de 3 c\u00e9ntimos por litro de leche para competir con los espa\u00f1oles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA denuncia que los ganaderos del resto de Europa tienen un margen de 3 c\u00e9ntimos por litro de leche para competir con los espa\u00f1oles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA denuncia que los ganaderos del resto de Europa tienen un margen de 3 c\u00e9ntimos por litro de leche para competir con los espa\u00f1oles - ASAJA \u00c1vila","description":"Los franceses, nuestros directos competidores, cobran 4,5 c\u00e9ntimos m\u00e1s el litro. Desde el mes de octubre, cuando se rompi\u00f3 la tendencia contraria que","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles","og_locale":"es_ES","og_type":"article","og_title":"ASAJA denuncia que los ganaderos del resto de Europa tienen un margen de 3 c\u00e9ntimos por litro de leche para competir con los espa\u00f1oles - ASAJA \u00c1vila","og_description":"Los franceses, nuestros directos competidores, cobran 4,5 c\u00e9ntimos m\u00e1s el litro. Desde el mes de octubre, cuando se rompi\u00f3 la tendencia contraria que","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles","og_site_name":"ASAJA \u00c1vila","article_published_time":"2017-03-08T10:39:11+00:00","article_modified_time":"2017-11-07T10:41:25+00:00","og_image":[{"width":1500,"height":1125,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/vacunolecheweb.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles","name":"ASAJA denuncia que los ganaderos del resto de Europa tienen un margen de 3 c\u00e9ntimos por litro de leche para competir con los espa\u00f1oles - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/vacunolecheweb.jpg","datePublished":"2017-03-08T10:39:11+00:00","dateModified":"2017-11-07T10:41:25+00:00","author":{"@id":""},"description":"Los franceses, nuestros directos competidores, cobran 4,5 c\u00e9ntimos m\u00e1s el litro. Desde el mes de octubre, cuando se rompi\u00f3 la tendencia contraria que","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/vacunolecheweb.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/vacunolecheweb.jpg","width":1500,"height":1125,"caption":"ASAJA denuncia que los ganaderos del resto de Europa tienen un margen de 3 c\u00e9ntimos por litro de leche para competir con los espa\u00f1oles"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/noticias\/asaja-denuncia-los-ganaderos-del-resto-europa-tienen-margen-3-centimos-litro-leche-competir-los-espanoles#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA denuncia que los ganaderos del resto de Europa tienen un margen de 3 c\u00e9ntimos por litro de leche para competir con los espa\u00f1oles"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"","url":"https:\/\/www.asajacyl.com\/avila\/author"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/460"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=460"}],"version-history":[{"count":3,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/460\/revisions"}],"predecessor-version":[{"id":464,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/460\/revisions\/464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/461"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}