{"id":4710,"date":"2019-03-13T15:15:08","date_gmt":"2019-03-13T14:15:08","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=4710"},"modified":"2019-03-22T09:49:20","modified_gmt":"2019-03-22T08:49:20","slug":"asaja-se-suma-la-protesta-irracional-bloqueo-la-caza","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza","title":{"rendered":"ASAJA se suma a la protesta contra el irracional bloqueo a la caza"},"content":{"rendered":"<p>En la protesta convocada por la Federaci\u00f3n de Caza frente a las Cortes ha quedado de manifiesto el hartazgo rural hacia el continuo acoso de los grupos animalistas<br \/>\nASAJA ha participado en la manifestaci\u00f3n convocada hoy por la Federaci\u00f3n de Caza de Castilla y Le\u00f3n frente a la fachada de las Cortes de Castilla y Le\u00f3n, donde hoy se ha aprobado, con el apoyo de PP, PSOE y Ciudadanos, una proposici\u00f3n de ley para blindar la actividad cineg\u00e9tica, para contrarrestar los autos dictados por el Tribunal Superior de Justicia de Castilla y Le\u00f3n que han paralizado la pr\u00e1ctica de la caza en la Comunidad Aut\u00f3noma.<br \/>\nEn esta convocatoria la Federaci\u00f3n de Caza pidi\u00f3 el apoyo tanto de los cazadores como de las organizaciones agrarias y de la Federaci\u00f3n Regional de Municipios y Provincias de Castilla y Le\u00f3n, ya que los ingresos procedentes de la actividad cineg\u00e9tica son vitales para asumir obras de mantenimiento esenciales para muchos peque\u00f1os pueblos de la comunidad aut\u00f3noma.<br \/>\nLos manifestantes ondearon banderas espa\u00f1olas y tambi\u00e9n pancartas en las que indicaban sus lugares de procedencia, diferentes puntos de la geograf\u00eda de Castilla y Le\u00f3n. Tambi\u00e9n corearon consignas en defensa de la caza, as\u00ed como en contra del acoso permanente de los grupos animalistas hacia el medio rural y sus tradiciones.<br \/>\nPara el presidente de ASAJA, Donaciano Dujo, que habl\u00f3 en nombre de los agricultores y ganaderos, calificando a la caza como \u201cimprescindible para controlar una fauna creciente que causa continuas p\u00e9rdidas a los agricultores y ganaderos, pero que adem\u00e1s es una amenaza para la sociedad en su conjunto. Sin caza proliferar\u00edan los problemas sanitarios y estar\u00eda en peligro el mismo equilibrio de la fauna y naturaleza\u201d, indic\u00f3 Dujo, quien record\u00f3 tambi\u00e9n la importancia de la actividad cineg\u00e9tica para muchas zonas rurales \u201cdonde no hay apenas actividad econ\u00f3mica\u201d.<br \/>\nPor todo ello, el presidente de ASAJA ha pedido a los responsables pol\u00edticos presentes en las Cortes regionales que \u201cde una vez por todas refrenden una ley clara y que no pueda ser recurrida por parte de grupos animalistas u otros\u201d.<br \/>\nHay que recordar que solo en lo que se refiere al lobo ya hay m\u00e1s de 4.000 animales dom\u00e9sticos muertos al a\u00f1o en Castilla y Le\u00f3n, cifras que se disparar\u00e1n a\u00fan m\u00e1s si no se efect\u00faa ning\u00fan tipo de control cineg\u00e9tico. Adem\u00e1s, hay que contabilizar los continuos da\u00f1os de otras especies, como jabal\u00edes o corzos, tanto en el sector agrario como en la sociedad en su conjunto, pues son causa continua de accidentes de tr\u00e1fico y problemas sanitarios, \u201cy eso que se matan al a\u00f1o m\u00e1s de 41.000 jabal\u00edes y casi 22.000 corzos en nuestra regi\u00f3n, dato que sirve para hacerse una idea de la selva que ser\u00eda el medio rural si no hubiera caza\u201d, apunta Dujo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la protesta convocada por la Federaci\u00f3n de Caza frente a las Cortes ha quedado de manifiesto el hartazgo rural hacia el continuo acoso de los grupos animalistas ASAJA ha participado en la manifestaci\u00f3n convocada hoy por la Federaci\u00f3n de Caza de Castilla y Le\u00f3n frente a la fachada de las Cortes de Castilla y [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4707,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA se suma a la protesta contra el irracional bloqueo a la caza - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"En la protesta convocada por la Federaci\u00f3n de Caza frente a las Cortes ha quedado de manifiesto el hartazgo rural hacia el continuo acoso de los grupos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA se suma a la protesta contra el irracional bloqueo a la caza - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"En la protesta convocada por la Federaci\u00f3n de Caza frente a las Cortes ha quedado de manifiesto el hartazgo rural hacia el continuo acoso de los grupos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-13T14:15:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-22T08:49:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/03\/FOTO-5-CONCENTRACI\u00d3N-CAZA-EN-VALLADOLID.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza\",\"name\":\"ASAJA se suma a la protesta contra el irracional bloqueo a la caza - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/03\/FOTO-5-CONCENTRACI\u00d3N-CAZA-EN-VALLADOLID.jpg\",\"datePublished\":\"2019-03-13T14:15:08+00:00\",\"dateModified\":\"2019-03-22T08:49:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"En la protesta convocada por la Federaci\u00f3n de Caza frente a las Cortes ha quedado de manifiesto el hartazgo rural hacia el continuo acoso de los grupos\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/03\/FOTO-5-CONCENTRACI\u00d3N-CAZA-EN-VALLADOLID.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/03\/FOTO-5-CONCENTRACI\u00d3N-CAZA-EN-VALLADOLID.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA se suma a la protesta contra el irracional bloqueo a la caza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA se suma a la protesta contra el irracional bloqueo a la caza - ASAJA \u00c1vila","description":"En la protesta convocada por la Federaci\u00f3n de Caza frente a las Cortes ha quedado de manifiesto el hartazgo rural hacia el continuo acoso de los grupos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza","og_locale":"es_ES","og_type":"article","og_title":"ASAJA se suma a la protesta contra el irracional bloqueo a la caza - ASAJA \u00c1vila","og_description":"En la protesta convocada por la Federaci\u00f3n de Caza frente a las Cortes ha quedado de manifiesto el hartazgo rural hacia el continuo acoso de los grupos","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza","og_site_name":"ASAJA \u00c1vila","article_published_time":"2019-03-13T14:15:08+00:00","article_modified_time":"2019-03-22T08:49:20+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/03\/FOTO-5-CONCENTRACI\u00d3N-CAZA-EN-VALLADOLID.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza","name":"ASAJA se suma a la protesta contra el irracional bloqueo a la caza - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/03\/FOTO-5-CONCENTRACI\u00d3N-CAZA-EN-VALLADOLID.jpg","datePublished":"2019-03-13T14:15:08+00:00","dateModified":"2019-03-22T08:49:20+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"En la protesta convocada por la Federaci\u00f3n de Caza frente a las Cortes ha quedado de manifiesto el hartazgo rural hacia el continuo acoso de los grupos","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/03\/FOTO-5-CONCENTRACI\u00d3N-CAZA-EN-VALLADOLID.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/03\/FOTO-5-CONCENTRACI\u00d3N-CAZA-EN-VALLADOLID.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-se-suma-la-protesta-irracional-bloqueo-la-caza#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA se suma a la protesta contra el irracional bloqueo a la caza"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4710"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=4710"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4710\/revisions"}],"predecessor-version":[{"id":4711,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4710\/revisions\/4711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/4707"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=4710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=4710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=4710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}