{"id":4807,"date":"2019-04-12T15:19:52","date_gmt":"2019-04-12T13:19:52","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=4807"},"modified":"2019-04-12T15:19:52","modified_gmt":"2019-04-12T13:19:52","slug":"convocatoria-plan-renove-2019","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019","title":{"rendered":"Convocatoria plan renove 2019"},"content":{"rendered":"<p><strong>Servicios T\u00e9cnicos de ASAJA CyL<\/strong><br \/>\nEl Ministerio de Agricultura, Pesca y Alimentaci\u00f3n ha publicado la convocatoria de las ayudas correspondientes al Plan de Renovaci\u00f3n del Parque Nacional de Maquinaria Agr\u00edcola (PLAN RENOVE) para el ejercicio 2019.<br \/>\nEl plazo de presentaci\u00f3n de solicitudes finaliza el 15 de septiembre de 2019 y el presupuesto destinado a estas ayudas es de 5 millones de euros.<br \/>\nSe subvenciona la adquisici\u00f3n de la siguiente maquinaria nueva:<br \/>\nTractores.<br \/>\nM\u00e1quinas automotrices: de recolecci\u00f3n, de aplicaci\u00f3n de productos fitosanitarios y fertilizantes, excluidas cisternas de pur\u00edn.<br \/>\nM\u00e1quinas arrastradas o suspendidas: sembradora directa, abonadora, equipos de aplicaci\u00f3n de productos fitosanitarios, cisternas de pur\u00edn con sistemas de localizaci\u00f3n de producto en el suelo (rejas y discos (para aplicaci\u00f3n en el suelo), tubos flexibles (mangueras) o r\u00edgidos (para aplicaci\u00f3n justo sobre el suelo), as\u00ed como sistemas de localizaci\u00f3n de pur\u00edn en el suelo independientemente de la cisterna)<br \/>\nLa cuant\u00eda de las ayudas tiene un l\u00edmite del 30% del coste total de adquisici\u00f3n sin impuestos, adem\u00e1s de no poder superar:<br \/>\n12.000 euros en tractores.<br \/>\n25.000 euros en m\u00e1quinas automotrices.<br \/>\n4.500 euros en abonadoras.<br \/>\n6.000 euros en equipos de aplicaci\u00f3n de productos fitosanitarios.<br \/>\n20.000 euros en sembradoras directas, cisternas para purines equipados con dispositivo de aplicaci\u00f3n localizada y la reforma de las cisternas de pur\u00edn sustituyendo el equipo de aplicaci\u00f3n por platos, abanico o ca\u00f1\u00f3n por equipos localizadores del producto en el suelo.<\/p>\n<p><a href=\"https:\/\/www.boe.es\/boe\/dias\/2019\/04\/12\/pdfs\/BOE-B-2019-16082.pdf\" target=\"_blank\" rel=\"noopener\">Ver extracto de la Orden del Ministerio de Agricultura, Pesca y Alimentaci\u00f3n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Servicios T\u00e9cnicos de ASAJA CyL El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n ha publicado la convocatoria de las ayudas correspondientes al Plan de Renovaci\u00f3n del Parque Nacional de Maquinaria Agr\u00edcola (PLAN RENOVE) para el ejercicio 2019. El plazo de presentaci\u00f3n de solicitudes finaliza el 15 de septiembre de 2019 y el presupuesto destinado a estas [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,46,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Convocatoria plan renove 2019 - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"Servicios T\u00e9cnicos de ASAJA CyL El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n ha publicado la convocatoria de las ayudas correspondientes al Plan de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocatoria plan renove 2019 - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"Servicios T\u00e9cnicos de ASAJA CyL El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n ha publicado la convocatoria de las ayudas correspondientes al Plan de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-12T13:19:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019\",\"name\":\"Convocatoria plan renove 2019 - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2019-04-12T13:19:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"Servicios T\u00e9cnicos de ASAJA CyL El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n ha publicado la convocatoria de las ayudas correspondientes al Plan de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA \u00c1vila\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocatoria plan renove 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocatoria plan renove 2019 - ASAJA \u00c1vila","description":"Servicios T\u00e9cnicos de ASAJA CyL El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n ha publicado la convocatoria de las ayudas correspondientes al Plan de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019","og_locale":"es_ES","og_type":"article","og_title":"Convocatoria plan renove 2019 - ASAJA \u00c1vila","og_description":"Servicios T\u00e9cnicos de ASAJA CyL El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n ha publicado la convocatoria de las ayudas correspondientes al Plan de","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019","og_site_name":"ASAJA \u00c1vila","article_published_time":"2019-04-12T13:19:52+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019","name":"Convocatoria plan renove 2019 - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2019-04-12T13:19:52+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"Servicios T\u00e9cnicos de ASAJA CyL El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n ha publicado la convocatoria de las ayudas correspondientes al Plan de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA \u00c1vila"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/convocatoria-plan-renove-2019#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"Convocatoria plan renove 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4807"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=4807"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4807\/revisions"}],"predecessor-version":[{"id":4808,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4807\/revisions\/4808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/794"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=4807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=4807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=4807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}