{"id":4863,"date":"2019-05-03T10:04:22","date_gmt":"2019-05-03T08:04:22","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=4863"},"modified":"2019-05-03T10:04:22","modified_gmt":"2019-05-03T08:04:22","slug":"asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon","title":{"rendered":"ASAJA critica que Agroseguro proponga cambios que implicar\u00edan incrementos desmesurados en las principales l\u00edneas para Castilla y Le\u00f3n"},"content":{"rendered":"<p>La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n califica de \u201calarmante\u201d el prop\u00f3sito de Agroseguro, la entidad espa\u00f1ola de entidades aseguradoras de los seguros agrarios, de introducir cambios en las l\u00edneas de seguros que implicar\u00edan subidas muy importantes de l\u00edneas vitales para la Comunidad Aut\u00f3noma, como los cereales y el vi\u00f1edo.<\/p>\n<p>Al parecer, tras dos a\u00f1os de siniestralidad, a causa principalmente de las recurrentes heladas y pedriscos, Agroseguro quiere recomponer, y adem\u00e1s con brevedad, las estad\u00edsticas que se emplean en los seguros. Aunque no se especifica la tarifa resultante, se estima que implicar\u00eda, en el caso de la uva de vinificaci\u00f3n, subidas de hasta un 40 por ciento en el precio que abona el agricultor. Estos incrementos se trasladar\u00edan pr\u00f3ximamente a otras l\u00edneas fundamentales para Castilla y Le\u00f3n, como la de cultivos herb\u00e1ceos extensivos.<\/p>\n<p>ASAJA considera que aplicar estas subidas de precio \u201cir\u00eda contra el sistema de seguros agrarios, e incluso podr\u00eda ponerlo en peligro, puesto que el elevado coste acabar\u00eda por alejar a una parte de los que ahora suscriben seguros, se romper\u00eda la solidaridad del sistema y finalmente se quedar\u00edan desamparados los que sufren m\u00e1s siniestros, siniestros que no olvidemos que obedecen a causas ajenas e inevitables\u201d. En todo caso, si fuera preciso alg\u00fan ajuste, lo razonable es que la subida fuera m\u00ednima y no comprometa el futuro del sistema, puesto que se trata de unas campa\u00f1as en las que han concurrido hechos excepcionales.<\/p>\n<p>Por estas razones, la organizaci\u00f3n agraria plante\u00f3 el tema en el \u00faltimo Consejo Regional Agrario, y tambi\u00e9n se ha dirigido a \u00d3scar Sayagu\u00e9s, presidente de la Comisi\u00f3n Territorial de Seguros Agrarios de Castilla y Le\u00f3n en su calidad de director de Producciones Agropecuarias de la Consejer\u00eda de Agricultura y Ganader\u00eda. ASAJA considera que \u201cCastilla y Le\u00f3n debe mostrar una oposici\u00f3n frontal com\u00fan, tanto de las organizaciones agrarias como de las instituciones, a esta estrategia de Agroseguro\u201d. La organizaci\u00f3n ha pedido que se convoque lo antes posible una reuni\u00f3n extraordinaria de la Comisi\u00f3n Territorial de Seguros Agrarios para analizar el problema y consensuar medidas a seguir para lograr que Agroseguro rectifique y retire esta propuesta.<\/p>\n<p>Como dato, en Castilla y Le\u00f3n en la \u00faltima campa\u00f1a se suscribieron casi 2000 p\u00f3lizas del seguro de uva de vinificaci\u00f3n, cubriendo aproximadamente 25.000 hect\u00e1reas de las 77.000 existentes en la CCAA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n califica de \u201calarmante\u201d el prop\u00f3sito de Agroseguro, la entidad espa\u00f1ola de entidades aseguradoras de los seguros agrarios, de introducir cambios en las l\u00edneas de seguros que implicar\u00edan subidas muy importantes de l\u00edneas vitales para la Comunidad Aut\u00f3noma, como los cereales y el vi\u00f1edo. Al parecer, tras dos [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA critica que Agroseguro proponga cambios que implicar\u00edan incrementos desmesurados en las principales l\u00edneas para Castilla y Le\u00f3n - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n califica de \u201calarmante\u201d el prop\u00f3sito de Agroseguro, la entidad espa\u00f1ola de entidades aseguradoras de los\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA critica que Agroseguro proponga cambios que implicar\u00edan incrementos desmesurados en las principales l\u00edneas para Castilla y Le\u00f3n - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n califica de \u201calarmante\u201d el prop\u00f3sito de Agroseguro, la entidad espa\u00f1ola de entidades aseguradoras de los\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-03T08:04:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/05\/CEEBADA-LA-TORRE-MAYO-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon\",\"name\":\"ASAJA critica que Agroseguro proponga cambios que implicar\u00edan incrementos desmesurados en las principales l\u00edneas para Castilla y Le\u00f3n - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/05\/CEEBADA-LA-TORRE-MAYO-4.jpg\",\"datePublished\":\"2019-05-03T08:04:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n califica de \u201calarmante\u201d el prop\u00f3sito de Agroseguro, la entidad espa\u00f1ola de entidades aseguradoras de los\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/05\/CEEBADA-LA-TORRE-MAYO-4.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/05\/CEEBADA-LA-TORRE-MAYO-4.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA critica que Agroseguro proponga cambios que implicar\u00edan incrementos desmesurados en las principales l\u00edneas para Castilla y Le\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA critica que Agroseguro proponga cambios que implicar\u00edan incrementos desmesurados en las principales l\u00edneas para Castilla y Le\u00f3n - ASAJA \u00c1vila","description":"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n califica de \u201calarmante\u201d el prop\u00f3sito de Agroseguro, la entidad espa\u00f1ola de entidades aseguradoras de los","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon","og_locale":"es_ES","og_type":"article","og_title":"ASAJA critica que Agroseguro proponga cambios que implicar\u00edan incrementos desmesurados en las principales l\u00edneas para Castilla y Le\u00f3n - ASAJA \u00c1vila","og_description":"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n califica de \u201calarmante\u201d el prop\u00f3sito de Agroseguro, la entidad espa\u00f1ola de entidades aseguradoras de los","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon","og_site_name":"ASAJA \u00c1vila","article_published_time":"2019-05-03T08:04:22+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/05\/CEEBADA-LA-TORRE-MAYO-4.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon","name":"ASAJA critica que Agroseguro proponga cambios que implicar\u00edan incrementos desmesurados en las principales l\u00edneas para Castilla y Le\u00f3n - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/05\/CEEBADA-LA-TORRE-MAYO-4.jpg","datePublished":"2019-05-03T08:04:22+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n califica de \u201calarmante\u201d el prop\u00f3sito de Agroseguro, la entidad espa\u00f1ola de entidades aseguradoras de los","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/05\/CEEBADA-LA-TORRE-MAYO-4.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/05\/CEEBADA-LA-TORRE-MAYO-4.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-critica-agroseguro-proponga-cambios-implicarian-incrementos-desmesurados-las-principales-lineas-castilla-leon#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA critica que Agroseguro proponga cambios que implicar\u00edan incrementos desmesurados en las principales l\u00edneas para Castilla y Le\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4863"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=4863"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4863\/revisions"}],"predecessor-version":[{"id":4865,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/4863\/revisions\/4865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/4864"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=4863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=4863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=4863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}