{"id":5098,"date":"2019-06-28T10:36:32","date_gmt":"2019-06-28T08:36:32","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=5098"},"modified":"2019-07-01T10:39:28","modified_gmt":"2019-07-01T08:39:28","slug":"gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur","title":{"rendered":"Gran preocupaci\u00f3n del sector agrario espa\u00f1ol ante el inminente acuerdo de la UE con Mercosur"},"content":{"rendered":"<p>Tras casi 20 a\u00f1os de negociaci\u00f3n, el Acuerdo de la UE y Mercosur se encuentra en un punto muy cercano a la firma. El sector agrario espa\u00f1ol, representado por las organizaciones ASAJA, COAG, UPA y Cooperativas Agro-alimentarias de Espa\u00f1a se ha dirigido al presidente del Gobierno, Pedro S\u00e1nchez, para expresarle la preocupaci\u00f3n de los productores agrarios ante la firma de un acuerdo desequilibrado que no tenga en cuenta ciertas producciones agrarias.<br \/>\nEl impacto del acuerdo no solo pondr\u00eda en peligro dichas producciones sino tambi\u00e9n el tejido econ\u00f3mico de las zonas productoras, algunas ya muy castigadas, e incluso el modelo productivo europeo m\u00e1s sostenible y respetuoso con el medio ambiente.<br \/>\nDe todos es conocido que el Gobierno espa\u00f1ol ha sido durante a\u00f1os, y lo es ahora junto con Alemania y otros socios europeos, defensor de alcanzar un acuerdo con Mercosur, pero debemos recordar que tambi\u00e9n existe otro bloque de pa\u00edses comunitarios encabezado por Francia y B\u00e9lgica que ha expresado su preocupaci\u00f3n por aspectos concretos del acuerdo. Desde el sector agrario espa\u00f1ol somos partidarios de un comercio internacional justo y equitativo pero sostenemos que \u201cquerer desarrollar un acuerdo con Mercosur no debe estar re\u00f1ido con la defensa de nuestros intereses agr\u00edcolas y ganaderos, base econ\u00f3mica de las zonas rurales y sustento clave para fijar poblaci\u00f3n en el territorio y para la gesti\u00f3n medioambiental.\u201d<br \/>\nLos estudios de impacto elaborados en relaci\u00f3n con este Acuerdo UE-Mercosur demuestran que hay una serie de productos que sufrir\u00e1n un grave efecto de ponerse en marcha el acuerdo en sus actuales t\u00e9rminos. En concreto hablamos de sectores tan importantes para Espa\u00f1a como son la ganader\u00eda, los c\u00edtricos o el arroz.<br \/>\nEl vacuno de carne, un sector con amplia implantaci\u00f3n en zonas de nuestro territorio con gran valor ambiental, soporta ya importaciones de Mercosur que suponen el 80% de la carne de vacuno que entra en la UE y cualquier concesi\u00f3n adicional introducir\u00e1 fuertes desequilibrios en este mercado en un momento en que tendremos que enfrentar tambi\u00e9n el Brexit.<br \/>\nEn el caso de los c\u00edtricos, un sector muy afectado ya por el aumento de concesiones acumuladas por otros acuerdos comerciales como el de Sud\u00e1frica, la firma de este acuerdo supondr\u00e1 empeorar a\u00fan m\u00e1s la situaci\u00f3n en los pr\u00f3ximos a\u00f1os por la liberalizaci\u00f3n de las importaciones de zumo de naranja de Brasil, que ya ostenta el 90% del mercado de la UE. Ello supondr\u00e1 el cierre de las pocas industrias que quedan en Espa\u00f1a. Otro producto mediterr\u00e1neo que deber\u00e1 ser reconocido como un sector sensible es el arroz, que tambi\u00e9n ha sufrido ya las concesiones de otros acuerdos comerciales. Debemos recordar que el arroz se cultiva en Espa\u00f1a en zonas medioambientalmente muy sensibles y donde no existen alternativas de cultivo.<br \/>\nTodas estas concesiones no solamente hacen peligrar un tejido econ\u00f3mico en las zonas productoras ya castigadas, sino que pone en duda el modelo productivo que defiende la UE, m\u00e1s respetuoso con el medio ambiente y de acci\u00f3n por el clima, que ser\u00e1 imposible de controlar en las producciones de Mercosur y que entrar\u00e1n en unas condiciones competitivas mejores y con menos requisitos en el mercado de la UE.<br \/>\nEn este sentido, debemos recordar las estrictas normas de obligado cumplimiento que rigen para los productores europeos en materia sanitaria, fitosanitaria, zoosanitaria y de sanidad animal y de respeto medioambiental que la UE debe conseguir que queden garantizadas de forma clara e inequ\u00edvoca en el acuerdo para asegurar a los consumidores europeos que los productos alimenticios que adquieran en el mercado comunitario cumplen con todos los requisitos y est\u00e1ndares europeos.<br \/>\nEn definitiva, el sector agrario espa\u00f1ol recuerda que negar las graves consecuencias de este acuerdo en amplias zonas productivas y productos sensibles no har\u00e1 desaparecer la realidad y por tanto el Gobierno de Espa\u00f1a tiene una responsabilidad con los sectores concernidos y a tenor de las negociaciones desarrolladas hasta el momento nunca se ha percibido la defensa de nuestros sectores sensibles, como si han hecho otros Estados miembros de la UE, especialmente con el vacuno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras casi 20 a\u00f1os de negociaci\u00f3n, el Acuerdo de la UE y Mercosur se encuentra en un punto muy cercano a la firma. El sector agrario espa\u00f1ol, representado por las organizaciones ASAJA, COAG, UPA y Cooperativas Agro-alimentarias de Espa\u00f1a se ha dirigido al presidente del Gobierno, Pedro S\u00e1nchez, para expresarle la preocupaci\u00f3n de los productores [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":5099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gran preocupaci\u00f3n del sector agrario espa\u00f1ol ante el inminente acuerdo de la UE con Mercosur - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"Tras casi 20 a\u00f1os de negociaci\u00f3n, el Acuerdo de la UE y Mercosur se encuentra en un punto muy cercano a la firma. El sector agrario espa\u00f1ol, representado\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gran preocupaci\u00f3n del sector agrario espa\u00f1ol ante el inminente acuerdo de la UE con Mercosur - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"Tras casi 20 a\u00f1os de negociaci\u00f3n, el Acuerdo de la UE y Mercosur se encuentra en un punto muy cercano a la firma. El sector agrario espa\u00f1ol, representado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-28T08:36:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-01T08:39:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/07\/contenedores.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"510\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur\",\"name\":\"Gran preocupaci\u00f3n del sector agrario espa\u00f1ol ante el inminente acuerdo de la UE con Mercosur - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/07\/contenedores.jpg\",\"datePublished\":\"2019-06-28T08:36:32+00:00\",\"dateModified\":\"2019-07-01T08:39:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"Tras casi 20 a\u00f1os de negociaci\u00f3n, el Acuerdo de la UE y Mercosur se encuentra en un punto muy cercano a la firma. El sector agrario espa\u00f1ol, representado\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/07\/contenedores.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/07\/contenedores.jpg\",\"width\":510,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gran preocupaci\u00f3n del sector agrario espa\u00f1ol ante el inminente acuerdo de la UE con Mercosur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gran preocupaci\u00f3n del sector agrario espa\u00f1ol ante el inminente acuerdo de la UE con Mercosur - ASAJA \u00c1vila","description":"Tras casi 20 a\u00f1os de negociaci\u00f3n, el Acuerdo de la UE y Mercosur se encuentra en un punto muy cercano a la firma. El sector agrario espa\u00f1ol, representado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur","og_locale":"es_ES","og_type":"article","og_title":"Gran preocupaci\u00f3n del sector agrario espa\u00f1ol ante el inminente acuerdo de la UE con Mercosur - ASAJA \u00c1vila","og_description":"Tras casi 20 a\u00f1os de negociaci\u00f3n, el Acuerdo de la UE y Mercosur se encuentra en un punto muy cercano a la firma. El sector agrario espa\u00f1ol, representado","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur","og_site_name":"ASAJA \u00c1vila","article_published_time":"2019-06-28T08:36:32+00:00","article_modified_time":"2019-07-01T08:39:28+00:00","og_image":[{"width":510,"height":340,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/07\/contenedores.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur","name":"Gran preocupaci\u00f3n del sector agrario espa\u00f1ol ante el inminente acuerdo de la UE con Mercosur - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/07\/contenedores.jpg","datePublished":"2019-06-28T08:36:32+00:00","dateModified":"2019-07-01T08:39:28+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"Tras casi 20 a\u00f1os de negociaci\u00f3n, el Acuerdo de la UE y Mercosur se encuentra en un punto muy cercano a la firma. El sector agrario espa\u00f1ol, representado","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/07\/contenedores.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/07\/contenedores.jpg","width":510,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/gran-preocupacion-del-sector-agrario-espanol-ante-inminente-acuerdo-la-ue-mercosur#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"Gran preocupaci\u00f3n del sector agrario espa\u00f1ol ante el inminente acuerdo de la UE con Mercosur"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/5098"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=5098"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/5098\/revisions"}],"predecessor-version":[{"id":5100,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/5098\/revisions\/5100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/5099"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=5098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=5098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=5098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}