{"id":5289,"date":"2019-09-20T17:30:25","date_gmt":"2019-09-20T15:30:25","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=5289"},"modified":"2019-09-24T12:47:34","modified_gmt":"2019-09-24T10:47:34","slug":"asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable","title":{"rendered":"ASAJA pide a Carnero una legislatura con pol\u00edticas que impulsen un campo m\u00e1s competitivo y rentable"},"content":{"rendered":"<div class=\"td-full-screen-header-image-wrap\">\n<div class=\"td-container td-post-header\">\n<div class=\"td-post-header-holder\">\n<header class=\"td-post-title\">\n<div class=\"td-module-meta-info\"><span style=\"font-size: 14pt\">El consejero recoge las peticiones de la OPA de incrementar las concentraciones parcelarias y mejorar los regad\u00edos<\/span><\/div>\n<div><\/div>\n<\/header>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"td-container\">\n<div class=\"td-pb-row\">\n<div class=\"td-pb-span12 td-main-content\" role=\"main\">\n<div class=\"td-ss-main-content\">\n<div class=\"td-post-content\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-15501 alignright td-animation-stack-type0-2\" src=\"https:\/\/www.asajacyl.com\/wp-content\/uploads\/2019\/09\/VALLADOLID-1-300x214.jpg\" alt=\"\" width=\"300\" height=\"214\" \/> ASAJA ha valorado la receptividad del consejero de Agricultura, Ganader\u00eda y Desarrollo Rural, Jes\u00fas Julio Carnero, a las propuestas que la organizaci\u00f3n profesional agraria y ganadera le ha transmitido para que en esta legislatura se den pasos muy necesarios para lograr un sector m\u00e1s competitivo y rentable, que sea capaz de ilusionar a las nuevas generaciones. El consejero asist\u00eda hoy a la Junta Directiva de ASAJA de Castilla y Le\u00f3n, constituida por las nueve organizaciones provinciales m\u00e1s los responsables regionales, encabezada por el presidente, Donaciano Dujo.<\/p>\n<p>La reuni\u00f3n se celebraba excepcionalmente en la sede de ASAJA-Valladolid, ejerciendo su presidente, Juan Ram\u00f3n Alonso, como anfitri\u00f3n. Un gesto \u201ccon el que queremos respaldar la gesti\u00f3n y trabajo desarrollada por la nueva directiva provincial, tras un periodo muy complicado, y adem\u00e1s que es muy oportuno hacerlo coincidir con la visita de Jes\u00fas Julio Carnero, tantos a\u00f1os dedicado a la pol\u00edtica de esta provincia\u201d, subray\u00f3 Donaciano Dujo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-15500 alignright td-animation-stack-type0-2\" src=\"https:\/\/www.asajacyl.com\/wp-content\/uploads\/2019\/09\/VALLADOLID-3-356x220.jpg\" alt=\"\" width=\"300\" height=\"185\" \/>En la reuni\u00f3n, ASAJA pidi\u00f3 a Carnero que \u201cabandere una pol\u00edtica auton\u00f3mica agraria ilusionante, que se marque objetivos reales que repercutan en una mayor productividad, calidad y competitividad de nuestro sector\u201d, dijo Dujo. Entre otras medidas, se\u00f1al\u00f3 que la mayor parte de la superficie agr\u00edcola precisa de una nueva concentraci\u00f3n parcelaria, \u201cporque han pasado cincuenta a\u00f1os y la agricultura y la ganader\u00eda no tienen nada que ver con las de entonces\u201d, y lo mismo el regad\u00edo, porque todav\u00eda hay 120.000 hect\u00e1reas de riego en superficie pendientes de modernizar, as\u00ed como otras tantas de riego subterr\u00e1neo que necesitan ser consolidadas.<\/p>\n<p>Junto a estas medidas espec\u00edficas, se precisa el soporte de una PAC bien financiada y dirigida al profesional del campo, y tambi\u00e9n un seguro potente, \u201cjusto lo contrario que est\u00e1 ocurriendo en los \u00faltimos tiempos, en los que la dejadez del Gobierno est\u00e1 permitiendo que empeoren los seguros que hasta ahora ten\u00edamos, en vez de mejorar\u201d, critic\u00f3 el presidente de ASAJA, quien tambi\u00e9n defendi\u00f3 un papel m\u00e1s activo de la administraci\u00f3n en el control de los abusos en la cadena de valor.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-15502 alignright td-animation-stack-type0-2\" src=\"https:\/\/www.asajacyl.com\/wp-content\/uploads\/2019\/09\/valladolid-4-300x202.jpg\" alt=\"\" width=\"300\" height=\"202\" \/>Tambi\u00e9n fueron tratados temas de actualidad y preocupaci\u00f3n en el campo, como la plaga de topillos, y la multiplicaci\u00f3n de fauna silvestre, con los problemas sanitarios que acarrea, as\u00ed como la l\u00ednea de pr\u00e9stamos por sequ\u00eda, que pr\u00f3ximamente convocar\u00e1 la Consejer\u00eda.<\/p>\n<p>Por su parte, el consejero de Agricultura, Ganader\u00eda y Desarrollo Rural agradeci\u00f3 la invitaci\u00f3n de ASAJA, destacando su liderazgo y su representatividad en las nueve provincias de la Comunidad Aut\u00f3noma, \u201cprueba del m\u00fasculo que esta organizaci\u00f3n tiene en el campo\u201d. Coincidi\u00f3 con ASAJA en que el principal problema del sector es el relevo generacional, y que medidas como las concentraciones o la mejora de los regad\u00edos son fundamentales. Tambi\u00e9n pidi\u00f3 a los medios de comunicaci\u00f3n, y al sector y la sociedad en su conjunto, que contribuyan para dar una mejor imagen de la profesi\u00f3n:\u00a0\u201ccon frecuencia se destaca lo negativo, cuando hay muchas cosas buenas que tiene la agricultura y la ganader\u00eda de las que no se habla. Hay que resaltar lo positivo de esta profesi\u00f3n para poder atraer a los j\u00f3venes al campo\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-15499 aligncenter td-animation-stack-type0-2\" src=\"https:\/\/www.asajacyl.com\/wp-content\/uploads\/2019\/09\/VALLADOLID-2-300x180.jpg\" alt=\"\" width=\"300\" height=\"180\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El consejero recoge las peticiones de la OPA de incrementar las concentraciones parcelarias y mejorar los regad\u00edos ASAJA ha valorado la receptividad del consejero de Agricultura, Ganader\u00eda y Desarrollo Rural, Jes\u00fas Julio Carnero, a las propuestas que la organizaci\u00f3n profesional agraria y ganadera le ha transmitido para que en esta legislatura se den pasos muy [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":5290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA pide a Carnero una legislatura con pol\u00edticas que impulsen un campo m\u00e1s competitivo y rentable - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"El consejero recoge las peticiones de la OPA de incrementar las concentraciones parcelarias y mejorar los regad\u00edos ASAJA ha valorado la receptividad del\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA pide a Carnero una legislatura con pol\u00edticas que impulsen un campo m\u00e1s competitivo y rentable - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"El consejero recoge las peticiones de la OPA de incrementar las concentraciones parcelarias y mejorar los regad\u00edos ASAJA ha valorado la receptividad del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-20T15:30:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-24T10:47:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/09\/VALLADOLID-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable\",\"name\":\"ASAJA pide a Carnero una legislatura con pol\u00edticas que impulsen un campo m\u00e1s competitivo y rentable - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/09\/VALLADOLID-2.jpg\",\"datePublished\":\"2019-09-20T15:30:25+00:00\",\"dateModified\":\"2019-09-24T10:47:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"El consejero recoge las peticiones de la OPA de incrementar las concentraciones parcelarias y mejorar los regad\u00edos ASAJA ha valorado la receptividad del\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/09\/VALLADOLID-2.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/09\/VALLADOLID-2.jpg\",\"width\":2500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA pide a Carnero una legislatura con pol\u00edticas que impulsen un campo m\u00e1s competitivo y rentable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA pide a Carnero una legislatura con pol\u00edticas que impulsen un campo m\u00e1s competitivo y rentable - ASAJA \u00c1vila","description":"El consejero recoge las peticiones de la OPA de incrementar las concentraciones parcelarias y mejorar los regad\u00edos ASAJA ha valorado la receptividad del","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable","og_locale":"es_ES","og_type":"article","og_title":"ASAJA pide a Carnero una legislatura con pol\u00edticas que impulsen un campo m\u00e1s competitivo y rentable - ASAJA \u00c1vila","og_description":"El consejero recoge las peticiones de la OPA de incrementar las concentraciones parcelarias y mejorar los regad\u00edos ASAJA ha valorado la receptividad del","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable","og_site_name":"ASAJA \u00c1vila","article_published_time":"2019-09-20T15:30:25+00:00","article_modified_time":"2019-09-24T10:47:34+00:00","og_image":[{"width":2500,"height":1500,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/09\/VALLADOLID-2.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable","name":"ASAJA pide a Carnero una legislatura con pol\u00edticas que impulsen un campo m\u00e1s competitivo y rentable - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/09\/VALLADOLID-2.jpg","datePublished":"2019-09-20T15:30:25+00:00","dateModified":"2019-09-24T10:47:34+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"El consejero recoge las peticiones de la OPA de incrementar las concentraciones parcelarias y mejorar los regad\u00edos ASAJA ha valorado la receptividad del","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/09\/VALLADOLID-2.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/09\/VALLADOLID-2.jpg","width":2500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-pide-carnero-una-legislatura-politicas-impulsen-campo-mas-competitivo-rentable#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA pide a Carnero una legislatura con pol\u00edticas que impulsen un campo m\u00e1s competitivo y rentable"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/5289"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=5289"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/5289\/revisions"}],"predecessor-version":[{"id":5291,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/5289\/revisions\/5291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/5290"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=5289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=5289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=5289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}