{"id":5367,"date":"2019-10-03T20:02:29","date_gmt":"2019-10-03T18:02:29","guid":{"rendered":"https:\/\/www.asajacyl.com\/avila\/?p=5367"},"modified":"2019-10-04T08:04:22","modified_gmt":"2019-10-04T06:04:22","slug":"asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos","title":{"rendered":"ASAJA reclama a Pedro S\u00e1nchez m\u00e1xima presi\u00f3n internacional para evitar nuevos aranceles americanos"},"content":{"rendered":"<h5><strong>Pedro Barato: \u201cSi la agricultura no puede ser moneda de cambio en los acuerdos comerciales con terceros pa\u00edses, menos a\u00fan podemos ser rehenes en las guerras comerciales entre potencias mundiales\u201d<\/strong><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-15593 alignright td-animation-stack-type0-2\" src=\"https:\/\/www.asajacyl.com\/wp-content\/uploads\/2019\/10\/trump-300x169.jpeg\" alt=\"\" width=\"300\" height=\"169\" \/>Si la Comisi\u00f3n Europea no consigue evitarlo, a partir del pr\u00f3ximo 18 de octubre la Administraci\u00f3n Trump podr\u00eda aplicar aranceles de hasta un 25% a determinados productos agroalimentarios de los pa\u00edses que forman parte del consorcio Airbus (Espa\u00f1a, Francia, Alemania y Reino Unido),\u00a0 por un montante que podr\u00eda llegar a los 7.500 millones de d\u00f3lares. Espa\u00f1a, junto con Francia ser\u00e1 el pa\u00eds m\u00e1s afectado por este gravamen porque entre las\u00a0 producciones penalizadas se encuentran el aceite de oliva, el vino, las frutas y hortalizas, los quesos y la aceituna de mesa, todos ellos productos netamente mediterr\u00e1neos.<\/p>\n<p>El anuncio por parte de los EE.UU. de nuevos aranceles de un 25% a determinados productos agrarios procedentes de los pa\u00edses socios del consorcio Airbus, entre los que se encuentra Espa\u00f1a, y el posterior visto bueno de la OMC a esta decisi\u00f3n,\u00a0 ha causado gran preocupaci\u00f3n en el sector productor y exportador espa\u00f1ol que tiene en el mercado estadounidense una importante fuente de clientes y negocio.<\/p>\n<p>Esta noticia supone un nuevo jarro de agua fr\u00eda para productores y exportadores agroalimentarios, algunos de los cuales ya est\u00e1n sufriendo la imposici\u00f3n de aranceles unilaterales, en concreto a la aceituna negra, que ha supuesto un recorte muy significativo de las exportaciones espa\u00f1olas de aceituna al mercado estadounidense. Adem\u00e1s de estos aranceles espec\u00edficos para los pa\u00edses del\u00a0 consorcio Airbus hay que a\u00f1adir los que se aplicar\u00e1n a los 28 pa\u00edses miembros de la UE y que afectan a ciertos productos derivados del cerdo, frutas y hortalizas, c\u00edtricos, l\u00e1cteos y mariscos, entre otros.<\/p>\n<p>Espa\u00f1a exporta anualmente a EE.UU. productos agroalimentarios por un valor cercano a los 2.000 millones de euros, de los cuales frutas y hortalizas, aceite de oliva, vino y licores, quesos y derivados c\u00e1rnicos son casi un 75% del total de las exportaciones agroalimentarias. Un arancel que supone una cuarta parte del valor de la producci\u00f3n nos da una idea bastante aproximada de las consecuencias que puede tener en las ventas en el pa\u00eds norteamericano.<\/p>\n<p>Por todo ello, ASAJA reclama a nuestro Gobierno, a pesar de estar en funciones, que multiplique sus gestiones y refuerce la presi\u00f3n ante las instituciones comunitarias, especialmente ante la comisaria de Comercio, Cecilia Maalstrom, el actual comisario de Agricultura y futuro comisario de Comercio Phil Hogan,\u00a0 y el todav\u00eda presidente de la Comisi\u00f3n Juncker, as\u00ed como a la presidenta electa Ursula Von der Leyen, para encontrar una soluci\u00f3n satisfactoria a los intereses exportadores de nuestros productores, cooperativas e industrias agroalimentarias. Hay que recordar que nuestro sector \u00a0agroexportador es uno de los principales contribuyentes a la recuperaci\u00f3n econ\u00f3mica del pa\u00eds\u00a0 y que genera gran cantidad de puestos de trabajo y est\u00e1 formado por peque\u00f1as y medianas empresas instaladas en el medio rural.<\/p>\n<p>La UE tiene presentado un recurso similar al planteado por EEUU, ante la OMC por las subvenciones otorgadas por el gobierno norteamericano a la compa\u00f1\u00eda a\u00e9rea Boeing. Podr\u00eda darse el caso que la OMC autorizara medidas arancelarias a la entrada de productos americanos en Europa. De hecho la UE ya present\u00f3 el pasado mes de abril la lista de productos potencialmente afectados. En ning\u00fan caso ser\u00eda bueno entrar en esta espiral de medidas de retorsi\u00f3n que solo perjudican a productores, usuarios y consumidores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pedro Barato: \u201cSi la agricultura no puede ser moneda de cambio en los acuerdos comerciales con terceros pa\u00edses, menos a\u00fan podemos ser rehenes en las guerras comerciales entre potencias mundiales\u201d Si la Comisi\u00f3n Europea no consigue evitarlo, a partir del pr\u00f3ximo 18 de octubre la Administraci\u00f3n Trump podr\u00eda aplicar aranceles de hasta un 25% a [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":5368,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA reclama a Pedro S\u00e1nchez m\u00e1xima presi\u00f3n internacional para evitar nuevos aranceles americanos - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"Pedro Barato: \u201cSi la agricultura no puede ser moneda de cambio en los acuerdos comerciales con terceros pa\u00edses, menos a\u00fan podemos ser rehenes en las\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA reclama a Pedro S\u00e1nchez m\u00e1xima presi\u00f3n internacional para evitar nuevos aranceles americanos - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"Pedro Barato: \u201cSi la agricultura no puede ser moneda de cambio en los acuerdos comerciales con terceros pa\u00edses, menos a\u00fan podemos ser rehenes en las\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-03T18:02:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-04T06:04:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/10\/PEDRO-BARATO-Y-PEDRO-S\u00c1NCHEZ.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"510\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos\",\"name\":\"ASAJA reclama a Pedro S\u00e1nchez m\u00e1xima presi\u00f3n internacional para evitar nuevos aranceles americanos - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/10\/PEDRO-BARATO-Y-PEDRO-S\u00c1NCHEZ.jpg\",\"datePublished\":\"2019-10-03T18:02:29+00:00\",\"dateModified\":\"2019-10-04T06:04:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\"},\"description\":\"Pedro Barato: \u201cSi la agricultura no puede ser moneda de cambio en los acuerdos comerciales con terceros pa\u00edses, menos a\u00fan podemos ser rehenes en las\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/10\/PEDRO-BARATO-Y-PEDRO-S\u00c1NCHEZ.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/10\/PEDRO-BARATO-Y-PEDRO-S\u00c1NCHEZ.jpg\",\"width\":680,\"height\":510},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA reclama a Pedro S\u00e1nchez m\u00e1xima presi\u00f3n internacional para evitar nuevos aranceles americanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed\",\"name\":\"Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g\",\"caption\":\"Joaqu\u00edn\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA reclama a Pedro S\u00e1nchez m\u00e1xima presi\u00f3n internacional para evitar nuevos aranceles americanos - ASAJA \u00c1vila","description":"Pedro Barato: \u201cSi la agricultura no puede ser moneda de cambio en los acuerdos comerciales con terceros pa\u00edses, menos a\u00fan podemos ser rehenes en las","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos","og_locale":"es_ES","og_type":"article","og_title":"ASAJA reclama a Pedro S\u00e1nchez m\u00e1xima presi\u00f3n internacional para evitar nuevos aranceles americanos - ASAJA \u00c1vila","og_description":"Pedro Barato: \u201cSi la agricultura no puede ser moneda de cambio en los acuerdos comerciales con terceros pa\u00edses, menos a\u00fan podemos ser rehenes en las","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos","og_site_name":"ASAJA \u00c1vila","article_published_time":"2019-10-03T18:02:29+00:00","article_modified_time":"2019-10-04T06:04:22+00:00","og_image":[{"width":680,"height":510,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/10\/PEDRO-BARATO-Y-PEDRO-S\u00c1NCHEZ.jpg","type":"image\/jpeg"}],"author":"Joaqu\u00edn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joaqu\u00edn","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos","name":"ASAJA reclama a Pedro S\u00e1nchez m\u00e1xima presi\u00f3n internacional para evitar nuevos aranceles americanos - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/10\/PEDRO-BARATO-Y-PEDRO-S\u00c1NCHEZ.jpg","datePublished":"2019-10-03T18:02:29+00:00","dateModified":"2019-10-04T06:04:22+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed"},"description":"Pedro Barato: \u201cSi la agricultura no puede ser moneda de cambio en los acuerdos comerciales con terceros pa\u00edses, menos a\u00fan podemos ser rehenes en las","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/10\/PEDRO-BARATO-Y-PEDRO-S\u00c1NCHEZ.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2019\/10\/PEDRO-BARATO-Y-PEDRO-S\u00c1NCHEZ.jpg","width":680,"height":510},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-reclama-pedro-sanchez-maxima-presion-internacional-evitar-nuevos-aranceles-americanos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA reclama a Pedro S\u00e1nchez m\u00e1xima presi\u00f3n internacional para evitar nuevos aranceles americanos"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/daf3c5c7d3afd005798ec283b78826ed","name":"Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a87f10166ff5a8a3b0c21a125bc069d?s=96&d=mm&r=g","caption":"Joaqu\u00edn"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/joaquinap"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/5367"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=5367"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/5367\/revisions"}],"predecessor-version":[{"id":5369,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/5367\/revisions\/5369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/5368"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=5367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=5367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=5367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}