{"id":904,"date":"2017-05-19T00:00:00","date_gmt":"2017-05-18T22:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/avila\/sin-categoria\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos"},"modified":"2017-05-19T00:00:00","modified_gmt":"2017-05-18T22:00:00","slug":"el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos","title":{"rendered":"EL N&#218;MERO DE SOLICITANTES PAC EN CASTILLA Y LE&#211;N SE REDUJO UN 15 POR CIENTO EN LOS &#218;LTIMOS 4 A&#209;OS"},"content":{"rendered":"<h2>La mayor profesionalizaci&#243;n se traduce en que pese al descenso de solicitudes crezca el n&#250;mero tramitado desde ASAJA<\/h2>\n<p>ASAJA recuerda que a&#250;n las cifras de perceptores est&#225;n bastante por encima de las de profesionales del sector cotizantes a la SS<\/p>\n<p>La mayor profesionalizaci&#243;n se traduce en que pese al descenso de solicitudes crezca el n&#250;mero tramitado desde ASAJA<\/p>\n<p>Los datos oficiales apuntan que entre el a&#241;o 2014 y el 2017 ha habido en Castilla y Le&#243;n una significativa reducci&#243;n de las solicitudes &#250;nicas de ayudas de la Pol&#237;tica Agr&#237;cola Com&#250;n (PAC). En esta campa&#241;a, reci&#233;n concluida, se han registrado 74.995 solicitudes, 13.606 menos que hace cuatro a&#241;os, lo que significa una disminuci&#243;n del 15,32 por ciento. El descenso es apreciable en toda la Comunidad Aut&#243;noma, con porcentajes que oscilan entre el 11 y el 21 por ciento, seg&#250;n provincias. Adem&#225;s, hay que tener en cuenta que unas 11.008 solicitudes se acogen al r&#233;gimen de &#8220;peque&#241;os productores&#8221; (importes inferiores a 1.250 &#8364;), un grupo en el que predominan perceptores que tienen la agricultura como renta complementaria, con lo que se reduce a&#250;n m&#225;s el n&#250;mero de titulares que son profesionales del sector. Esa profesionalizaci&#243;n explica por qu&#233; no desciende la superficie declarada: aunque este a&#241;o hay 4.532 solicitudes menos que el anterior, la superficie es la misma que en 2016, superando los 3,2 millones de hect&#225;reas: se mantiene el mismo nivel de actividad, con mayor eficacia.<br \/>\nEl descenso se debe principalmente a que con la PAC actual y la figura del &#8216;agricultor activo&#8221; se exige al solicitante como requisito cobrar al menos 300 euros, adem&#225;s de a motivos como los cambios de titularidad y a la progresiva concentraci&#243;n de las explotaciones agrarias. Para ASAJA, &#8220;es fundamental que la pol&#237;tica agraria com&#250;n concentre su apoyo en los verdaderos profesionales del sector, por justicia y tambi&#233;n por que cada vez la financiaci&#243;n es m&#225;s escasa, y m&#225;s a partir de la salida del Reino Unido por el brexit&#8221;, se&#241;ala ASAJA. Si se cruzan los datos del n&#250;mero de expedientes tramitados en los que se cobra pago b&#225;sico y pago verde &#8211;61.977&#8211;, excluyendo por lo tanto a los peque&#241;os productores, con los cotizantes a la Seguridad Social como agricultores &#8211;41.000&#8211;, se comprueba que el 66,3% de los solicitantes son agricultores a tiempo completo, y que el resto, el 33,6%, tienen la agricultura y la ganader&#237;a como un complemento de rentas. Dos de cada tres perceptores de ayudas de Castilla y Le&#243;n son profesionales, un porcentaje en todo caso superior al del conjunto de Espa&#241;a.<br \/>\nSin embargo, aunque el n&#250;mero global de PAC presentadas en Castilla y Le&#243;n ha descendido, ha aumentado el n&#250;mero de expedientes presentados desde ASAJA, sumando cerca de 12.000 en la Comunidad Aut&#243;noma, lo que confirma su liderazgo como organizaci&#243;n, y a gran distancia del resto, en tramitaci&#243;n de PAC. En el mismo periodo 2014-2017 que no ha dejado de bajar el n&#250;mero de solicitantes PAC, ha seguido creciendo los agricultores y ganaderos que han confiado a ASAJA la tramitaci&#243;n de su ayuda, siendo hoy un 11 por ciento m&#225;s que hace cuatro a&#241;os. Esta tendencia pone de manifiesto la progresiva profesionalizaci&#243;n del sector, que conlleva que las entidades financieras pierdan solicitantes a favor de los t&#233;cnicos especializados de las organizaciones profesionales agrarias. <\/p>\n<p>Fin del plazo de solicitudes PAC<br \/>\nComo bien saben los agricultores, la campa&#241;a PAC no termina el d&#237;a que acaba el plazo, en este caso el pasado 15 de mayo. Esta segunda quincena de mayo los equipos t&#233;cnicos de las organizaciones agrarias siguen trabajando, puesto que hay que filtrar duplicidades y corregir los cambios de cultivos, que ser&#225;n abundantes en una campa&#241;a tan dif&#237;cil como la actual. Adem&#225;s, todav&#237;a est&#225; abierto en mayo el plazo para efectuar cesiones de derechos. El objetivo de ASAJA es concluir todo &#8220;en tiempo y forma, para que la administraci&#243;n cumpla con su compromiso de que el anticipo de la PAC llegue lo antes posible, tal como necesitan los agricultores y ganaderos&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mayor profesionalizaci&#243;n se traduce en que pese al descenso de solicitudes crezca el n&#250;mero tramitado desde ASAJA<\/p>\n","protected":false},"author":3,"featured_media":469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EL N&#218;MERO DE SOLICITANTES PAC EN CASTILLA Y LE&#211;N SE REDUJO UN 15 POR CIENTO EN LOS &#218;LTIMOS 4 A&#209;OS - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"La mayor profesionalizaci&#243;n se traduce en que pese al descenso de solicitudes crezca el n&#250;mero tramitado desde ASAJA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EL N&#218;MERO DE SOLICITANTES PAC EN CASTILLA Y LE&#211;N SE REDUJO UN 15 POR CIENTO EN LOS &#218;LTIMOS 4 A&#209;OS - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"La mayor profesionalizaci&#243;n se traduce en que pese al descenso de solicitudes crezca el n&#250;mero tramitado desde ASAJA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-18T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/PAC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"448\" \/>\n\t<meta property=\"og:image:height\" content=\"119\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos\",\"name\":\"EL N&#218;MERO DE SOLICITANTES PAC EN CASTILLA Y LE&#211;N SE REDUJO UN 15 POR CIENTO EN LOS &#218;LTIMOS 4 A&#209;OS - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/PAC.jpg\",\"datePublished\":\"2017-05-18T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"La mayor profesionalizaci&#243;n se traduce en que pese al descenso de solicitudes crezca el n&#250;mero tramitado desde ASAJA\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/PAC.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/PAC.jpg\",\"width\":448,\"height\":119,\"caption\":\"Abierto el plazo de presentaci\u00f3n de solicitudes de la PAC 2017\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EL N&#218;MERO DE SOLICITANTES PAC EN CASTILLA Y LE&#211;N SE REDUJO UN 15 POR CIENTO EN LOS &#218;LTIMOS 4 A&#209;OS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EL N&#218;MERO DE SOLICITANTES PAC EN CASTILLA Y LE&#211;N SE REDUJO UN 15 POR CIENTO EN LOS &#218;LTIMOS 4 A&#209;OS - ASAJA \u00c1vila","description":"La mayor profesionalizaci&#243;n se traduce en que pese al descenso de solicitudes crezca el n&#250;mero tramitado desde ASAJA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos","og_locale":"es_ES","og_type":"article","og_title":"EL N&#218;MERO DE SOLICITANTES PAC EN CASTILLA Y LE&#211;N SE REDUJO UN 15 POR CIENTO EN LOS &#218;LTIMOS 4 A&#209;OS - ASAJA \u00c1vila","og_description":"La mayor profesionalizaci&#243;n se traduce en que pese al descenso de solicitudes crezca el n&#250;mero tramitado desde ASAJA","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos","og_site_name":"ASAJA \u00c1vila","article_published_time":"2017-05-18T22:00:00+00:00","og_image":[{"width":448,"height":119,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/PAC.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos","name":"EL N&#218;MERO DE SOLICITANTES PAC EN CASTILLA Y LE&#211;N SE REDUJO UN 15 POR CIENTO EN LOS &#218;LTIMOS 4 A&#209;OS - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/PAC.jpg","datePublished":"2017-05-18T22:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"La mayor profesionalizaci&#243;n se traduce en que pese al descenso de solicitudes crezca el n&#250;mero tramitado desde ASAJA","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/PAC.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/PAC.jpg","width":448,"height":119,"caption":"Abierto el plazo de presentaci\u00f3n de solicitudes de la PAC 2017"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-nmero-de-solicitantes-pac-en-castilla-y-len-se-redujo-un-15-por-ciento-en-los-ltimos-4-aos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"EL N&#218;MERO DE SOLICITANTES PAC EN CASTILLA Y LE&#211;N SE REDUJO UN 15 POR CIENTO EN LOS &#218;LTIMOS 4 A&#209;OS"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/904"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=904"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/904\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/469"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}