{"id":905,"date":"2017-05-18T00:00:00","date_gmt":"2017-05-17T22:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/avila\/sin-categoria\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto"},"modified":"2017-05-18T00:00:00","modified_gmt":"2017-05-17T22:00:00","slug":"el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto","title":{"rendered":"El ministerio, como la consejer&#237;a: buenas palabras y cero presupuesto"},"content":{"rendered":"<h2>Sin avances en la segunda reuni&#243;n en Madrid para analizar la evoluci&#243;n de la sequ&#237;a y da&#241;os en el sector agroganadero<\/h2>\n<p style=\"margin: 0px; padding: 10px 0px; color: rgb(118, 118, 118); font-family: Arial, Helvetica, sans-serif; font-size: 14.3px; line-height: 22px; text-align: justify;\">\nNing&#250;n avance en la segunda reuni&#243;n, celebrada hoy en Madrid, del Grupo de Trabajo COPAC-Sequ&#237;a, convocada por el Ministerio, para analizar la sequ&#237;a actual y los da&#241;os en el sector agrario y ganadero. El pron&#243;stico de la evoluci&#243;n de la producci&#243;n en Castilla y Le&#243;n es muy similar al ofrecido el pasado 28 de abril, aunque las lluvias ca&#237;das en torno a San Isidro han aliviado parte del secano m&#225;s tard&#237;o; sin embargo, la situaci&#243;n nada ha cambiado en regad&#237;o, y a&#250;n es peor en los cultivos afectados por las heladas, como vi&#241;edos, frutales, l&#250;pulo y otros t&#237;picos de siembra de primavera, mientras que en pastos apenas ha habido cambios porque el agua ca&#237;da no garantiza en modo alguno reservas. Tal como apunta Donaciano Dujo, que ha representado a ASAJA en la reuni&#243;n, &#8220;a d&#237;a de hoy el secano de Castilla y Le&#243;n podr&#237;a dividirse en tres partes: de las cerca de dos millones de hect&#225;reas, unas 650.000 estar&#237;an esquilmadas, y ofrecer&#237;an menos de 1.000 kilos por hect&#225;rea; otro tercio estar&#237;a entre los 1.000 y 2.000 kilos, y el tercio restante subir&#237;a un poco m&#225;s&#8221;. En todo caso, unas producciones muy por debajo de los 3.300 kilos hect&#225;rea que como media se obtienen en la Comunidad Aut&#243;noma.<\/p>\n<p style=\"margin: 0px; padding: 10px 0px; color: rgb(118, 118, 118); font-family: Arial, Helvetica, sans-serif; font-size: 14.3px; line-height: 22px; text-align: justify;\">\nEl ministerio de Agricultura &#8220;no se ha movido un mil&#237;metro y sigue el mismo esquema que la Consejer&#237;a: buenas palabras y cero presupuesto&#8221;, resume Donaciano Dujo. Las propuestas de Madrid son de contexto (reducciones fiscales, de Seguridad Social o cuotas de riego, facilitar pr&#233;stamos&#8230;) pero da la espalda a cualquier ayuda directa. S&#237; ha dado un paso al frente alguna comunidad aut&#243;noma, como la vecina La Rioja, que habla de aprobar ayudas de minimis para el vacuno de extensivo. &#8220;Lamentamos la cerraz&#243;n de las administraciones, que est&#225;n obcecadas en no gastar y para ello quieren negarse a ver la total gravedad y desamparo de miles de profesionales del sector&#8221;, denuncia Donaciano Dujo, que subraya la &#8220;absoluta determinaci&#243;n de ASAJA de seguir reclamando ayudas directas que garanticen la continuidad de las explotaciones profesionales m&#225;s castigadas&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sin avances en la segunda reuni&#243;n en Madrid para analizar la evoluci&#243;n de la sequ&#237;a y da&#241;os en el sector agroganadero<\/p>\n","protected":false},"author":3,"featured_media":794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El ministerio, como la consejer&#237;a: buenas palabras y cero presupuesto - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"Sin avances en la segunda reuni&#243;n en Madrid para analizar la evoluci&#243;n de la sequ&#237;a y da&#241;os en el sector agroganadero\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El ministerio, como la consejer&#237;a: buenas palabras y cero presupuesto - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"Sin avances en la segunda reuni&#243;n en Madrid para analizar la evoluci&#243;n de la sequ&#237;a y da&#241;os en el sector agroganadero\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-17T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto\",\"name\":\"El ministerio, como la consejer&#237;a: buenas palabras y cero presupuesto - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2017-05-17T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Sin avances en la segunda reuni&#243;n en Madrid para analizar la evoluci&#243;n de la sequ&#237;a y da&#241;os en el sector agroganadero\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA \u00c1vila\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El ministerio, como la consejer&#237;a: buenas palabras y cero presupuesto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El ministerio, como la consejer&#237;a: buenas palabras y cero presupuesto - ASAJA \u00c1vila","description":"Sin avances en la segunda reuni&#243;n en Madrid para analizar la evoluci&#243;n de la sequ&#237;a y da&#241;os en el sector agroganadero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto","og_locale":"es_ES","og_type":"article","og_title":"El ministerio, como la consejer&#237;a: buenas palabras y cero presupuesto - ASAJA \u00c1vila","og_description":"Sin avances en la segunda reuni&#243;n en Madrid para analizar la evoluci&#243;n de la sequ&#237;a y da&#241;os en el sector agroganadero","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto","og_site_name":"ASAJA \u00c1vila","article_published_time":"2017-05-17T22:00:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto","name":"El ministerio, como la consejer&#237;a: buenas palabras y cero presupuesto - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2017-05-17T22:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Sin avances en la segunda reuni&#243;n en Madrid para analizar la evoluci&#243;n de la sequ&#237;a y da&#241;os en el sector agroganadero","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA \u00c1vila"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/el-ministerio-como-la-consejera-buenas-palabras-y-cero-presupuesto#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"El ministerio, como la consejer&#237;a: buenas palabras y cero presupuesto"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/905"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=905"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/794"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}