{"id":921,"date":"2017-04-11T00:00:00","date_gmt":"2017-04-10T22:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/avila\/sin-categoria\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo"},"modified":"2017-04-11T00:00:00","modified_gmt":"2017-04-10T22:00:00","slug":"asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo","title":{"rendered":"ASAJA CELEBRA QUE SE RECONOZCA EL VALOR DE LA TRASHUMANCIA PERO RECUERDA QUE SE SUSTENTA SOBRE UNA ACTIVIDAD ECON&#211;MICA QUE PRECISA DE APOYO"},"content":{"rendered":"<h2>ASAJA pide a las administraciones competentes que m&#225;s all&#225; de los reconocimientos sean conscientes de los problemas a los que se enfrentan estos ganaderos que todav&#237;a mantienen la trashumancia como algo vivo, no solo otra bonita fotograf&#237;a en un museo.<\/h2>\n<p>Hoy aparece en el Bolet&#237;n Oficial del Estado el Real Decreto del Ministerio de Educaci&#243;n y Cultura por el que se declara la Trashumancia como Manifestaci&#243;n Representativa del Patrimonio Cultural Inmaterial de Espa&#241;a. ASAJA celebra que la trashumancia reciba este merecido reconocimiento por sus inmensas aportaciones durante siglos al desarrollo econ&#243;mico, social y cultural de nuestro pa&#237;s; sin embargo, quiere puntualizar que este rico patrimonio inmaterial se sostiene gracias a una actividad econ&#243;mica y pr&#225;ctica ganadera real, que como tal debe ser protegida por el Ministerio de Agricultura y la Junta de Castilla y Le&#243;n.<br \/>\n    Esta protecci&#243;n en muchos casos ha sido m&#237;nima cuando no inexistente, lo que explica que hoy por hoy, la trashumancia en ovino, la que durante siglos ha ocupado las v&#237;as pecuarias de la meseta, salvo algunos honrosos casos, est&#233; pr&#225;cticamente a extinguir. Ha aumentado, por el contrario, la trashumancia o en su caso trasterminancia (movimiento dentro de la misma provincia) para el caso del vacuno de extensivo, desde las zonas del per&#237;metro monta&#241;oso de Castilla y Le&#243;n a &#225;reas de interior. Los duros inviernos, sin pastos ni sitio donde proteger a las vacas nodrizas, obligan a los ganaderos a transportar los animales hasta la llegada de la primavera.<br \/>\n    Pese a los reconocimientos verbales que recibe, lo cierto es que hay muy pocas ayudas espec&#237;ficas para apoyar a la trashumancia. Por el contrario, est&#225; sujeta a multitud de trabas burocr&#225;ticas que complican el movimiento de animales, as&#237; como licencias sobre pastos y multitud de normativas. Por su propia naturaleza itinerante, la trashumancia implica normalmente a m&#225;s de una comunidad aut&#243;noma, lo que significa tener que someterse a legislaciones no siempre coincidentes en materias clave como la sanidad animal, y no s&#243;lo por las normativas auton&#243;micas espec&#237;ficas, sino tambi&#233;n por el modo diverso que tiene cada regi&#243;n de interpretar las leyes del Estado y de la Uni&#243;n Europea. Todo ello limita la pr&#225;ctica de la trashumancia a un determinado tipo de ganader&#237;as, las que por absoluta necesidad tienen que seguir practic&#225;ndola.<br \/>\n    ASAJA pide a las administraciones competentes que m&#225;s all&#225; de los reconocimientos sean conscientes de los problemas a los que se enfrentan estos ganaderos que todav&#237;a mantienen la trashumancia como algo vivo, no solo otra bonita fotograf&#237;a en un museo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ASAJA pide a las administraciones competentes que m&#225;s all&#225; de los reconocimientos sean conscientes de los problemas a los que se enfrentan estos ganaderos que todav&#237;a mantienen la trashumancia como algo vivo, no solo otra bonita fotograf&#237;a en un museo.<\/p>\n","protected":false},"author":3,"featured_media":922,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA CELEBRA QUE SE RECONOZCA EL VALOR DE LA TRASHUMANCIA PERO RECUERDA QUE SE SUSTENTA SOBRE UNA ACTIVIDAD ECON&#211;MICA QUE PRECISA DE APOYO - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"ASAJA pide a las administraciones competentes que m&#225;s all&#225; de los reconocimientos sean conscientes de los problemas a los que se enfrentan estos ganaderos que todav&#237;a mantienen la trashumancia como algo vivo, no solo otra bonita fotograf&#237;a en un museo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA CELEBRA QUE SE RECONOZCA EL VALOR DE LA TRASHUMANCIA PERO RECUERDA QUE SE SUSTENTA SOBRE UNA ACTIVIDAD ECON&#211;MICA QUE PRECISA DE APOYO - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"ASAJA pide a las administraciones competentes que m&#225;s all&#225; de los reconocimientos sean conscientes de los problemas a los que se enfrentan estos ganaderos que todav&#237;a mantienen la trashumancia como algo vivo, no solo otra bonita fotograf&#237;a en un museo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-10T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMGP6715.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3072\" \/>\n\t<meta property=\"og:image:height\" content=\"2304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo\",\"name\":\"ASAJA CELEBRA QUE SE RECONOZCA EL VALOR DE LA TRASHUMANCIA PERO RECUERDA QUE SE SUSTENTA SOBRE UNA ACTIVIDAD ECON&#211;MICA QUE PRECISA DE APOYO - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMGP6715.jpg\",\"datePublished\":\"2017-04-10T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"ASAJA pide a las administraciones competentes que m&#225;s all&#225; de los reconocimientos sean conscientes de los problemas a los que se enfrentan estos ganaderos que todav&#237;a mantienen la trashumancia como algo vivo, no solo otra bonita fotograf&#237;a en un museo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMGP6715.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMGP6715.jpg\",\"width\":3072,\"height\":2304},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA CELEBRA QUE SE RECONOZCA EL VALOR DE LA TRASHUMANCIA PERO RECUERDA QUE SE SUSTENTA SOBRE UNA ACTIVIDAD ECON&#211;MICA QUE PRECISA DE APOYO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA CELEBRA QUE SE RECONOZCA EL VALOR DE LA TRASHUMANCIA PERO RECUERDA QUE SE SUSTENTA SOBRE UNA ACTIVIDAD ECON&#211;MICA QUE PRECISA DE APOYO - ASAJA \u00c1vila","description":"ASAJA pide a las administraciones competentes que m&#225;s all&#225; de los reconocimientos sean conscientes de los problemas a los que se enfrentan estos ganaderos que todav&#237;a mantienen la trashumancia como algo vivo, no solo otra bonita fotograf&#237;a en un museo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo","og_locale":"es_ES","og_type":"article","og_title":"ASAJA CELEBRA QUE SE RECONOZCA EL VALOR DE LA TRASHUMANCIA PERO RECUERDA QUE SE SUSTENTA SOBRE UNA ACTIVIDAD ECON&#211;MICA QUE PRECISA DE APOYO - ASAJA \u00c1vila","og_description":"ASAJA pide a las administraciones competentes que m&#225;s all&#225; de los reconocimientos sean conscientes de los problemas a los que se enfrentan estos ganaderos que todav&#237;a mantienen la trashumancia como algo vivo, no solo otra bonita fotograf&#237;a en un museo.","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo","og_site_name":"ASAJA \u00c1vila","article_published_time":"2017-04-10T22:00:00+00:00","og_image":[{"width":3072,"height":2304,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMGP6715.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo","name":"ASAJA CELEBRA QUE SE RECONOZCA EL VALOR DE LA TRASHUMANCIA PERO RECUERDA QUE SE SUSTENTA SOBRE UNA ACTIVIDAD ECON&#211;MICA QUE PRECISA DE APOYO - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMGP6715.jpg","datePublished":"2017-04-10T22:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"ASAJA pide a las administraciones competentes que m&#225;s all&#225; de los reconocimientos sean conscientes de los problemas a los que se enfrentan estos ganaderos que todav&#237;a mantienen la trashumancia como algo vivo, no solo otra bonita fotograf&#237;a en un museo.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMGP6715.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/IMGP6715.jpg","width":3072,"height":2304},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-celebra-que-se-reconozca-el-valor-de-la-trashumancia-pero-recuerda-que-se-sustenta-sobre-una-actividad-econmica-que-precisa-de-apoyo#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA CELEBRA QUE SE RECONOZCA EL VALOR DE LA TRASHUMANCIA PERO RECUERDA QUE SE SUSTENTA SOBRE UNA ACTIVIDAD ECON&#211;MICA QUE PRECISA DE APOYO"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/921"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=921"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/921\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/922"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}