{"id":924,"date":"2017-03-31T00:00:00","date_gmt":"2017-03-30T22:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/avila\/sin-categoria\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila"},"modified":"2017-03-31T00:00:00","modified_gmt":"2017-03-30T22:00:00","slug":"mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila","title":{"rendered":"Mil nuevos &#225;rboles para Langa gracias a la intermediaci&#243;n de ASAJA de &#193;vila"},"content":{"rendered":"<h2>La Consejer&#237;a de Fomento y Medio Ambiente ha donado 800 pinos pi&#241;oneros, 50 sauces y 50 fresnos para una reforestaci&#243;n en Langa proyectada por Asaja.<\/h2>\n<p>La Consejer&#237;a de Fomento y Medio Ambiente ha donado 800 pinos pi&#241;oneros, 50 sauces y 50 fresnos para una reforestaci&#243;n en Langa proyectada y gestionada por ASAJA de &#193;vila. <\/p>\n<p>El delegado territorial de la Junta, Jos&#233; Francisco Hern&#225;ndez, ha visitado la localidad, donde se ha reunido con la alcaldesa, Clara Isabel S&#225;ez, para repasar las inversiones de la Administraci&#243;n auton&#243;mica en el municipio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Consejer&#237;a de Fomento y Medio Ambiente ha donado 800 pinos pi&#241;oneros, 50 sauces y 50 fresnos para una reforestaci&#243;n en Langa proyectada por Asaja.<\/p>\n","protected":false},"author":3,"featured_media":794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mil nuevos &#225;rboles para Langa gracias a la intermediaci&#243;n de ASAJA de &#193;vila - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"La Consejer&#237;a de Fomento y Medio Ambiente ha donado 800 pinos pi&#241;oneros, 50 sauces y 50 fresnos para una reforestaci&#243;n en Langa proyectada por Asaja.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mil nuevos &#225;rboles para Langa gracias a la intermediaci&#243;n de ASAJA de &#193;vila - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"La Consejer&#237;a de Fomento y Medio Ambiente ha donado 800 pinos pi&#241;oneros, 50 sauces y 50 fresnos para una reforestaci&#243;n en Langa proyectada por Asaja.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-30T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila\",\"name\":\"Mil nuevos &#225;rboles para Langa gracias a la intermediaci&#243;n de ASAJA de &#193;vila - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2017-03-30T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"La Consejer&#237;a de Fomento y Medio Ambiente ha donado 800 pinos pi&#241;oneros, 50 sauces y 50 fresnos para una reforestaci&#243;n en Langa proyectada por Asaja.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA \u00c1vila\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mil nuevos &#225;rboles para Langa gracias a la intermediaci&#243;n de ASAJA de &#193;vila\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mil nuevos &#225;rboles para Langa gracias a la intermediaci&#243;n de ASAJA de &#193;vila - ASAJA \u00c1vila","description":"La Consejer&#237;a de Fomento y Medio Ambiente ha donado 800 pinos pi&#241;oneros, 50 sauces y 50 fresnos para una reforestaci&#243;n en Langa proyectada por Asaja.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila","og_locale":"es_ES","og_type":"article","og_title":"Mil nuevos &#225;rboles para Langa gracias a la intermediaci&#243;n de ASAJA de &#193;vila - ASAJA \u00c1vila","og_description":"La Consejer&#237;a de Fomento y Medio Ambiente ha donado 800 pinos pi&#241;oneros, 50 sauces y 50 fresnos para una reforestaci&#243;n en Langa proyectada por Asaja.","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila","og_site_name":"ASAJA \u00c1vila","article_published_time":"2017-03-30T22:00:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila","name":"Mil nuevos &#225;rboles para Langa gracias a la intermediaci&#243;n de ASAJA de &#193;vila - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2017-03-30T22:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"La Consejer&#237;a de Fomento y Medio Ambiente ha donado 800 pinos pi&#241;oneros, 50 sauces y 50 fresnos para una reforestaci&#243;n en Langa proyectada por Asaja.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA \u00c1vila"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/mil-nuevos-rboles-para-langa-gracias-a-la-intermediacin-de-asaja-de-vila#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"Mil nuevos &#225;rboles para Langa gracias a la intermediaci&#243;n de ASAJA de &#193;vila"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/924"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=924"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/794"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}