{"id":927,"date":"2017-03-28T00:00:00","date_gmt":"2017-03-27T22:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/avila\/sin-categoria\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera"},"modified":"2017-03-28T00:00:00","modified_gmt":"2017-03-27T22:00:00","slug":"asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera","title":{"rendered":"ASAJA de &#193;vila interpone recurso de alzada contra la prospecci&#243;n minera del Valle del Corneja por su afecci&#243;n a la actividad ganadera"},"content":{"rendered":"<h2>La Asociaci&#243;n Agraria J&#243;venes Agricultores (ASAJA) de &#193;vila ha interpuesto hoy un recurso de alzada contra el otorgamiento del permiso de investigaci&#243;n denominado &#8216;Sonsoles&#8217; para la explotaci&#243;n de feldespatos en los municipios de T&#243;rtoles, Bonilla de la Sierra, Becedillas y Zapardiel de la Ca&#241;ada, al considerar que una prospecci&#243;n minera en esta zona afectar&#237;a gravemente a la actividad ganadera que se desarrolla en esta comarca.<\/h2>\n<p>La Asociaci&#243;n Agraria J&#243;venes Agricultores (ASAJA) de &#193;vila ha interpuesto hoy un recurso de alzada contra el otorgamiento del permiso de investigaci&#243;n denominado &#8216;Sonsoles&#8217; para la explotaci&#243;n de feldespatos en los municipios de T&#243;rtoles, Bonilla de la Sierra, Becedillas y Zapardiel de la Ca&#241;ada, al considerar que una prospecci&#243;n minera en esta zona afectar&#237;a gravemente a la actividad ganadera que se desarrolla en esta comarca. <\/p>\n<p>  La organizaci&#243;n agraria ha presentado recurso de alzada hoy mismo ante el director general de Energ&#237;a y Minas de la Junta de Castilla y Le&#243;n, en apoyo a los vecinos y a los alcaldes de estos municipios, que se han movilizado en contra de la concesi&#243;n de un permiso de investigaci&#243;n minera cuyo objetivo es la explotaci&#243;n o aprovechamiento de feldespatos.  <\/p>\n<p>  El presidente de ASAJA de &#193;vila, Joaqu&#237;n Antonio Pino, ha recordado que la principal actividad econ&#243;mica de T&#243;rtoles, Bonilla de la Sierra, Becedillas y Zapardiel de la Ca&#241;ada es la agraria, especialmente la ganadera, y que &#233;sta se ver&#237;a perjudicada en caso de que este proyecto minero saliera adelante, puesto que afectar&#237;a gravemente tanto a la caba&#241;a ganadera como a los pastos y dehesas en una comarca donde se practica de forma tradicional la ganader&#237;a extensiva, una actividad que da de comer a muchas familias de los municipios afectados.  <\/p>\n<p>  Asimismo, ASAJA de &#193;vila recuerda que la principal actividad econ&#243;mica en estos municipios, y que por tanto es la que contribuye a fijar poblaci&#243;n en este medio rural, es la agraria, de modo que deber&#237;a primarse y protegerse por encima de otras actividades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asociaci&#243;n Agraria J&#243;venes Agricultores (ASAJA) de &#193;vila ha interpuesto hoy un recurso de alzada contra el otorgamiento del permiso de investigaci&#243;n denominado &#8216;Sonsoles&#8217; para la explotaci&#243;n de feldespatos en los municipios de T&#243;rtoles, Bonilla de la Sierra, Becedillas y Zapardiel de la Ca&#241;ada, al considerar que una prospecci&#243;n minera en esta zona afectar&#237;a gravemente a la actividad ganadera que se desarrolla en esta comarca.<\/p>\n","protected":false},"author":3,"featured_media":928,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA de &#193;vila interpone recurso de alzada contra la prospecci&#243;n minera del Valle del Corneja por su afecci&#243;n a la actividad ganadera - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"La Asociaci&#243;n Agraria J&#243;venes Agricultores (ASAJA) de &#193;vila ha interpuesto hoy un recurso de alzada contra el otorgamiento del permiso de investigaci&#243;n denominado &#8216;Sonsoles&#8217; para la explotaci&#243;n de feldespatos en los municipios de T&#243;rtoles, Bonilla de la Sierra, Becedillas y Zapardiel de la Ca&#241;ada, al considerar que una prospecci&#243;n minera en esta zona afectar&#237;a gravemente a la actividad ganadera que se desarrolla en esta comarca.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA de &#193;vila interpone recurso de alzada contra la prospecci&#243;n minera del Valle del Corneja por su afecci&#243;n a la actividad ganadera - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"La Asociaci&#243;n Agraria J&#243;venes Agricultores (ASAJA) de &#193;vila ha interpuesto hoy un recurso de alzada contra el otorgamiento del permiso de investigaci&#243;n denominado &#8216;Sonsoles&#8217; para la explotaci&#243;n de feldespatos en los municipios de T&#243;rtoles, Bonilla de la Sierra, Becedillas y Zapardiel de la Ca&#241;ada, al considerar que una prospecci&#243;n minera en esta zona afectar&#237;a gravemente a la actividad ganadera que se desarrolla en esta comarca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-27T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/bonilladelasierra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera\",\"name\":\"ASAJA de &#193;vila interpone recurso de alzada contra la prospecci&#243;n minera del Valle del Corneja por su afecci&#243;n a la actividad ganadera - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/bonilladelasierra.jpg\",\"datePublished\":\"2017-03-27T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"La Asociaci&#243;n Agraria J&#243;venes Agricultores (ASAJA) de &#193;vila ha interpuesto hoy un recurso de alzada contra el otorgamiento del permiso de investigaci&#243;n denominado &#8216;Sonsoles&#8217; para la explotaci&#243;n de feldespatos en los municipios de T&#243;rtoles, Bonilla de la Sierra, Becedillas y Zapardiel de la Ca&#241;ada, al considerar que una prospecci&#243;n minera en esta zona afectar&#237;a gravemente a la actividad ganadera que se desarrolla en esta comarca.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/bonilladelasierra.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/bonilladelasierra.jpg\",\"width\":500,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA de &#193;vila interpone recurso de alzada contra la prospecci&#243;n minera del Valle del Corneja por su afecci&#243;n a la actividad ganadera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA de &#193;vila interpone recurso de alzada contra la prospecci&#243;n minera del Valle del Corneja por su afecci&#243;n a la actividad ganadera - ASAJA \u00c1vila","description":"La Asociaci&#243;n Agraria J&#243;venes Agricultores (ASAJA) de &#193;vila ha interpuesto hoy un recurso de alzada contra el otorgamiento del permiso de investigaci&#243;n denominado &#8216;Sonsoles&#8217; para la explotaci&#243;n de feldespatos en los municipios de T&#243;rtoles, Bonilla de la Sierra, Becedillas y Zapardiel de la Ca&#241;ada, al considerar que una prospecci&#243;n minera en esta zona afectar&#237;a gravemente a la actividad ganadera que se desarrolla en esta comarca.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera","og_locale":"es_ES","og_type":"article","og_title":"ASAJA de &#193;vila interpone recurso de alzada contra la prospecci&#243;n minera del Valle del Corneja por su afecci&#243;n a la actividad ganadera - ASAJA \u00c1vila","og_description":"La Asociaci&#243;n Agraria J&#243;venes Agricultores (ASAJA) de &#193;vila ha interpuesto hoy un recurso de alzada contra el otorgamiento del permiso de investigaci&#243;n denominado &#8216;Sonsoles&#8217; para la explotaci&#243;n de feldespatos en los municipios de T&#243;rtoles, Bonilla de la Sierra, Becedillas y Zapardiel de la Ca&#241;ada, al considerar que una prospecci&#243;n minera en esta zona afectar&#237;a gravemente a la actividad ganadera que se desarrolla en esta comarca.","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera","og_site_name":"ASAJA \u00c1vila","article_published_time":"2017-03-27T22:00:00+00:00","og_image":[{"width":500,"height":375,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/bonilladelasierra.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera","name":"ASAJA de &#193;vila interpone recurso de alzada contra la prospecci&#243;n minera del Valle del Corneja por su afecci&#243;n a la actividad ganadera - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/bonilladelasierra.jpg","datePublished":"2017-03-27T22:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"La Asociaci&#243;n Agraria J&#243;venes Agricultores (ASAJA) de &#193;vila ha interpuesto hoy un recurso de alzada contra el otorgamiento del permiso de investigaci&#243;n denominado &#8216;Sonsoles&#8217; para la explotaci&#243;n de feldespatos en los municipios de T&#243;rtoles, Bonilla de la Sierra, Becedillas y Zapardiel de la Ca&#241;ada, al considerar que una prospecci&#243;n minera en esta zona afectar&#237;a gravemente a la actividad ganadera que se desarrolla en esta comarca.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/bonilladelasierra.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/12\/bonilladelasierra.jpg","width":500,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/asaja-de-vila-interpone-recurso-de-alzada-contra-la-prospeccin-minera-del-valle-del-corneja-por-su-afeccin-a-la-actividad-ganadera#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"ASAJA de &#193;vila interpone recurso de alzada contra la prospecci&#243;n minera del Valle del Corneja por su afecci&#243;n a la actividad ganadera"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/927"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=927"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/928"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}