{"id":960,"date":"2017-02-24T00:00:00","date_gmt":"2017-02-23T23:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/avila\/sin-categoria\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho"},"modified":"2017-02-24T00:00:00","modified_gmt":"2017-02-23T23:00:00","slug":"la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho","title":{"rendered":"La Junta de Castilla y Le&#243;n construir&#225; una red de caminos en Solosancho"},"content":{"rendered":"<h2>El Consejo de Gobierno de Castilla y Le&#243;n ha aprobado la construcci&#243;n de una red de caminos en la zona de concentraci&#243;n parcelaria de Solosancho.<\/h2>\n<p>\nEl Consejo de Gobierno de Castilla y Le&#243;n ha aprobado la construcci&#243;n de una red de caminos en la zona de concentraci&#243;n parcelaria de Solosancho.<\/p>\n<p>\nAs&#237;, se construir&#225; una red de caminos de 12 kil&#243;metros de las concentraciones parcelarias de Solosancho-Villaviciosa y Robledillo-Baterna con las v&#237;as de comunicaci&#243;n principales. Adem&#225;s, se va a llevar a cabo la regeneraci&#243;n de taludes, la plantaci&#243;n de 250 encinas para recuperar la cubierta vegetal y el vallado en las fincas de restauraci&#243;n. A estas infraestructuras rurales se van a destinar 321.117 euros.<\/p>\n<p>\nEn el municipio de Solosancho se est&#225;n desarrollando las concentraciones parcelarias en las zonas de Solosancho-Villaviciosa y Robledillo-Baterna. En la primera de ellas la superficie concentrada comprende 1.562 hect&#225;reas que pertenecen a 563 propietarios. En la zona de concentraci&#243;n parcelaria de Robledillo-Baterna, los propietarios son 634 y la superficie es de 1.208 hect&#225;reas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo de Gobierno de Castilla y Le&#243;n ha aprobado la construcci&#243;n de una red de caminos en la zona de concentraci&#243;n parcelaria de Solosancho.<\/p>\n","protected":false},"author":3,"featured_media":794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Junta de Castilla y Le&#243;n construir&#225; una red de caminos en Solosancho - ASAJA \u00c1vila<\/title>\n<meta name=\"description\" content=\"El Consejo de Gobierno de Castilla y Le&#243;n ha aprobado la construcci&#243;n de una red de caminos en la zona de concentraci&#243;n parcelaria de Solosancho.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Junta de Castilla y Le&#243;n construir&#225; una red de caminos en Solosancho - ASAJA \u00c1vila\" \/>\n<meta property=\"og:description\" content=\"El Consejo de Gobierno de Castilla y Le&#243;n ha aprobado la construcci&#243;n de una red de caminos en la zona de concentraci&#243;n parcelaria de Solosancho.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA \u00c1vila\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-23T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho\",\"name\":\"La Junta de Castilla y Le&#243;n construir&#225; una red de caminos en Solosancho - ASAJA \u00c1vila\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2017-02-23T23:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"El Consejo de Gobierno de Castilla y Le&#243;n ha aprobado la construcci&#243;n de una red de caminos en la zona de concentraci&#243;n parcelaria de Solosancho.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA \u00c1vila\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/avila\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Junta de Castilla y Le&#243;n construir&#225; una red de caminos en Solosancho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/avila\/\",\"name\":\"ASAJA \u00c1vila\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/avila\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Junta de Castilla y Le&#243;n construir&#225; una red de caminos en Solosancho - ASAJA \u00c1vila","description":"El Consejo de Gobierno de Castilla y Le&#243;n ha aprobado la construcci&#243;n de una red de caminos en la zona de concentraci&#243;n parcelaria de Solosancho.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho","og_locale":"es_ES","og_type":"article","og_title":"La Junta de Castilla y Le&#243;n construir&#225; una red de caminos en Solosancho - ASAJA \u00c1vila","og_description":"El Consejo de Gobierno de Castilla y Le&#243;n ha aprobado la construcci&#243;n de una red de caminos en la zona de concentraci&#243;n parcelaria de Solosancho.","og_url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho","og_site_name":"ASAJA \u00c1vila","article_published_time":"2017-02-23T23:00:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho","url":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho","name":"La Junta de Castilla y Le&#243;n construir&#225; una red de caminos en Solosancho - ASAJA \u00c1vila","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/avila\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2017-02-23T23:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"El Consejo de Gobierno de Castilla y Le&#243;n ha aprobado la construcci&#243;n de una red de caminos en la zona de concentraci&#243;n parcelaria de Solosancho.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho#primaryimage","url":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/avila\/wp-content\/uploads\/sites\/4\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA \u00c1vila"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/avila\/asaja-avila-informa\/la-junta-de-castilla-y-len-construir-una-red-de-caminos-en-solosancho#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/avila\/"},{"@type":"ListItem","position":2,"name":"La Junta de Castilla y Le&#243;n construir&#225; una red de caminos en Solosancho"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/avila\/#website","url":"https:\/\/www.asajacyl.com\/avila\/","name":"ASAJA \u00c1vila","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/avila\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/avila\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/avila\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/960"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/comments?post=960"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/posts\/960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media\/794"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/media?parent=960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/categories?post=960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/avila\/wp-json\/wp\/v2\/tags?post=960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}