{"id":15825,"date":"2024-11-25T12:12:17","date_gmt":"2024-11-25T11:12:17","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg"},"modified":"2024-11-25T12:12:17","modified_gmt":"2024-11-25T11:12:17","slug":"harinera-villafranquina","status":"inherit","type":"attachment","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/manifestacion-en-arevalo-el-viernes-29\/attachment\/harinera-villafranquina","title":{"rendered":"Harinera Villafranquina"},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Harinera Villafranquina - ASAJA Le\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Harinera Villafranquina - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg\",\"name\":\"Harinera Villafranquina - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"datePublished\":\"2024-11-25T11:12:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manifestaci\u00f3n en Ar\u00e9valo el viernes 29\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/manifestacion-en-arevalo-el-viernes-29\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Harinera Villafranquina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Harinera Villafranquina - ASAJA Le\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg","og_locale":"es_ES","og_type":"article","og_title":"Harinera Villafranquina - ASAJA Le\u00f3n","og_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg","og_site_name":"ASAJA Le\u00f3n","og_image":[{"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg","name":"Harinera Villafranquina - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"datePublished":"2024-11-25T11:12:17+00:00","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Manifestaci\u00f3n en Ar\u00e9valo el viernes 29","item":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/manifestacion-en-arevalo-el-viernes-29"},{"@type":"ListItem","position":3,"name":"Harinera Villafranquina"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-300x169.jpg 300w, https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-1024x576.jpg 1024w, https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-768x432.jpg 768w, https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-747x420.jpg 747w, https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-696x392.jpg 696w, https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-1068x601.jpg 1068w, https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":675,"file":"2024\/11\/Harinera-Villafranquina.jpg","filesize":86543,"sizes":{"medium":{"file":"Harinera-Villafranquina-300x169.jpg","width":300,"height":169,"filesize":11302,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-300x169.jpg"},"large":{"file":"Harinera-Villafranquina-1024x576.jpg","width":1024,"height":576,"filesize":80174,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-1024x576.jpg"},"thumbnail":{"file":"Harinera-Villafranquina-150x150.jpg","width":150,"height":150,"filesize":5672,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-150x150.jpg"},"medium_large":{"file":"Harinera-Villafranquina-768x432.jpg","width":768,"height":432,"filesize":50535,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-768x432.jpg"},"mx8-opinion":{"file":"Harinera-Villafranquina-696x518.jpg","width":696,"height":518,"filesize":52852,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-696x518.jpg"},"mx8-publicacion":{"file":"Harinera-Villafranquina-324x437.jpg","width":324,"height":437,"filesize":24255,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-324x437.jpg"},"td_0x420":{"file":"Harinera-Villafranquina-747x420.jpg","width":747,"height":420,"filesize":48971,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-747x420.jpg"},"td_80x60":{"file":"Harinera-Villafranquina-80x60.jpg","width":80,"height":60,"filesize":1710,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-80x60.jpg"},"td_218x150":{"file":"Harinera-Villafranquina-218x150.jpg","width":218,"height":150,"filesize":7901,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-218x150.jpg"},"td_485x360":{"file":"Harinera-Villafranquina-485x360.jpg","width":485,"height":360,"filesize":29547,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-485x360.jpg"},"td_696x0":{"file":"Harinera-Villafranquina-696x392.jpg","width":696,"height":392,"filesize":43114,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-696x392.jpg"},"td_1068x0":{"file":"Harinera-Villafranquina-1068x601.jpg","width":1068,"height":601,"filesize":86825,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-1068x601.jpg"},"td_324x160":{"file":"Harinera-Villafranquina-324x160.jpg","width":324,"height":160,"filesize":10505,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-324x160.jpg"},"td_324x235":{"file":"Harinera-Villafranquina-324x235.jpg","width":324,"height":235,"filesize":15400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-324x235.jpg"},"td_356x220":{"file":"Harinera-Villafranquina-356x220.jpg","width":356,"height":220,"filesize":15815,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-356x220.jpg"},"td_356x364":{"file":"Harinera-Villafranquina-356x364.jpg","width":356,"height":364,"filesize":22753,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-356x364.jpg"},"td_534x462":{"file":"Harinera-Villafranquina-534x462.jpg","width":534,"height":462,"filesize":38447,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-534x462.jpg"},"td_696x385":{"file":"Harinera-Villafranquina-696x385.jpg","width":696,"height":385,"filesize":42445,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-696x385.jpg"},"td_741x486":{"file":"Harinera-Villafranquina-741x486.jpg","width":741,"height":486,"filesize":53506,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-741x486.jpg"},"td_1068x580":{"file":"Harinera-Villafranquina-1068x580.jpg","width":1068,"height":580,"filesize":82150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-1068x580.jpg"},"cmplz_banner_image":{"file":"Harinera-Villafranquina-350x100.jpg","width":350,"height":100,"filesize":6997,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina-350x100.jpg"},"full":{"file":"Harinera-Villafranquina.jpg","width":1200,"height":675,"mime_type":"image\/jpeg","source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":15824,"source_url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Harinera-Villafranquina.jpg","_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/15825"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=15825"}]}}