{"id":10193,"date":"2019-06-07T09:00:20","date_gmt":"2019-06-07T07:00:20","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=10193"},"modified":"2019-06-22T11:20:38","modified_gmt":"2019-06-22T09:20:38","slug":"las-seis-noticias-agrarias-de-la-semana-07-06-2019","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 07\/06\/2019"},"content":{"rendered":"<h2><strong>Repsol, Campsa y Petronor, plaga de conejos, cultivo de ma\u00edz, s\u00f3lo el 41 por ciento de la superficie de cultivo est\u00e1 asegurada\u00a0 frente a da\u00f1os integrales, venta de tractores nuevos, reuni\u00f3n de la Junta Directiva y el Consejo Asesor de ASAJA de Le\u00f3n<\/strong><\/h2>\n<ol>\n<li style=\"list-style-type: none\">\n<ol>\n<li>\n<h6>Fruto de un convenio entre ASAJA y REPSOL, los socios de la organizaci\u00f3n pueden beneficiarse de ventajas econ\u00f3micas al repostar los distintos tipos de carburante en las gasolineras del grupo, es decir, en <strong>REPSOL, CAMPSA y PETRONOR<\/strong>. Mediante una tarjeta de pago o descuento, que es gratuita, el cliente recibe un descuento entre 8 y 10 c\u00e9ntimos por cada litro consumido. Adem\u00e1s, a final de mes se recibe una factura que globaliza la totalidad de los repostajes, con efectos fiscales si es el caso. Las tarjetas se pueden solicitar en cualquiera de las oficinas de la organizaci\u00f3n.<\/h6>\n<\/li>\n<li>\n<h6>Los responsables comarcales y provinciales de la organizaci\u00f3n agraria ASAJA visitaron la pasada semana varias vi\u00f1as en el Bierzo con importante da\u00f1os provocados por la<strong> plaga de conejos<\/strong>. Son muchas las cepas que han perdido la producci\u00f3n y abundan las que se han secado debido a la continua presi\u00f3n que ejerce sobre la planta esta plaga de conejos de monte. ASAJA exige a los cotos de caza que reduzcan la poblaci\u00f3n con batidas organizadas y pide labores de limpieza en fincas abandonadas donde los roedores se refugian.\u00a0 La administraci\u00f3n deber\u00eda de imponer un adecuado mantenimiento en las fincas que se encuentran en estado de abandono.<\/h6>\n<\/li>\n<li>\n<h6>La provincia de Le\u00f3n tiene este a\u00f1o 72.000 hect\u00e1reas de <strong>cultivo de ma\u00edz<\/strong> incluyendo el ma\u00edz grano y el ma\u00edz forraje para ensilado, lo que supone un record de superficie a lo largo de la historia de este cultivo. Debido a que aproximadamente la mitad se cultiva en regad\u00edos modernizados, frente a la otra mitad que se riega por inundaci\u00f3n, son previsibles producciones medias que podr\u00eda llegar a 13.000 kilos por hect\u00e1rea, superando por vez primera los 900 millones de kilos de grano.<\/h6>\n<\/li>\n<li>\n<h6>\u00a0En la provincia de Le\u00f3n\u00a0 tan <strong>s\u00f3lo el 41 por ciento de la superficie de cultivo est\u00e1 asegurada\u00a0 frente a da\u00f1os integrales<\/strong>, y en concreto contra el da\u00f1o por sequ\u00eda, aunque es cierto que el grado de aseguramiento es mayor entre el colectivo de profesionales que viven exclusivamente del campo. La provincia de Le\u00f3n tiene declarada una superficie de 97.700 hect\u00e1reas de distintos cultivos herb\u00e1ceos en secano, destacando el cereal de invierno con 71.000 hect\u00e1reas, el girasol con 8.600 hect\u00e1reas, 4.900 hect\u00e1reas de alfalfa, 700 hect\u00e1reas de proteaginosas,\u00a0 800 hect\u00e1reas de legumbres, 1.400 de colza y 10.300 de vezas.<\/h6>\n<\/li>\n<li>\n<h6>El mes de abril fue un buen mes para la <strong>venta de tractores nuevos<\/strong> en la provincia de Le\u00f3n, matricul\u00e1ndose 20 unidades de un total de 110 en toda Castilla y Le\u00f3n. Marzo tambi\u00e9n fue buen mes con 18 unidades vendidas, pero no as\u00ed febrero con solo 4 y enero con 10 tractores matriculados. Es previsible que esta buena tendencia se rompa en los pr\u00f3ximos\u00a0 meses debido a la descapitalizaci\u00f3n que se va a producir en las explotaciones de amplias zonas del secano leon\u00e9s que est\u00e1 siendo azotado por la sequ\u00eda.<\/h6>\n<\/li>\n<li>\n<h6><strong>E<\/strong>l viernes 31 de mayo <strong>se reuni\u00f3 la Junta Directiva y el Consejo Asesor de ASAJA de Le\u00f3n<\/strong> para abordar el funcionamiento de la organizaci\u00f3n y analizar la situaci\u00f3n de la pol\u00edtica agraria. La organizaci\u00f3n valor\u00f3 el \u00e9xito que est\u00e1 teniendo en servicios a los socios propios de estas fechas del a\u00f1o, como son el asesoramiento fiscal, la suscripci\u00f3n del seguro agrario, la gesti\u00f3n de las ayudas de la PAC, o los tr\u00e1mites para la incorporaci\u00f3n de j\u00f3venes al sector. ASAJA valor\u00f3 el momento pol\u00edtico tras las elecciones y abog\u00f3 por acuerdos que permitan la formaci\u00f3n de gobiernos estables en el menor tiempo posible.<\/h6>\n<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Repsol, Campsa y Petronor, plaga de conejos, cultivo de ma\u00edz, s\u00f3lo el 41 por ciento de la superficie de cultivo est\u00e1 asegurada\u00a0 frente a da\u00f1os integrales, venta de tractores nuevos, reuni\u00f3n de la Junta Directiva y el Consejo Asesor de ASAJA de Le\u00f3n Fruto de un convenio entre ASAJA y REPSOL, los socios de la [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":8673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 07\/06\/2019 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Repsol, Campsa y Petronor, plaga de conejos, cultivo de ma\u00edz, s\u00f3lo el 41 por ciento de la superficie de cultivo est\u00e1 asegurada\u00a0 frente a da\u00f1os integrales,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 07\/06\/2019 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Repsol, Campsa y Petronor, plaga de conejos, cultivo de ma\u00edz, s\u00f3lo el 41 por ciento de la superficie de cultivo est\u00e1 asegurada\u00a0 frente a da\u00f1os integrales,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-07T07:00:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-22T09:20:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/plaga-conejos-bierzo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019\",\"name\":\"Las seis noticias agrarias de la semana - 07\/06\/2019 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/plaga-conejos-bierzo-1.jpg\",\"datePublished\":\"2019-06-07T07:00:20+00:00\",\"dateModified\":\"2019-06-22T09:20:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Repsol, Campsa y Petronor, plaga de conejos, cultivo de ma\u00edz, s\u00f3lo el 41 por ciento de la superficie de cultivo est\u00e1 asegurada\u00a0 frente a da\u00f1os integrales,\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/plaga-conejos-bierzo-1.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/plaga-conejos-bierzo-1.jpg\",\"width\":1024,\"height\":684},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 07\/06\/2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 07\/06\/2019 - ASAJA Le\u00f3n","description":"Repsol, Campsa y Petronor, plaga de conejos, cultivo de ma\u00edz, s\u00f3lo el 41 por ciento de la superficie de cultivo est\u00e1 asegurada\u00a0 frente a da\u00f1os integrales,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 07\/06\/2019 - ASAJA Le\u00f3n","og_description":"Repsol, Campsa y Petronor, plaga de conejos, cultivo de ma\u00edz, s\u00f3lo el 41 por ciento de la superficie de cultivo est\u00e1 asegurada\u00a0 frente a da\u00f1os integrales,","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2019-06-07T07:00:20+00:00","article_modified_time":"2019-06-22T09:20:38+00:00","og_image":[{"width":1024,"height":684,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/plaga-conejos-bierzo-1.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019","name":"Las seis noticias agrarias de la semana - 07\/06\/2019 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/plaga-conejos-bierzo-1.jpg","datePublished":"2019-06-07T07:00:20+00:00","dateModified":"2019-06-22T09:20:38+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Repsol, Campsa y Petronor, plaga de conejos, cultivo de ma\u00edz, s\u00f3lo el 41 por ciento de la superficie de cultivo est\u00e1 asegurada\u00a0 frente a da\u00f1os integrales,","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/plaga-conejos-bierzo-1.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/plaga-conejos-bierzo-1.jpg","width":1024,"height":684},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-07-06-2019#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 07\/06\/2019"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10193"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=10193"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10193\/revisions"}],"predecessor-version":[{"id":10194,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10193\/revisions\/10194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8673"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=10193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=10193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=10193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}