{"id":10374,"date":"2019-08-18T18:10:33","date_gmt":"2019-08-18T16:10:33","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=10374"},"modified":"2019-08-18T18:10:33","modified_gmt":"2019-08-18T16:10:33","slug":"parroquias-pobres","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres","title":{"rendered":"Parroquias pobres"},"content":{"rendered":"<h6>Informaba el pasado domingo este peri\u00f3dico de una campa\u00f1a de la Di\u00f3cesis de Le\u00f3n que tiene como finalidad recaudar fondos de las parroquias m\u00e1s pudientes, entiendo que la mayor\u00eda en la capital o cabeceras de comarca, para ayudar al sostenimiento de otras de peque\u00f1as localidades que tienen pocos posibles. Buena me parece la medida, y bien me parece que se ponga el foco en unas parroquias que necesitan seguir prestando los servicios b\u00e1sicos, o al menos los m\u00e1s imprescindibles, y que necesitan fondos para afrontar sus gastos corrientes y las inversiones a veces urgentes para conservar unos bienes patrimoniales que son tambi\u00e9n riqueza art\u00edstica y cultural. La Diputaci\u00f3n de Le\u00f3n, los ayuntamientos, las juntas vecinales, y la solidaridad de los vecinos de los pueblos, han costeado multitud de obras en el patrimonio religioso de nuestra provincia, por lo que podemos decir que est\u00e1 m\u00e1s cuidado que nunca, y se han rescatado obras de arte abandonadas o desconocidas. Tenemos iglesias m\u00e1s bonitas, mejor cuidadas, pero algunas ya no se abren casi nunca, salvo para oficiar un funeral, que ahora es el acto religioso que m\u00e1s abunda en los pueblos. Cuando se cierra la iglesia, cuando se jubila con setenta y cinco a\u00f1os el cura y el obispado no puede sustituirlo porque no hay vocaciones, comienza el declive, comienza la cuenta atr\u00e1s del abandono rural como cuando cierra la escuela, desatienden el consultorio m\u00e9dico, deja de parar el tren, o desaparece la cantina. Algo deber\u00eda de estar pensando la Iglesia Cat\u00f3lica, al menos al nivel de Conferencia Episcopal, para atender las necesidades religiosas de la \u201cEspa\u00f1a vaciada\u201d de pueblos y parroquias casi diminutas como las que hay en la provincia de Le\u00f3n. Y tanto las di\u00f3cesis, en nuestro caso la de Le\u00f3n y la de Astorga, como las instituciones, deber\u00edan de idear un plan para el sostenimiento y la puesta en valor de un patrimonio que trasciende a la religi\u00f3n, y que es de todos, tambi\u00e9n de los no creyentes. Y si el se\u00f1or Obispo me lo permite, le dir\u00e9 que no nos quite de los pueblos peque\u00f1os a los mejores curas, que a veces le tienta.<\/h6>\n<h6>*Art\u00edculo de opini\u00f3n de Jos\u00e9 Antonio Turrado publicado en La Nueva Cr\u00f3nica del viernes 16 de agosto de 2019<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Informaba el pasado domingo este peri\u00f3dico de una campa\u00f1a de la Di\u00f3cesis de Le\u00f3n que tiene como finalidad recaudar fondos de las parroquias m\u00e1s pudientes, entiendo que la mayor\u00eda en la capital o cabeceras de comarca, para ayudar al sostenimiento de otras de peque\u00f1as localidades que tienen pocos posibles. Buena me parece la medida, y [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":9981,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Parroquias pobres - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Informaba el pasado domingo este peri\u00f3dico de una campa\u00f1a de la Di\u00f3cesis de Le\u00f3n que tiene como finalidad recaudar fondos de las parroquias m\u00e1s pudientes,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parroquias pobres - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Informaba el pasado domingo este peri\u00f3dico de una campa\u00f1a de la Di\u00f3cesis de Le\u00f3n que tiene como finalidad recaudar fondos de las parroquias m\u00e1s pudientes,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-18T16:10:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/03\/iglesia_Matade\u00f3n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres\",\"name\":\"Parroquias pobres - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/03\/iglesia_Matade\u00f3n.jpg\",\"datePublished\":\"2019-08-18T16:10:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Informaba el pasado domingo este peri\u00f3dico de una campa\u00f1a de la Di\u00f3cesis de Le\u00f3n que tiene como finalidad recaudar fondos de las parroquias m\u00e1s pudientes,\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/03\/iglesia_Matade\u00f3n.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/03\/iglesia_Matade\u00f3n.jpg\",\"width\":800,\"height\":540,\"caption\":\"Iglesia de Matade\u00f3n de los Oteros\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parroquias pobres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parroquias pobres - ASAJA Le\u00f3n","description":"Informaba el pasado domingo este peri\u00f3dico de una campa\u00f1a de la Di\u00f3cesis de Le\u00f3n que tiene como finalidad recaudar fondos de las parroquias m\u00e1s pudientes,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres","og_locale":"es_ES","og_type":"article","og_title":"Parroquias pobres - ASAJA Le\u00f3n","og_description":"Informaba el pasado domingo este peri\u00f3dico de una campa\u00f1a de la Di\u00f3cesis de Le\u00f3n que tiene como finalidad recaudar fondos de las parroquias m\u00e1s pudientes,","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2019-08-18T16:10:33+00:00","og_image":[{"width":800,"height":540,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/03\/iglesia_Matade\u00f3n.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres","name":"Parroquias pobres - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/03\/iglesia_Matade\u00f3n.jpg","datePublished":"2019-08-18T16:10:33+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Informaba el pasado domingo este peri\u00f3dico de una campa\u00f1a de la Di\u00f3cesis de Le\u00f3n que tiene como finalidad recaudar fondos de las parroquias m\u00e1s pudientes,","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/03\/iglesia_Matade\u00f3n.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/03\/iglesia_Matade\u00f3n.jpg","width":800,"height":540,"caption":"Iglesia de Matade\u00f3n de los Oteros"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/parroquias-pobres#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Parroquias pobres"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10374"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=10374"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10374\/revisions"}],"predecessor-version":[{"id":10375,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10374\/revisions\/10375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/9981"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=10374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=10374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=10374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}