{"id":10464,"date":"2019-09-25T14:26:45","date_gmt":"2019-09-25T12:26:45","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=10464"},"modified":"2019-10-01T12:01:00","modified_gmt":"2019-10-01T10:01:00","slug":"asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste","title":{"rendered":"Asaja critica el empeoramiento de las condiciones del seguro agrario: menor cobertura y mayor coste"},"content":{"rendered":"<h6>Cuando los riesgos clim\u00e1ticos hacen m\u00e1s necesario que nunca que se universalice el seguro en la agricultura y la ganader\u00eda, parece que Agroseguro est\u00e1 trabajando justo en direcci\u00f3n contraria. Seg\u00fan constata ASAJA, las condiciones del seguro de sequ\u00eda y pedrisco, el m\u00e1s suscrito por los agricultores, es esta campa\u00f1a m\u00e1s caro y encima ofrece menor cobertura de rendimientos. En resumen, tal como se\u00f1ala Donaciano Dujo, presidente de ASAJA de Castilla y Le\u00f3n, \u201caseguramos menos y pagamos m\u00e1s\u201d. Una tendencia que ya se not\u00f3 en 2018, cuando se asegur\u00f3 solo un 62 por ciento del cereal, mientras que en 2017 hab\u00eda sido el 80 por ciento, y que este 2019 todo indica que se agudizar\u00e1, reduci\u00e9ndose a\u00fan m\u00e1s superficie, por las condiciones que ofrece Agroseguro para la pr\u00f3xima campa\u00f1a.<\/h6>\n<h6>Para ASAJA, hay dos motivos detr\u00e1s de este empeoramiento del seguro agrario. Primera y fundamental: la falta de compromiso del Ministerio de Agricultura, que pasa por alto sus competencias -a trav\u00e9s de ENESA, la Entidad Nacional Espa\u00f1ola de Seguros Agrarios- para financiar y apostar por un seguro que de verdad cubra las necesidades del campo. La segunda, la repercusi\u00f3n que para su financiaci\u00f3n est\u00e1n teniendo la inestabilidad clim\u00e1tica de las \u00faltimas campa\u00f1as, especialmente la de la sequ\u00eda de 2017. \u201cAs\u00ed pues, Agroseguro ha decidido cortar por lo sano, mirando solo por su cuenta de resultados, con la permisividad del Gobierno, que ni habilita una partida mayor para apoyar los seguros ni pone freno a las propuestas irracionales de Agroseguro\u201d denuncia ASAJA.<\/h6>\n<h6>Las opciones que ofrece Agroseguro en la contrataci\u00f3n de seguro agrario para la campa\u00f1a agr\u00edcola a punto de comenzar confirman su determinaci\u00f3n de rebajar la cosecha asegurable y de incrementar el precio de la p\u00f3liza. Tras analizar la repercusi\u00f3n de sus propuestas en una muestra significativa de agricultores profesionales de Castilla y Le\u00f3n socios de ASAJA, se constata que cerca de la mitad experimentar\u00e1 un descenso importante en los rendimientos asegurables. Respecto al precio, Agroseguro apunta que subir\u00e1n en torno a un 2,67 por ciento, pero los c\u00e1lculos de ASAJA se\u00f1alan que, para la opci\u00f3n m\u00e1s contratada en Castilla y Le\u00f3n, la del seguro que garantiza el 70 por ciento de la producci\u00f3n, la subida aplicada ser\u00e1 de un 8,5 por ciento, llegando al 22 por ciento en el nivel m\u00e1s bajo de aseguramiento, el 50%. Adem\u00e1s, la aseguradora elimina la posibilidad de asegurar el 80 por ciento del rendimiento, que hasta el a\u00f1o pasado se ofrec\u00eda.<\/h6>\n<h6><strong>En el caso de la provincia de Le\u00f3n, con los datos que maneja ASAJA, la subida en el importe de las p\u00f3lizas es de un promedio del 10,1%, y la bajada de los rendimientos asegurables de un promedio del 5,4%, para las p\u00f3lizas de seguro m\u00e1s habituales. Esto afecta sobre todo a las explotaciones de secano que la provincia, mayoritariamente en las comarcas de Sahag\u00fan y de Esla-Campos. <\/strong><\/h6>\n<h6>Todos estos cambios tendr\u00e1n una repercusi\u00f3n muy negativa en la contrataci\u00f3n, advierte ASAJA. \u201cCuando lo deseable es que se ampl\u00ede la superficie cubierta, acerc\u00e1ndonos lo m\u00e1s posible al seguro universal, la administraci\u00f3n pone palos en las ruedas que lograr\u00e1n el efecto contrario\u201d, lamenta la OPA, que insta a la Consejer\u00eda de Agricultura y Ganader\u00eda a que busque la complicidad de las comunidades aut\u00f3nomas para presionar a un ministerio que lleva meses instalado en la provisionalidad, sin pensar en las consecuencias que tiene su inacci\u00f3n y dejar morir por falta de apoyo una pol\u00edtica vital para el campo, el seguro agrario\u201d.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Cuando los riesgos clim\u00e1ticos hacen m\u00e1s necesario que nunca que se universalice el seguro en la agricultura y la ganader\u00eda, parece que Agroseguro est\u00e1 trabajando justo en direcci\u00f3n contraria. Seg\u00fan constata ASAJA, las condiciones del seguro de sequ\u00eda y pedrisco, el m\u00e1s suscrito por los agricultores, es esta campa\u00f1a m\u00e1s caro y encima ofrece menor [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":6548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Asaja critica el empeoramiento de las condiciones del seguro agrario: menor cobertura y mayor coste - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Cuando los riesgos clim\u00e1ticos hacen m\u00e1s necesario que nunca que se universalice el seguro en la agricultura y la ganader\u00eda, parece que Agroseguro est\u00e1\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asaja critica el empeoramiento de las condiciones del seguro agrario: menor cobertura y mayor coste - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Cuando los riesgos clim\u00e1ticos hacen m\u00e1s necesario que nunca que se universalice el seguro en la agricultura y la ganader\u00eda, parece que Agroseguro est\u00e1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-25T12:26:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-01T10:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/finca_centeno_siniestro_total_granizo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"482\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste\",\"name\":\"Asaja critica el empeoramiento de las condiciones del seguro agrario: menor cobertura y mayor coste - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/finca_centeno_siniestro_total_granizo.jpg\",\"datePublished\":\"2019-09-25T12:26:45+00:00\",\"dateModified\":\"2019-10-01T10:01:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Cuando los riesgos clim\u00e1ticos hacen m\u00e1s necesario que nunca que se universalice el seguro en la agricultura y la ganader\u00eda, parece que Agroseguro est\u00e1\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/finca_centeno_siniestro_total_granizo.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/finca_centeno_siniestro_total_granizo.jpg\",\"width\":640,\"height\":482},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asaja critica el empeoramiento de las condiciones del seguro agrario: menor cobertura y mayor coste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asaja critica el empeoramiento de las condiciones del seguro agrario: menor cobertura y mayor coste - ASAJA Le\u00f3n","description":"Cuando los riesgos clim\u00e1ticos hacen m\u00e1s necesario que nunca que se universalice el seguro en la agricultura y la ganader\u00eda, parece que Agroseguro est\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste","og_locale":"es_ES","og_type":"article","og_title":"Asaja critica el empeoramiento de las condiciones del seguro agrario: menor cobertura y mayor coste - ASAJA Le\u00f3n","og_description":"Cuando los riesgos clim\u00e1ticos hacen m\u00e1s necesario que nunca que se universalice el seguro en la agricultura y la ganader\u00eda, parece que Agroseguro est\u00e1","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2019-09-25T12:26:45+00:00","article_modified_time":"2019-10-01T10:01:00+00:00","og_image":[{"width":640,"height":482,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/finca_centeno_siniestro_total_granizo.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste","name":"Asaja critica el empeoramiento de las condiciones del seguro agrario: menor cobertura y mayor coste - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/finca_centeno_siniestro_total_granizo.jpg","datePublished":"2019-09-25T12:26:45+00:00","dateModified":"2019-10-01T10:01:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Cuando los riesgos clim\u00e1ticos hacen m\u00e1s necesario que nunca que se universalice el seguro en la agricultura y la ganader\u00eda, parece que Agroseguro est\u00e1","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/finca_centeno_siniestro_total_granizo.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/finca_centeno_siniestro_total_granizo.jpg","width":640,"height":482},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-critica-el-empeoramiento-de-las-condiciones-del-seguro-agrario-menor-cobertura-y-mayor-coste#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Asaja critica el empeoramiento de las condiciones del seguro agrario: menor cobertura y mayor coste"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10464"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=10464"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10464\/revisions"}],"predecessor-version":[{"id":10465,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10464\/revisions\/10465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/6548"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=10464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=10464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=10464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}