{"id":10634,"date":"2019-11-07T09:17:27","date_gmt":"2019-11-07T08:17:27","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=10634"},"modified":"2019-11-15T15:11:23","modified_gmt":"2019-11-15T14:11:23","slug":"la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano","title":{"rendered":"La Junta licitar\u00e1 el Sector XVII de Payuelos en el primer trimestre del a\u00f1o"},"content":{"rendered":"<h6>El consejero de Agricultura y Ganader\u00eda de la Junta de Castilla y Le\u00f3n, Jes\u00fas Julio Carnero, se comprometi\u00f3 en una visita a la localidad de Castrovega de Valmadrigal, el mi\u00e9rcoles 6 de noviembre, a licitar las obras de regad\u00edos del Sector XVII de Payuelos en el primer trimestre del pr\u00f3ximo a\u00f1o 2020. Este sector ocupa una superficie de cultivo de 4.266 hect\u00e1reas, de las cuales 2.650 se transformar\u00e1n en regad\u00edo. El Sector XVII ocupa terrenos del municipio de Valverde Enrique y parte de otros municipios lim\u00edtrofes en este territorio del sureste leon\u00e9s.<\/h6>\n<h6>El consejero de Agricultura y Ganader\u00eda, que acudi\u00f3 a la visita acompa\u00f1ado por personal de su equipo y por el Delegado de la Junta en la provincia, se comprometi\u00f3 tambi\u00e9n a finalizar a lo largo de la actual legislatura el ambicioso proyecto de reconcentraci\u00f3n parcelaria en los Oteros, que mejorar\u00e1 las condiciones agron\u00f3micas en esta zona que ocupa el secano m\u00e1s productivo de la provincia. Por otra parte, se manifest\u00f3 tambi\u00e9n el compromiso de la Consejer\u00eda de poner al d\u00eda la entrega de los t\u00edtulos de propiedad de las nuevas parcelas entregadas en los distintos procesos de concentraci\u00f3n parcelaria que se han llevado a cabo en la provincia en los \u00faltimos 20 a\u00f1os.<\/h6>\n<h6>El Consejero, que estuvo acompa\u00f1ado por el Alcalde y miembros de la corporaci\u00f3n municipal de Valverde Enrique, as\u00ed como por los responsables de ASAJA Arsenio Garc\u00eda Vidal, Donaciano Dujo y Jos\u00e9 Antonio Turrado, dedic\u00f3 parte de su intervenci\u00f3n a defender la PAC y a pedir que en la nueva reforma se mantenga al menos el actual presupuesto<strong>. <\/strong>Hizo una defensa de la Uni\u00f3n Europea, de donde vienen la mayor\u00eda de los fondos para el campo, y pidi\u00f3 un Gobierno fuerte para afrontar las negociaciones que se libran en Bruselas.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El consejero de Agricultura y Ganader\u00eda de la Junta de Castilla y Le\u00f3n, Jes\u00fas Julio Carnero, se comprometi\u00f3 en una visita a la localidad de Castrovega de Valmadrigal, el mi\u00e9rcoles 6 de noviembre, a licitar las obras de regad\u00edos del Sector XVII de Payuelos en el primer trimestre del pr\u00f3ximo a\u00f1o 2020. Este sector ocupa [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":10636,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Junta licitar\u00e1 el Sector XVII de Payuelos en el primer trimestre del a\u00f1o - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"El consejero de Agricultura y Ganader\u00eda de la Junta de Castilla y Le\u00f3n, Jes\u00fas Julio Carnero, se comprometi\u00f3 en una visita a la localidad de Castrovega de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Junta licitar\u00e1 el Sector XVII de Payuelos en el primer trimestre del a\u00f1o - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El consejero de Agricultura y Ganader\u00eda de la Junta de Castilla y Le\u00f3n, Jes\u00fas Julio Carnero, se comprometi\u00f3 en una visita a la localidad de Castrovega de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-07T08:17:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-15T14:11:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/11\/ACTO-CON-EL-CONSEJERO-DE-AGRICULTURA-EN-CASTROVEGA-DE-VALMADRIGAL-06-11-2019-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1134\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano\",\"name\":\"La Junta licitar\u00e1 el Sector XVII de Payuelos en el primer trimestre del a\u00f1o - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/11\/ACTO-CON-EL-CONSEJERO-DE-AGRICULTURA-EN-CASTROVEGA-DE-VALMADRIGAL-06-11-2019-2.jpg\",\"datePublished\":\"2019-11-07T08:17:27+00:00\",\"dateModified\":\"2019-11-15T14:11:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"El consejero de Agricultura y Ganader\u00eda de la Junta de Castilla y Le\u00f3n, Jes\u00fas Julio Carnero, se comprometi\u00f3 en una visita a la localidad de Castrovega de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/11\/ACTO-CON-EL-CONSEJERO-DE-AGRICULTURA-EN-CASTROVEGA-DE-VALMADRIGAL-06-11-2019-2.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/11\/ACTO-CON-EL-CONSEJERO-DE-AGRICULTURA-EN-CASTROVEGA-DE-VALMADRIGAL-06-11-2019-2.jpg\",\"width\":2016,\"height\":1134},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Junta licitar\u00e1 el Sector XVII de Payuelos en el primer trimestre del a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Junta licitar\u00e1 el Sector XVII de Payuelos en el primer trimestre del a\u00f1o - ASAJA Le\u00f3n","description":"El consejero de Agricultura y Ganader\u00eda de la Junta de Castilla y Le\u00f3n, Jes\u00fas Julio Carnero, se comprometi\u00f3 en una visita a la localidad de Castrovega de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano","og_locale":"es_ES","og_type":"article","og_title":"La Junta licitar\u00e1 el Sector XVII de Payuelos en el primer trimestre del a\u00f1o - ASAJA Le\u00f3n","og_description":"El consejero de Agricultura y Ganader\u00eda de la Junta de Castilla y Le\u00f3n, Jes\u00fas Julio Carnero, se comprometi\u00f3 en una visita a la localidad de Castrovega de","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2019-11-07T08:17:27+00:00","article_modified_time":"2019-11-15T14:11:23+00:00","og_image":[{"width":2016,"height":1134,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/11\/ACTO-CON-EL-CONSEJERO-DE-AGRICULTURA-EN-CASTROVEGA-DE-VALMADRIGAL-06-11-2019-2.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano","name":"La Junta licitar\u00e1 el Sector XVII de Payuelos en el primer trimestre del a\u00f1o - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/11\/ACTO-CON-EL-CONSEJERO-DE-AGRICULTURA-EN-CASTROVEGA-DE-VALMADRIGAL-06-11-2019-2.jpg","datePublished":"2019-11-07T08:17:27+00:00","dateModified":"2019-11-15T14:11:23+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"El consejero de Agricultura y Ganader\u00eda de la Junta de Castilla y Le\u00f3n, Jes\u00fas Julio Carnero, se comprometi\u00f3 en una visita a la localidad de Castrovega de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/11\/ACTO-CON-EL-CONSEJERO-DE-AGRICULTURA-EN-CASTROVEGA-DE-VALMADRIGAL-06-11-2019-2.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/11\/ACTO-CON-EL-CONSEJERO-DE-AGRICULTURA-EN-CASTROVEGA-DE-VALMADRIGAL-06-11-2019-2.jpg","width":2016,"height":1134},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/la-junta-licitara-el-sector-xvii-de-payuelos-en-el-primer-trimestre-del-ano#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"La Junta licitar\u00e1 el Sector XVII de Payuelos en el primer trimestre del a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10634"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=10634"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10634\/revisions"}],"predecessor-version":[{"id":10635,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10634\/revisions\/10635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/10636"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=10634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=10634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=10634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}