{"id":10946,"date":"2020-01-30T13:16:25","date_gmt":"2020-01-30T12:16:25","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=10946"},"modified":"2020-01-30T13:16:25","modified_gmt":"2020-01-30T12:16:25","slug":"crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon","title":{"rendered":"Crece una 42,2% la venta anual de tractores nuevos en Le\u00f3n"},"content":{"rendered":"<h6>En el periodo de enero a diciembre se matricularon en la provincia de Le\u00f3n 155 tractores agr\u00edcolas nuevos, lo que representa un crecimiento del 42,2 por ciento respecto a los 109 que se matricularon en todo el a\u00f1o 2018. Se confirma as\u00ed un crecimiento que ASAJA ya valor\u00f3 hace un mes con los datos de matriculaciones a 30 de noviembre (<a href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/crece-un-25-la-venta-anual-de-tractores-nuevos-en-leon-a-falta-de-conocer-los-datos-de-diciembre\">https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/crece-un-25-la-venta-anual-de-tractores-nuevos-en-leon-a-falta-de-conocer-los-datos-de-diciembre<\/a>).<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En el periodo de enero a diciembre se matricularon en la provincia de Le\u00f3n 155 tractores agr\u00edcolas nuevos, lo que representa un crecimiento del 42,2 por ciento respecto a los 109 que se matricularon en todo el a\u00f1o 2018. Se confirma as\u00ed un crecimiento que ASAJA ya valor\u00f3 hace un mes con los datos de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":6249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crece una 42,2% la venta anual de tractores nuevos en Le\u00f3n - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"En el periodo de enero a diciembre se matricularon en la provincia de Le\u00f3n 155 tractores agr\u00edcolas nuevos, lo que representa un crecimiento del 42,2 por\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crece una 42,2% la venta anual de tractores nuevos en Le\u00f3n - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"En el periodo de enero a diciembre se matricularon en la provincia de Le\u00f3n 155 tractores agr\u00edcolas nuevos, lo que representa un crecimiento del 42,2 por\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-30T12:16:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/CAMPUS_NEW_HOLLAND_20-02-17_3-1024x576.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon\",\"name\":\"Crece una 42,2% la venta anual de tractores nuevos en Le\u00f3n - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/CAMPUS_NEW_HOLLAND_20-02-17_3.jpg\",\"datePublished\":\"2020-01-30T12:16:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"En el periodo de enero a diciembre se matricularon en la provincia de Le\u00f3n 155 tractores agr\u00edcolas nuevos, lo que representa un crecimiento del 42,2 por\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/CAMPUS_NEW_HOLLAND_20-02-17_3.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/CAMPUS_NEW_HOLLAND_20-02-17_3.jpg\",\"width\":3920,\"height\":2204},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crece una 42,2% la venta anual de tractores nuevos en Le\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crece una 42,2% la venta anual de tractores nuevos en Le\u00f3n - ASAJA Le\u00f3n","description":"En el periodo de enero a diciembre se matricularon en la provincia de Le\u00f3n 155 tractores agr\u00edcolas nuevos, lo que representa un crecimiento del 42,2 por","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon","og_locale":"es_ES","og_type":"article","og_title":"Crece una 42,2% la venta anual de tractores nuevos en Le\u00f3n - ASAJA Le\u00f3n","og_description":"En el periodo de enero a diciembre se matricularon en la provincia de Le\u00f3n 155 tractores agr\u00edcolas nuevos, lo que representa un crecimiento del 42,2 por","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2020-01-30T12:16:25+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/CAMPUS_NEW_HOLLAND_20-02-17_3-1024x576.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon","name":"Crece una 42,2% la venta anual de tractores nuevos en Le\u00f3n - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/CAMPUS_NEW_HOLLAND_20-02-17_3.jpg","datePublished":"2020-01-30T12:16:25+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"En el periodo de enero a diciembre se matricularon en la provincia de Le\u00f3n 155 tractores agr\u00edcolas nuevos, lo que representa un crecimiento del 42,2 por","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/CAMPUS_NEW_HOLLAND_20-02-17_3.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/CAMPUS_NEW_HOLLAND_20-02-17_3.jpg","width":3920,"height":2204},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/crece-una-422-la-venta-anual-de-tractores-nuevos-en-leon#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Crece una 42,2% la venta anual de tractores nuevos en Le\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10946"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=10946"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10946\/revisions"}],"predecessor-version":[{"id":10947,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/10946\/revisions\/10947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/6249"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=10946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=10946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=10946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}