{"id":11301,"date":"2020-04-24T08:48:51","date_gmt":"2020-04-24T06:48:51","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=11301"},"modified":"2020-05-07T13:52:44","modified_gmt":"2020-05-07T11:52:44","slug":"las-seis-noticias-agrarias-la-semana-24-04-2020","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 24\/04\/2020"},"content":{"rendered":"<h2>Ayudas a la modernizaci\u00f3n de explotaciones y la incorporaci\u00f3n de j\u00f3venes agricultores, plazo de suscripci\u00f3n de determinadas l\u00edneas de seguros agrarios, Los hogares espa\u00f1oles han estabilizado sus compras de alimentos, f\u00e1brica de Pascual en Aranda de Duero, Subdelegado del Gobierno en Le\u00f3n, Faustino S\u00e1nchez, el Programa Nacional de Control y Erradicaci\u00f3n del vector\u00a0Trioza erytreae, y el Programa Nacional de Prevenci\u00f3n del vector\u00a0Daphorina Citri\u00a0y la bacteria Candidatus liberibacter.<\/h2>\n<ol>\n<li>\n<h6>\u00a0<strong>Las ayudas a la modernizaci\u00f3n de explotaciones y la incorporaci\u00f3n de j\u00f3venes agricultores<\/strong> mantienen abierto el plazo de solicitud debido a la declaraci\u00f3n del estado de alarma, aunque las organizaciones agrarias han seguido prestando servicios y por lo tanto consideran que ya han tramitado los expedientes de la mayor\u00eda de los interesados. A mediados de esta semana se hab\u00edan registrado 231 expedientes en la provincia, de los cuales 142 se han tramitado en ASAJA de Le\u00f3n.<\/h6>\n<\/li>\n<li>\n<h6>Pr\u00f3ximamente finaliza el plazo de <strong>suscripci\u00f3n de determinadas l\u00edneas de seguros agrarios<\/strong> de especial importancia en la provincia. As\u00ed, el 30 de abril finaliza el plazo para suscribir el seguro\u00a0 del vi\u00f1edo con coberturas de pedrisco. Unos d\u00edas m\u00e1s tarde, el 10 de mayo, finaliza el plazo para suscribir el seguro de l\u00fapulo, que permite asegurar tanto da\u00f1os en la planta, como da\u00f1os en las infraestructuras de postes y alambradas.<\/h6>\n<\/li>\n<li>\n<h6><strong>Los hogares espa\u00f1oles han estabilizado sus compras de alimentos<\/strong> la semana del 6 al 12 de abril, seg\u00fan se desprende de los datos del An\u00e1lisis de consumo en el hogar, del Ministerio de Agricultura, Pesca y Alimentaci\u00f3n. En esta cuarta semana tras la declaraci\u00f3n del estado de alarma, el volumen de compra de alimentos apenas se incrementa un 0,1 % en la semana 15 del a\u00f1o con respecto a la semana anterior, aunque experimenta una subida del 36,2 % en relaci\u00f3n a la misma semana de 2019.<\/h6>\n<\/li>\n<li>\n<h6>El presidente de la Junta de Castilla y Le\u00f3n visit\u00f3 el pasado martes la <strong>f\u00e1brica de Pascual en Aranda de Duero<\/strong> y se deshizo en elogios a la misma por el papel que desempe\u00f1a en el sector agroalimentario de la regi\u00f3n. Los ganaderos no entienden ese afecto de la Junta de Castilla y Le\u00f3n para con una empresa que forma el cartel, sancionado por la Comisi\u00f3n Nacional del Mercado de la Competencia, que durante a\u00f1os pact\u00f3 precios y perjudic\u00f3 a los ingresos de miles de familias ganaderas de Castilla y Le\u00f3n y del resto de Espa\u00f1a.<\/h6>\n<\/li>\n<li>\n<h6>El<strong> Subdelegado del Gobierno en Le\u00f3n, Faustino S\u00e1nchez<\/strong>, se reuni\u00f3 el ayer viernes por videoconferencia con las organizaciones agrarias y con los sindicatos de clase de los trabajadores para\u00a0 analizar las medidas puestas en marcha por el Gobierno, durante el estado de alarma sanitaria, en relaci\u00f3n con el empleo agrario. El objetivo de las medidas es paliar la falta de mano de obra debido a las restricciones de movimiento de trabajadores inmigrantes, algo que afecta sobre todo a los trabajos de campa\u00f1a.<\/h6>\n<\/li>\n<li>\n<h6>El Consejo de Ministros del 21 de abril aprob\u00f3 un Real Decreto que modifica otro anterior\u00a0en el que se establece el <strong>Programa Nacional de Control y Erradicaci\u00f3n del vector\u00a0<em>Trioza erytreae<\/em>, y el Programa Nacional de Prevenci\u00f3n del vector\u00a0<em>Daphorina Citri<\/em>\u00a0y la bacteria C<em>andidatus liberibacter<\/em>. Unas plagas y enfermedad que afectan a c\u00edtricos, plantas ornamentales y otras especies sensibles<\/strong>. Con ello se actualiza la normativa vigente, incorporando al ordenamiento jur\u00eddico nacional las nuevas disposiciones en esta materia, recogidas en los \u00faltimos reglamentos de la Uni\u00f3n Europea,\u00a0relativos a las medidas de protecci\u00f3n contra la introducci\u00f3n de organismos nocivos para los vegetales y contra su propagaci\u00f3n.<\/h6>\n<\/li>\n<\/ol>\n<h6><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Ayudas a la modernizaci\u00f3n de explotaciones y la incorporaci\u00f3n de j\u00f3venes agricultores, plazo de suscripci\u00f3n de determinadas l\u00edneas de seguros agrarios, Los hogares espa\u00f1oles han estabilizado sus compras de alimentos, f\u00e1brica de Pascual en Aranda de Duero, Subdelegado del Gobierno en Le\u00f3n, Faustino S\u00e1nchez, el Programa Nacional de Control y Erradicaci\u00f3n del vector\u00a0Trioza erytreae, y [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":7572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 24\/04\/2020 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Ayudas a la modernizaci\u00f3n de explotaciones y la incorporaci\u00f3n de j\u00f3venes agricultores, plazo de suscripci\u00f3n de determinadas l\u00edneas de seguros agrarios,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 24\/04\/2020 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Ayudas a la modernizaci\u00f3n de explotaciones y la incorporaci\u00f3n de j\u00f3venes agricultores, plazo de suscripci\u00f3n de determinadas l\u00edneas de seguros agrarios,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-24T06:48:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-07T11:52:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pivot_para_campo_leones.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020\",\"name\":\"Las seis noticias agrarias de la semana - 24\/04\/2020 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pivot_para_campo_leones.jpg\",\"datePublished\":\"2020-04-24T06:48:51+00:00\",\"dateModified\":\"2020-05-07T11:52:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Ayudas a la modernizaci\u00f3n de explotaciones y la incorporaci\u00f3n de j\u00f3venes agricultores, plazo de suscripci\u00f3n de determinadas l\u00edneas de seguros agrarios,\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pivot_para_campo_leones.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pivot_para_campo_leones.jpg\",\"width\":1600,\"height\":1200,\"caption\":\"pivot\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 24\/04\/2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 24\/04\/2020 - ASAJA Le\u00f3n","description":"Ayudas a la modernizaci\u00f3n de explotaciones y la incorporaci\u00f3n de j\u00f3venes agricultores, plazo de suscripci\u00f3n de determinadas l\u00edneas de seguros agrarios,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 24\/04\/2020 - ASAJA Le\u00f3n","og_description":"Ayudas a la modernizaci\u00f3n de explotaciones y la incorporaci\u00f3n de j\u00f3venes agricultores, plazo de suscripci\u00f3n de determinadas l\u00edneas de seguros agrarios,","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2020-04-24T06:48:51+00:00","article_modified_time":"2020-05-07T11:52:44+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pivot_para_campo_leones.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020","name":"Las seis noticias agrarias de la semana - 24\/04\/2020 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pivot_para_campo_leones.jpg","datePublished":"2020-04-24T06:48:51+00:00","dateModified":"2020-05-07T11:52:44+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Ayudas a la modernizaci\u00f3n de explotaciones y la incorporaci\u00f3n de j\u00f3venes agricultores, plazo de suscripci\u00f3n de determinadas l\u00edneas de seguros agrarios,","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pivot_para_campo_leones.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pivot_para_campo_leones.jpg","width":1600,"height":1200,"caption":"pivot"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-la-semana-24-04-2020#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 24\/04\/2020"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/11301"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=11301"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/11301\/revisions"}],"predecessor-version":[{"id":11302,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/11301\/revisions\/11302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/7572"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=11301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=11301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=11301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}