{"id":11398,"date":"2020-05-27T14:19:46","date_gmt":"2020-05-27T12:19:46","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=11398"},"modified":"2020-05-27T14:19:46","modified_gmt":"2020-05-27T12:19:46","slug":"cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020","title":{"rendered":"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n &#8211; Sesi\u00f3n 27\/05\/2020"},"content":{"rendered":"<h2><strong>Comienza a cotizar en la Lonja de Le\u00f3n la alfalfa en rama, la veza y forrajes<\/strong><\/h2>\n<h6>En la sesi\u00f3n de la lonja de Le\u00f3n celebrada hoy en Santa Mar\u00eda del P\u00e1ramo, ha comenzado a cotizar la nueva campa\u00f1a de alfalfas, vezas y forrajes, a 150 \u20ac\/t, 108 \u20ac\/t y 80 \u20ac\/t respectivamente.<\/h6>\n<h6>Se espera una buena campa\u00f1a con rendimientos superiores a la media y en especial a la de la campa\u00f1a 2.019 que fue desastrosa.<\/h6>\n<h6>En la provincia de Le\u00f3n hay 12.000 ha de alfalfa y 10.300 ha de veza forrajera.<\/h6>\n<h6>Hoy tambi\u00e9n se ha tomado la decisi\u00f3n de dejar de cotizar todos los cereales de invierno a la espera de la nueva cosecha, puesto que ya no hay g\u00e9nero en manos de los agricultores, solamente ha cotizado el ma\u00edz a 161\u20ac\/t, lo que representa una bajada de 1 euro.<\/h6>\n<h6>En Le\u00f3n a 27 de mayo de 2.020.<\/h6>\n<h6>Precios Orientativos Euros\/Tonelada <u>en Almac\u00e9n<\/u><\/h6>\n<h6>(Condiciones de Calidad O.C.M. Cereales-F.E.G.A. Campa\u00f1a 2017\/2018)<\/h6>\n<h6><\/h6>\n<table>\n<tbody>\n<tr>\n<td width=\"206\">\n<h6><strong>CEREALES<\/strong><\/h6>\n<\/td>\n<td width=\"123\">\n<h6><strong>COTIZACION<\/strong><\/h6>\n<h6><strong>ANTERIOR<\/strong><\/h6>\n<\/td>\n<td width=\"132\">\n<h6><strong>COTIZACION<\/strong><\/h6>\n<h6><strong>ACTUAL<\/strong><\/h6>\n<\/td>\n<td width=\"113\">\n<h6><strong>DIF.<\/strong><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6><\/h6>\n<\/td>\n<td width=\"123\">\n<h6><strong>\u20ac\/t<\/strong><\/h6>\n<\/td>\n<td width=\"132\">\n<h6><strong>\u20ac\/t<\/strong><\/h6>\n<\/td>\n<td width=\"113\">\n<h6><strong>\u00a0<\/strong><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Trigo Pienso<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>183,00<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"113\">\n<h6><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Cebada<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>155,00<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"113\">\n<h6><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Triticale<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"113\">\n<h6><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Centeno<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>154,00<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"113\">\n<h6><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Avena<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"113\">\n<h6><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Ma\u00edz<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>162,00<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>161,00<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>\u25bc<\/h6>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h6><\/h6>\n<h6>*\u00a0 Ma\u00edz\u00a0 con menos del 15% de humedad<\/h6>\n<h6><\/h6>\n<h6><\/h6>\n<h6><\/h6>\n<h6><\/h6>\n<h6><\/h6>\n<h6><\/h6>\n<h6><\/h6>\n<table>\n<tbody>\n<tr>\n<td width=\"206\">\n<h6><strong>FORRAJES<\/strong><\/h6>\n<\/td>\n<td width=\"123\">\n<h6><strong>COTIZACION<\/strong><\/h6>\n<h6><strong>ANTERIOR<\/strong><\/h6>\n<\/td>\n<td width=\"123\">\n<h6><strong>COTIZACION<\/strong><\/h6>\n<h6><strong>ACTUAL<\/strong><\/h6>\n<\/td>\n<td width=\"76\">\n<h6><strong>DIF.<\/strong><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6><\/h6>\n<\/td>\n<td width=\"123\">\n<h6><strong>\u20ac\/t<\/strong><\/h6>\n<\/td>\n<td width=\"123\">\n<h6><strong>\u20ac\/t<\/strong><\/h6>\n<\/td>\n<td width=\"76\">\n<h6><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Alfalfa paquete rama<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>150,00<\/h6>\n<\/td>\n<td width=\"76\">\n<h6><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Alfalfa paquete deshidratado<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"76\">\n<h6><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Paja 1\u00aa (Cebada)<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>45,00<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>45,00<\/h6>\n<\/td>\n<td width=\"76\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Veza forraje de 1\u00aa<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>108,00<\/h6>\n<\/td>\n<td width=\"76\">\n<h6><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Forraje<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>80,00<\/h6>\n<\/td>\n<td width=\"76\">\n<h6><\/h6>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h6><\/h6>\n<h6><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Comienza a cotizar en la Lonja de Le\u00f3n la alfalfa en rama, la veza y forrajes En la sesi\u00f3n de la lonja de Le\u00f3n celebrada hoy en Santa Mar\u00eda del P\u00e1ramo, ha comenzado a cotizar la nueva campa\u00f1a de alfalfas, vezas y forrajes, a 150 \u20ac\/t, 108 \u20ac\/t y 80 \u20ac\/t respectivamente. Se espera una [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":9046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cotizaciones de la Lonja Agropecuaria de Le\u00f3n - Sesi\u00f3n 27\/05\/2020 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Comienza a cotizar en la Lonja de Le\u00f3n la alfalfa en rama, la veza y forrajes En la sesi\u00f3n de la lonja de Le\u00f3n celebrada hoy en Santa Mar\u00eda del P\u00e1ramo, ha\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n - Sesi\u00f3n 27\/05\/2020 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Comienza a cotizar en la Lonja de Le\u00f3n la alfalfa en rama, la veza y forrajes En la sesi\u00f3n de la lonja de Le\u00f3n celebrada hoy en Santa Mar\u00eda del P\u00e1ramo, ha\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-27T12:19:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/tractor_segando.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020\",\"name\":\"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n - Sesi\u00f3n 27\/05\/2020 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/tractor_segando.jpg\",\"datePublished\":\"2020-05-27T12:19:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Comienza a cotizar en la Lonja de Le\u00f3n la alfalfa en rama, la veza y forrajes En la sesi\u00f3n de la lonja de Le\u00f3n celebrada hoy en Santa Mar\u00eda del P\u00e1ramo, ha\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/tractor_segando.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/tractor_segando.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n &#8211; Sesi\u00f3n 27\/05\/2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n - Sesi\u00f3n 27\/05\/2020 - ASAJA Le\u00f3n","description":"Comienza a cotizar en la Lonja de Le\u00f3n la alfalfa en rama, la veza y forrajes En la sesi\u00f3n de la lonja de Le\u00f3n celebrada hoy en Santa Mar\u00eda del P\u00e1ramo, ha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020","og_locale":"es_ES","og_type":"article","og_title":"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n - Sesi\u00f3n 27\/05\/2020 - ASAJA Le\u00f3n","og_description":"Comienza a cotizar en la Lonja de Le\u00f3n la alfalfa en rama, la veza y forrajes En la sesi\u00f3n de la lonja de Le\u00f3n celebrada hoy en Santa Mar\u00eda del P\u00e1ramo, ha","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2020-05-27T12:19:46+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/tractor_segando.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020","name":"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n - Sesi\u00f3n 27\/05\/2020 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/tractor_segando.jpg","datePublished":"2020-05-27T12:19:46+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Comienza a cotizar en la Lonja de Le\u00f3n la alfalfa en rama, la veza y forrajes En la sesi\u00f3n de la lonja de Le\u00f3n celebrada hoy en Santa Mar\u00eda del P\u00e1ramo, ha","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/tractor_segando.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/tractor_segando.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-27-05-2020#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n &#8211; Sesi\u00f3n 27\/05\/2020"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/11398"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=11398"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/11398\/revisions"}],"predecessor-version":[{"id":11399,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/11398\/revisions\/11399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/9046"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=11398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=11398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=11398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}