{"id":11734,"date":"2020-09-25T14:40:19","date_gmt":"2020-09-25T12:40:19","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=11734"},"modified":"2020-10-02T09:41:11","modified_gmt":"2020-10-02T07:41:11","slug":"las-seis-noticias-agrarias-de-la-semana-25-09-2020","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 25\/09\/2020"},"content":{"rendered":"\n<h2>Reglamento de la Denominaci\u00f3n de Origen Bierzo, asociaci\u00f3n de productores de patata del noroeste de Europa, el consejero de agricultura y la presidenta de CHD, declaraci\u00f3n obligatoria sobre datos de la cosecha de uva, da\u00f1os por sequ\u00eda en el cultivo de la alfalfa de secano, registro de operadores y establecimientos en el sector de la alimentaci\u00f3n animal<\/h2>\n<ol>\n<li>\n<h6>En el BOCYL de 17 de septiembre se ha publicado la Orden AGR 842\/2020, de 2 de septiembre, por la que se aprueba el nuevo Reglamento de la Denominaci\u00f3n de Origen Bierzo y de su Consejo Regulador. Este reglamento, que sustituye al vigente, se ha elaborado como una necesidad para responder a cambios normativos, tanto en aspecto t\u00e9cnicos como org\u00e1nicos, que se han venido sucediendo desde la aprobaci\u00f3n del inicial en 1989.<\/h6>\n<\/li>\n<li>\n<h6>La asociaci\u00f3n de productores de patata del noroeste de Europa ha publicado sus estimaciones de rendimientos y producci\u00f3n de esta campa\u00f1a. Francia ha incrementado su producci\u00f3n un 16% respecto a la media de los \u00faltimos cinco a\u00f1os, y Alemania un 10%. La asociaci\u00f3n ha advertido a los socios que si quieren mantener un nivel de precios aceptable para el a\u00f1o 2021, deben de ser prudentes a la hora de planificar las siembras.<\/h6>\n<\/li>\n<li>\n<h6>El consejero de Agricultura, Ganader\u00eda y Desarrollo Rural, Jes\u00fas Julio Carnero, y la presidenta de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero, Cristina Dan\u00e9s, se han reunido recientemente en Valladolid, para abordar los temas importantes de presente y de futuro en materia de gesti\u00f3n del agua\u00a0y desarrollo rural que competen a ambas administraciones. Se ha hablado de las actuaciones recogidas en el Plan Hidrol\u00f3gico actual, de las regulaciones pendientes urgentes, del tercer ciclo de planificaci\u00f3n hidrol\u00f3gica (2021-2027), de la problem\u00e1tica de los regad\u00edos de aguas subterr\u00e1neas y de tr\u00e1mites administrativos vinculados a importantes zonas de regad\u00edo de Castilla y Le\u00f3n.<\/h6>\n<\/li>\n<li>\n<h6>ASAJA recuerda a los viticultores que hasta el 10 de diciembre disponen de plazo para efectuar la declaraci\u00f3n obligatoria sobre datos de la cosecha de uva obtenida en 2020, pues as\u00ed lo recoge el Real Decreto 739\/2015. No cumplir con esta obligaci\u00f3n conlleva sanciones administrativas. Si bien hasta ahora la Junta de Castilla y Le\u00f3n no hab\u00eda actuado en esta materia, todo parece indicar que en esta campa\u00f1a se van a intensificar los controles. Adem\u00e1s, muchos viticultores se vieron excluidos de las ayudas al sector por no tener hecho este tr\u00e1mite en campa\u00f1as anteriores.<\/h6>\n<\/li>\n<li>\n<h6>La Compa\u00f1\u00eda Agroseguro, con el benepl\u00e1cito de ENESA, va a poner en marcha ya para esta pr\u00f3xima campa\u00f1a una nueva cobertura de da\u00f1os por sequ\u00eda en el cultivo de la alfalfa de secano. Se establecer\u00e1n unos rendimientos m\u00e1ximos asegurables que ser\u00e1n de 2.600 kilos en el primer corte y de 1.400 kilos en el segundo corte, y se garantiza el 70% de dicha producci\u00f3n asegurada cuando no se alcance debido a la sequ\u00eda.<\/h6>\n<\/li>\n<li>\n<h6>La consejer\u00eda de Agricultura prepara una Orden por la que se va a regular el registro de operadores y establecimientos en el sector de la alimentaci\u00f3n animal, a la vez que derogar\u00e1 normativa anterior en esta materia. Esta norma ser\u00e1 un desarrollo del Real Decreto 629\/2019. Afecta a fabricantes, comerciantes y transportistas de piensos, aditivos, premezclas de aditivos y piensos compuestos.<\/h6>\n<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Reglamento de la Denominaci\u00f3n de Origen Bierzo, asociaci\u00f3n de productores de patata del noroeste de Europa, el consejero de agricultura y la presidenta de CHD, declaraci\u00f3n obligatoria sobre datos de la cosecha de uva, da\u00f1os por sequ\u00eda en el cultivo de la alfalfa de secano, registro de operadores y establecimientos en el sector de la [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":8669,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 25\/09\/2020 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Reglamento de la Denominaci\u00f3n de Origen Bierzo, asociaci\u00f3n de productores de patata del noroeste de Europa, el consejero de agricultura y la presidenta de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 25\/09\/2020 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Reglamento de la Denominaci\u00f3n de Origen Bierzo, asociaci\u00f3n de productores de patata del noroeste de Europa, el consejero de agricultura y la presidenta de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-25T12:40:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-02T07:41:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/frutales-bierzo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020\",\"name\":\"Las seis noticias agrarias de la semana - 25\/09\/2020 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/frutales-bierzo.jpg\",\"datePublished\":\"2020-09-25T12:40:19+00:00\",\"dateModified\":\"2020-10-02T07:41:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Reglamento de la Denominaci\u00f3n de Origen Bierzo, asociaci\u00f3n de productores de patata del noroeste de Europa, el consejero de agricultura y la presidenta de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/frutales-bierzo.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/frutales-bierzo.jpg\",\"width\":2500,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 25\/09\/2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 25\/09\/2020 - ASAJA Le\u00f3n","description":"Reglamento de la Denominaci\u00f3n de Origen Bierzo, asociaci\u00f3n de productores de patata del noroeste de Europa, el consejero de agricultura y la presidenta de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 25\/09\/2020 - ASAJA Le\u00f3n","og_description":"Reglamento de la Denominaci\u00f3n de Origen Bierzo, asociaci\u00f3n de productores de patata del noroeste de Europa, el consejero de agricultura y la presidenta de","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2020-09-25T12:40:19+00:00","article_modified_time":"2020-10-02T07:41:11+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/frutales-bierzo.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020","name":"Las seis noticias agrarias de la semana - 25\/09\/2020 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/frutales-bierzo.jpg","datePublished":"2020-09-25T12:40:19+00:00","dateModified":"2020-10-02T07:41:11+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Reglamento de la Denominaci\u00f3n de Origen Bierzo, asociaci\u00f3n de productores de patata del noroeste de Europa, el consejero de agricultura y la presidenta de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/frutales-bierzo.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/frutales-bierzo.jpg","width":2500,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-25-09-2020#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 25\/09\/2020"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/11734"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=11734"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/11734\/revisions"}],"predecessor-version":[{"id":11735,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/11734\/revisions\/11735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8669"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=11734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=11734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=11734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}