{"id":11868,"date":"2020-12-02T13:06:55","date_gmt":"2020-12-02T12:06:55","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=11868"},"modified":"2020-12-02T13:06:56","modified_gmt":"2020-12-02T12:06:56","slug":"situacion-del-sector-de-la-leche-de-vacuno","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno","title":{"rendered":"Situaci\u00f3n del sector de la leche de vacuno"},"content":{"rendered":"\n<h6>En el a\u00f1o 2019 se entregaron a industrias <strong>7.221.934 toneladas de leche<\/strong>, lo que supuso un 1,4% m\u00e1s que el a\u00f1o 2018, el cual se creci\u00f3 tambi\u00e9n un 1,4% respecto a 2017. La principal comunidad aut\u00f3noma en producci\u00f3n es Galicia con el 38%, seguida de <strong>Castilla y Le\u00f3n<\/strong>, que ha representado, tanto en 2019 como en 2018, el <strong>13% de la producci\u00f3n nacional<\/strong>.<\/h6>\n<h6><strong><u>Censos<\/u><\/strong><\/h6>\n<h6>El censo de vacas lecheras en noviembre 2020 era de <strong>829.197 vacas<\/strong> de m\u00e1s de 24 meses, as\u00ed como de <strong>275.583 novillas<\/strong>, representando las novillas el 25% del total de animales, lo que significa que cada cuatro a\u00f1os, de media, se reponen la totalidad de vacas en producci\u00f3n, o lo que es lo mismo, la vida medida de una vaca en producci\u00f3n es de cuatro partos.<\/h6>\n<h6>El censo de vacas lecheras en Castilla y Le\u00f3n es de <strong>94.258<\/strong>, lo que representa el <strong>11% del censo total<\/strong>. Si con el 11% de vacas producimos el 13% de la leche, es evidente que las vacas de Castilla y Le\u00f3n son m\u00e1s productivas que la media nacional. Seg\u00fan los datos que se aportan, la producci\u00f3n por hembra lechera es de <strong>9.960 litros a\u00f1o en Castilla y Le\u00f3n<\/strong>, mientras que en el conjunto de Espa\u00f1a se sit\u00faa en 8.710 litros.<\/h6>\n<h6>En n\u00famero de ganaderos, en el pasado mes de septiembre hubo <strong>12.320 ganaderos<\/strong> con entregas en el conjunto del territorio espa\u00f1ol, y esto es un 5,4% menos que el mismo mes del a\u00f1o anterior. Por n\u00famero de ganaderos, Galicia es la primera comunidad aut\u00f3noma, seguida de Asturias y Cantabria, situ\u00e1ndose <strong>Castilla y Le\u00f3n en cuarta posici\u00f3n con el 8% del censo<\/strong> de ganaderos, lo que equivaldr\u00eda a <strong>985 ganaderos o explotaciones<\/strong>. Con esto datos, <strong>cada explotaci\u00f3n l\u00e1ctea produce una media de 586.000 litros de leche al a\u00f1o, que en el caso de Castilla y Le\u00f3n se eleva hasta los <u>953.000 litros<\/u> al a\u00f1o.<\/strong><\/h6>\n<h6><em>En resumen, Castilla y Le\u00f3n, con el 8% de explotaciones y el 11% del censo de vacas en lactaci\u00f3n, produce el 13% de toda la\u00a0 leche (953.000 toneladas). Por lo tanto, las ganader\u00edas de Castilla y Le\u00f3n est\u00e1n m\u00e1s dimensionadas que la media y las vacas producen m\u00e1s leche por cada lactaci\u00f3n<\/em>.<\/h6>\n<h6>Aunque el informe de coyuntura del Ministerio de Agricultura no\u00a0 entra en esta cuesti\u00f3n, <strong>la alimentaci\u00f3n es un factor diferencial tambi\u00e9n en la ganader\u00eda de vacuno de leche de Castilla y Le\u00f3n<\/strong>. En la raci\u00f3n de volumen la materia prima con m\u00e1s peso es el ma\u00edz forrajero y el \u201cpastone\u201d de ma\u00edz, y es Castilla y Le\u00f3n la principal zona productora de Espa\u00f1a, adem\u00e1s de que en las principales comarcas ganaderas, ubicadas en Palencia y Le\u00f3n, los ganaderos producen en sus fincas agr\u00edcolas el ma\u00edz que consumen. Pero adem\u00e1s\u00a0 Castilla y Le\u00f3n exporta otras materias primas necesarias en la alimentaci\u00f3n de las vacas lecheras como es el grano de cereal, paja de cereal, forraje de cereal y heno de alfalfa. En resumen, <strong>los menores costes en la alimentaci\u00f3n con respecto a otras zonas productoras, a pesar de no tener pastos, es un factor que juega a favor de la ganader\u00eda de leche de Castilla y Le\u00f3n.<\/strong><\/h6>\n<h6><strong><u>Fabricaci\u00f3n de l\u00e1cteos en Espa\u00f1a<\/u><\/strong><\/h6>\n<table>\n<tbody>\n<tr>\n<td width=\"360\">\n<h6>Leche consumo directo<\/h6>\n<\/td>\n<td width=\"169\">\n<h6>2.154.957<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"360\">\n<h6>Nata<\/h6>\n<\/td>\n<td width=\"169\">\n<h6>597.251<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"360\">\n<h6>Yogures<\/h6>\n<\/td>\n<td width=\"169\">\n<h6>790.723<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"360\">\n<h6>Leche concentrada<\/h6>\n<\/td>\n<td width=\"169\">\n<h6>68.259<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"360\">\n<h6>Leche en polvo<\/h6>\n<\/td>\n<td width=\"169\">\n<h6>85.819<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"360\">\n<h6>Mantequilla<\/h6>\n<\/td>\n<td width=\"169\">\n<h6>536.036<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"360\">\n<h6>Queso de vaca<\/h6>\n<\/td>\n<td width=\"169\">\n<h6>1.038.680<\/h6>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h6>\u00a0<\/h6>\n<h6><strong><u>Consumo<\/u><\/strong><\/h6>\n<h6>Respecto al consumo, en los \u00faltimos a\u00f1os se ha venido detectando un descenso del consumo en Espa\u00f1a. En 2019 el consumo en hogares ascendi\u00f3 a 3.194.952 toneladas de leche, 733.771 toneladas de yogures, y 359.925 toneladas de queso. Las circunstancias excepcionales de este a\u00f1o 2020 han provocado tambi\u00e9n cambios importantes en la estad\u00edstica del consumo de l\u00e1cteos, y as\u00ed, <strong>en el periodo enero- agosto de 2020 el consumo de leche se ha incrementado el 7,6%, el 5,7% los yogures, y el 15% los quesos<\/strong>.<\/h6>\n<h6><strong><u>Comercio exterior<\/u><\/strong><\/h6>\n<h6>Cada a\u00f1o <strong>Espa\u00f1a est\u00e1 reduciendo su dependencia exterior en l\u00e1cteos<\/strong>. En 2019 exportamos sobre todo nata, quesos y mantequilla, y el destino pa\u00edses europeos como Francia, Portugal, Italia y Pa\u00edses Bajos. Son poco relevantes las exportaciones a pa\u00edses terceros.<\/h6>\n<h6>Las importaciones fueron sobre todo de quesos, leche en polvo y mantequilla, y la procedencia Francia, Alemania,\u00a0 Pa\u00edses Bajos y Portugal.<\/h6>\n<h6>Comparando el a\u00f1o 2019 con 2018, en valor las importaciones aumentaron el 22% y las exportaciones aumentaron el 38%.<\/h6>\n<h6><strong><u>Precios al ganadero<\/u><\/strong><\/h6>\n<h6>Durante 2019 los precios fueron ligeramente superiores a 2018. Tomando como referencia el mes de octubre, el\u00a0 Observatorio de Precios de la Leche de la Comisi\u00f3n Europea fija para <strong>Espa\u00f1a un precio medio de 31,17 euros por cien litros, lo que es un 19,76% menos de los 37,33 que cobraron los ganaderos franceses, nuestros principales competidores, o un 9,27% menos de los 34,06 euros por cien litros que cobraron el conjunto de los ganaderos de la UE-27<\/strong>. Aunque esas diferencias se han agrandado en los \u00faltimos meses, no es algo puntual que siendo Espa\u00f1a deficitaria en la producci\u00f3n de leche se pague a los ganaderos menos de lo que se les paga en los pa\u00edses exportadores o menos de lo que se paga a los ganaderos del conjunto de la Uni\u00f3n Europea. Estas diferencies comenzaron a ser patentes en 2016 y desde entonces as\u00ed se mantienen. En los diez meses del a\u00f1o 2020, la leche en Espa\u00f1a se ha pagado a una media de 31,89 euros cada cien litros, en Francia 35,99 euros y en el conjunto de la Uni\u00f3n a 33,7 euros. <strong>De los principales pa\u00edses que importamos leche o sus derivados, el precio al ganadero es mejor que en Espa\u00f1a en todos ellos salvo en Portugal.<\/strong><\/h6>\n<h6>ASAJA CYL. 23 de noviembre de 2020.<\/h6>\n<h6>*La mayor\u00eda de los datos se han tomado del informe de coyuntura publicado por el Ministerio de Agricultura, Pesca y Alimentaci\u00f3n.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En el a\u00f1o 2019 se entregaron a industrias 7.221.934 toneladas de leche, lo que supuso un 1,4% m\u00e1s que el a\u00f1o 2018, el cual se creci\u00f3 tambi\u00e9n un 1,4% respecto a 2017. La principal comunidad aut\u00f3noma en producci\u00f3n es Galicia con el 38%, seguida de Castilla y Le\u00f3n, que ha representado, tanto en 2019 como [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":7563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Situaci\u00f3n del sector de la leche de vacuno - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"En el a\u00f1o 2019 se entregaron a industrias 7.221.934 toneladas de leche, lo que supuso un 1,4% m\u00e1s que el a\u00f1o 2018, el cual se creci\u00f3 tambi\u00e9n un 1,4%\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Situaci\u00f3n del sector de la leche de vacuno - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"En el a\u00f1o 2019 se entregaron a industrias 7.221.934 toneladas de leche, lo que supuso un 1,4% m\u00e1s que el a\u00f1o 2018, el cual se creci\u00f3 tambi\u00e9n un 1,4%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-02T12:06:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-02T12:06:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1109\" \/>\n\t<meta property=\"og:image:height\" content=\"926\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno\",\"name\":\"Situaci\u00f3n del sector de la leche de vacuno - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg\",\"datePublished\":\"2020-12-02T12:06:55+00:00\",\"dateModified\":\"2020-12-02T12:06:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"En el a\u00f1o 2019 se entregaron a industrias 7.221.934 toneladas de leche, lo que supuso un 1,4% m\u00e1s que el a\u00f1o 2018, el cual se creci\u00f3 tambi\u00e9n un 1,4%\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg\",\"width\":1109,\"height\":926},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Situaci\u00f3n del sector de la leche de vacuno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Situaci\u00f3n del sector de la leche de vacuno - ASAJA Le\u00f3n","description":"En el a\u00f1o 2019 se entregaron a industrias 7.221.934 toneladas de leche, lo que supuso un 1,4% m\u00e1s que el a\u00f1o 2018, el cual se creci\u00f3 tambi\u00e9n un 1,4%","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno","og_locale":"es_ES","og_type":"article","og_title":"Situaci\u00f3n del sector de la leche de vacuno - ASAJA Le\u00f3n","og_description":"En el a\u00f1o 2019 se entregaron a industrias 7.221.934 toneladas de leche, lo que supuso un 1,4% m\u00e1s que el a\u00f1o 2018, el cual se creci\u00f3 tambi\u00e9n un 1,4%","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2020-12-02T12:06:55+00:00","article_modified_time":"2020-12-02T12:06:56+00:00","og_image":[{"width":1109,"height":926,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno","name":"Situaci\u00f3n del sector de la leche de vacuno - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg","datePublished":"2020-12-02T12:06:55+00:00","dateModified":"2020-12-02T12:06:56+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"En el a\u00f1o 2019 se entregaron a industrias 7.221.934 toneladas de leche, lo que supuso un 1,4% m\u00e1s que el a\u00f1o 2018, el cual se creci\u00f3 tambi\u00e9n un 1,4%","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg","width":1109,"height":926},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/situacion-del-sector-de-la-leche-de-vacuno#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Situaci\u00f3n del sector de la leche de vacuno"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/11868"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=11868"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/11868\/revisions"}],"predecessor-version":[{"id":11869,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/11868\/revisions\/11869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/7563"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=11868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=11868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=11868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}