{"id":12042,"date":"2021-02-05T10:33:29","date_gmt":"2021-02-05T09:33:29","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=12042"},"modified":"2021-02-12T13:37:03","modified_gmt":"2021-02-12T12:37:03","slug":"la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon","title":{"rendered":"La mayor protecci\u00f3n del lobo es una decisi\u00f3n ideol\u00f3gica muy lesiva para los intereses ganaderos de la provincia de Le\u00f3n"},"content":{"rendered":"\n<h6>La organizaci\u00f3n agraria ASAJA rechaza con la m\u00e1xima contundencia el acuerdo adoptado en el d\u00eda de ayer por el Gobierno y determinadas comunidades aut\u00f3nomas para aumentar el grado de\u00a0 protecci\u00f3n sobre el lobo y consecuencia de ello sacarlo del listado de especies cineg\u00e9ticas. Aunque ASAJA no est\u00e1 satisfecha con el control que se viene haciendo de la especie, ya que ning\u00fan a\u00f1o se cumplen los cupos de ejemplares que se pueden abatir, una regulaci\u00f3n m\u00e1s restrictiva contribuir\u00e1 a un censo mayor de camadas de lobos por todo el territorio provincial incluidas zonas en la que nunca antes se hab\u00eda avistado.<\/h6>\n<h6>Hoy el lobo es ya el gran enemigo de la ganader\u00eda extensiva en pastoreo, sobre todo de vacuno y de equino, en todas las comarcas monta\u00f1osas y de media monta\u00f1a de la provincia Le\u00f3n. Donde este c\u00e1nido campa a sus anchas es inviable hacer una ganader\u00eda extensiva en la que el ganadero no est\u00e1 permanentemente presente con el ganado, y aunque hubiera mecanismos de compensaci\u00f3n econ\u00f3mica, que no los hay, ello no ser\u00eda una soluci\u00f3n. \u00a0En el ganado ovino los da\u00f1os no son tan elevados ya que las ovejas son animales gregarios, que pastan juntos, y siempre est\u00e1 presente el pastor, que junto a los perros mastines, consiguen ahuyentar la mayor\u00eda de los ataques. Muchos da\u00f1os de los lobos no se pueden demostrar y por lo tanto peritar, y al valor del animal siniestrado hay que sumar un lucro cesante que a veces es superior todav\u00eda.<\/h6>\n<h6>Tan pronto como cambie el estatus actual del lobo al norte del r\u00edo Duero, donde se encuentra la provincia de Le\u00f3n, se dejar\u00e1 de percibir la indemnizaci\u00f3n por da\u00f1os de este c\u00e1nido en los cotos de caza que gestiona la Junta de Castilla y Le\u00f3n, como son las reservas de caza de los Ancares, Mampodre y Ria\u00f1o. La prohibici\u00f3n de la caza supone tambi\u00e9n una p\u00e9rdida de ingresos para las juntas vecinales de la provincia propietarias de los cotos cineg\u00e9ticos.<\/h6>\n<h6>ASAJA considera que la decisi\u00f3n de ayer es una victoria de los conservacionistas contra los ganaderos, y que ha sido posible por la propensi\u00f3n del Gobierno a tomar decisiones marcadas por sesgos ideol\u00f3gicos al margen de las valoraciones t\u00e9cnicas, de la equidad y del sentido com\u00fan. Se equivoca el Gobierno legislando contra los intereses de quienes viven en los pueblos, sin escucharles ni empatizar con ellos, para tener contenta a una legi\u00f3n de conservacionistas \u201cperroflautas\u201d unos y \u201cni\u00f1os de pap\u00e1\u201d otros, que \u00fanicamente se acercan al campo de fin de semana y normalmente para crear problemas a la poblaci\u00f3n local.<\/h6>\n<h6>ASAJA. Le\u00f3n, 5 de febrero de 2021<\/h6>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n agraria ASAJA rechaza con la m\u00e1xima contundencia el acuerdo adoptado en el d\u00eda de ayer por el Gobierno y determinadas comunidades aut\u00f3nomas para aumentar el grado de\u00a0 protecci\u00f3n sobre el lobo y consecuencia de ello sacarlo del listado de especies cineg\u00e9ticas. Aunque ASAJA no est\u00e1 satisfecha con el control que se viene haciendo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":9055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La mayor protecci\u00f3n del lobo es una decisi\u00f3n ideol\u00f3gica muy lesiva para los intereses ganaderos de la provincia de Le\u00f3n - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"La organizaci\u00f3n agraria ASAJA rechaza con la m\u00e1xima contundencia el acuerdo adoptado en el d\u00eda de ayer por el Gobierno y determinadas comunidades\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La mayor protecci\u00f3n del lobo es una decisi\u00f3n ideol\u00f3gica muy lesiva para los intereses ganaderos de la provincia de Le\u00f3n - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La organizaci\u00f3n agraria ASAJA rechaza con la m\u00e1xima contundencia el acuerdo adoptado en el d\u00eda de ayer por el Gobierno y determinadas comunidades\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-05T09:33:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-12T12:37:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/paisaje_monta\u00f1a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon\",\"name\":\"La mayor protecci\u00f3n del lobo es una decisi\u00f3n ideol\u00f3gica muy lesiva para los intereses ganaderos de la provincia de Le\u00f3n - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/paisaje_monta\u00f1a.jpg\",\"datePublished\":\"2021-02-05T09:33:29+00:00\",\"dateModified\":\"2021-02-12T12:37:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"La organizaci\u00f3n agraria ASAJA rechaza con la m\u00e1xima contundencia el acuerdo adoptado en el d\u00eda de ayer por el Gobierno y determinadas comunidades\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/paisaje_monta\u00f1a.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/paisaje_monta\u00f1a.jpg\",\"width\":2500,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La mayor protecci\u00f3n del lobo es una decisi\u00f3n ideol\u00f3gica muy lesiva para los intereses ganaderos de la provincia de Le\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La mayor protecci\u00f3n del lobo es una decisi\u00f3n ideol\u00f3gica muy lesiva para los intereses ganaderos de la provincia de Le\u00f3n - ASAJA Le\u00f3n","description":"La organizaci\u00f3n agraria ASAJA rechaza con la m\u00e1xima contundencia el acuerdo adoptado en el d\u00eda de ayer por el Gobierno y determinadas comunidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon","og_locale":"es_ES","og_type":"article","og_title":"La mayor protecci\u00f3n del lobo es una decisi\u00f3n ideol\u00f3gica muy lesiva para los intereses ganaderos de la provincia de Le\u00f3n - ASAJA Le\u00f3n","og_description":"La organizaci\u00f3n agraria ASAJA rechaza con la m\u00e1xima contundencia el acuerdo adoptado en el d\u00eda de ayer por el Gobierno y determinadas comunidades","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2021-02-05T09:33:29+00:00","article_modified_time":"2021-02-12T12:37:03+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/paisaje_monta\u00f1a.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon","name":"La mayor protecci\u00f3n del lobo es una decisi\u00f3n ideol\u00f3gica muy lesiva para los intereses ganaderos de la provincia de Le\u00f3n - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/paisaje_monta\u00f1a.jpg","datePublished":"2021-02-05T09:33:29+00:00","dateModified":"2021-02-12T12:37:03+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"La organizaci\u00f3n agraria ASAJA rechaza con la m\u00e1xima contundencia el acuerdo adoptado en el d\u00eda de ayer por el Gobierno y determinadas comunidades","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/paisaje_monta\u00f1a.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/paisaje_monta\u00f1a.jpg","width":2500,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-mayor-proteccion-del-lobo-es-una-decision-ideologica-muy-lesiva-para-los-intereses-ganaderos-de-la-provincia-de-leon#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"La mayor protecci\u00f3n del lobo es una decisi\u00f3n ideol\u00f3gica muy lesiva para los intereses ganaderos de la provincia de Le\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12042"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=12042"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12042\/revisions"}],"predecessor-version":[{"id":12043,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12042\/revisions\/12043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/9055"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=12042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=12042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=12042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}