{"id":12170,"date":"2021-03-12T11:35:17","date_gmt":"2021-03-12T10:35:17","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=12170"},"modified":"2021-03-15T19:49:06","modified_gmt":"2021-03-15T18:49:06","slug":"las-seis-noticias-agrarias-de-la-semana-12-03-2021","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 12\/03\/2021"},"content":{"rendered":"\n<h6><strong>Seguro de vi\u00f1edo, Juan Carlos Su\u00e1rez Qui\u00f1ones, coeficiente de rendimientos de cultivos herb\u00e1ceos, PIB Castilla y Le\u00f3n, Subdelegado del Gobierno en Le\u00f3n, actuaciones de eficiencia energ\u00e9tica en explotaciones agropecuarias<\/strong><\/h6>\n<ol>\n<li>\n<h6>Los viticultores disponen hasta el 25 de marzo de\u00a0 plazo para suscribir el SEGURO DE VI\u00d1EDO que cubre tambi\u00e9n da\u00f1os de <strong><u>HELADAS<\/u><\/strong>. En otra modalidad de seguro, que no cubre los da\u00f1os de heladas, pero cubre mayormente pedrisco, el plazo est\u00e1 abierto hasta el 30 de abril. Los seguros agrarios se contratan con Agroseguro con la mediaci\u00f3n como tomadores de ASAJA y otras organizaciones profesionales agrarias.<\/h6>\n<\/li>\n<li>\n<h6>El presidente de la Junta de Castilla y Le\u00f3n, Alfonso Fern\u00e1ndez Ma\u00f1ueco, firm\u00f3 el 4 de marzo la delegaci\u00f3n del \u00e1rea de\u00a0 Agricultura, Ganader\u00eda y Desarrollo Rural al consejero de Fomento y Medio Ambiente, <strong>Juan Carlos Su\u00e1rez Qui\u00f1ones<\/strong>, hasta que Jes\u00fas Julio Carnero pueda incorporarse a sus funciones tras superar la Covid. El jefe del Ejecutivo auton\u00f3mico desea una pronta recuperaci\u00f3n al consejero de Agricultura, cuya evoluci\u00f3n es positiva pero sigue\u00a0ingresado en la Unidad de Cuidados Intensivos. Las dos consejer\u00edas comparten interlocutores, como las Organizaciones Profesionales Agrarias (OPAS) e intereses comunes, ya que\u00a0el Medio Ambiente tiene un peso espec\u00edfico en la negociaci\u00f3n de la nueva Pol\u00edtica Agraria Com\u00fan (PAC). Adem\u00e1s, el propio consejero ya gestion\u00f3 el \u00e1rea de Agricultura durante cuatro meses en la anterior legislatura.<\/h6>\n<\/li>\n<li>\n<h6>Para calcular el <strong>coeficiente de rendimientos de cultivos herb\u00e1ceos<\/strong> Agroseguro toma el hist\u00f3rico de 10 a\u00f1os. De cara al Plan de Seguros de 2021 se incorporan los a\u00f1os 2019 y 2020 y se sacan el 2009 y 2010. Dado que de los diez a\u00f1os que se toman como referencia no se tienen en cuenta ni el de mejor ni el de peor producci\u00f3n, se va a excluir el 2017 por ser el peor y el 2020 por ser el mejor. Estos nuevos c\u00e1lculos mejoran levemente los rendimientos respecto al periodo anterior.<\/h6>\n<\/li>\n<li>\n<h6>La agricultura fue el \u00fanico sector con crecimiento positivo y por lo tanto el que mejor se comport\u00f3 en el a\u00f1o 2019 en la formaci\u00f3n del <strong>Producto Interior Bruto de Castilla y Le\u00f3n<\/strong>. A ello contribuy\u00f3 las mejores cosechas por una climatolog\u00eda m\u00e1s favorable y un impacto del COVID19 menos negativo que en otros como la industria, la construcci\u00f3n o los servicios. El consumo dom\u00e9stico y la exportaci\u00f3n evitaron un desplome de los precios que no obstante tuvo sus ajustes en determinados sectores como el c\u00e1rnico y los vinos.<\/h6>\n<\/li>\n<li>\n<h6>La organizaci\u00f3n agraria ASAJA se reuni\u00f3 el pasado martes con el <strong>Subdelegado del Gobierno en Le\u00f3n<\/strong> y con el Jefe de Carreteras para manifestar el trastorno que ocasiona a los agricultores las restricciones a la hora de instalar los sistemas de riego modernizado en las partes de las parcelas afectadas por la zona de dominio p\u00fablico o servidumbre de las carreteras. Esta situaci\u00f3n se produce en las fincas que lindan con la cuneta de la carretera al no haber un camino agr\u00edcola del por medio. La normativa no permite tuber\u00edas de riego enterradas.<\/h6>\n<\/li>\n<li>\n<h6>El Consejo de Ministros ha aprobado el Real Decreto que regula el programa de ayudas para la realizaci\u00f3n de <strong>actuaciones de eficiencia energ\u00e9tica en explotaciones agropecuarias<\/strong>. Este programa, que cuenta con una dotaci\u00f3n de 30 millones de euros, favorecer\u00e1 el ahorro energ\u00e9tico y, con ello, la mejora de la competitividad del sector, as\u00ed como la utilizaci\u00f3n de las energ\u00edas renovables y la reducci\u00f3n de las emisiones de CO<sub>2<\/sub>, contribuyendo al cumplimiento del Plan Nacional Integrado de Energ\u00eda y Clima 2021-2030 que prev\u00e9 la necesidad de medidas de apoyo al ahorro energ\u00e9tico, instalaci\u00f3n de renovables y reducci\u00f3n de emisiones en el sector primario. Las ayudas cubrir\u00e1n hasta el 30% del coste necesario para la ejecuci\u00f3n del proyecto.<\/h6>\n<\/li>\n<\/ol>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguro de vi\u00f1edo, Juan Carlos Su\u00e1rez Qui\u00f1ones, coeficiente de rendimientos de cultivos herb\u00e1ceos, PIB Castilla y Le\u00f3n, Subdelegado del Gobierno en Le\u00f3n, actuaciones de eficiencia energ\u00e9tica en explotaciones agropecuarias Los viticultores disponen hasta el 25 de marzo de\u00a0 plazo para suscribir el SEGURO DE VI\u00d1EDO que cubre tambi\u00e9n da\u00f1os de HELADAS. En otra modalidad de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":8595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 12\/03\/2021 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Seguro de vi\u00f1edo, Juan Carlos Su\u00e1rez Qui\u00f1ones, coeficiente de rendimientos de cultivos herb\u00e1ceos, PIB Castilla y Le\u00f3n, Subdelegado del Gobierno en Le\u00f3n,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 12\/03\/2021 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Seguro de vi\u00f1edo, Juan Carlos Su\u00e1rez Qui\u00f1ones, coeficiente de rendimientos de cultivos herb\u00e1ceos, PIB Castilla y Le\u00f3n, Subdelegado del Gobierno en Le\u00f3n,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-12T10:35:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-15T18:49:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/vi\u00f1edo_oteros.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021\",\"name\":\"Las seis noticias agrarias de la semana - 12\/03\/2021 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/vi\u00f1edo_oteros.jpg\",\"datePublished\":\"2021-03-12T10:35:17+00:00\",\"dateModified\":\"2021-03-15T18:49:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Seguro de vi\u00f1edo, Juan Carlos Su\u00e1rez Qui\u00f1ones, coeficiente de rendimientos de cultivos herb\u00e1ceos, PIB Castilla y Le\u00f3n, Subdelegado del Gobierno en Le\u00f3n,\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/vi\u00f1edo_oteros.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/vi\u00f1edo_oteros.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 12\/03\/2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 12\/03\/2021 - ASAJA Le\u00f3n","description":"Seguro de vi\u00f1edo, Juan Carlos Su\u00e1rez Qui\u00f1ones, coeficiente de rendimientos de cultivos herb\u00e1ceos, PIB Castilla y Le\u00f3n, Subdelegado del Gobierno en Le\u00f3n,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 12\/03\/2021 - ASAJA Le\u00f3n","og_description":"Seguro de vi\u00f1edo, Juan Carlos Su\u00e1rez Qui\u00f1ones, coeficiente de rendimientos de cultivos herb\u00e1ceos, PIB Castilla y Le\u00f3n, Subdelegado del Gobierno en Le\u00f3n,","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2021-03-12T10:35:17+00:00","article_modified_time":"2021-03-15T18:49:06+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/vi\u00f1edo_oteros.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021","name":"Las seis noticias agrarias de la semana - 12\/03\/2021 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/vi\u00f1edo_oteros.jpg","datePublished":"2021-03-12T10:35:17+00:00","dateModified":"2021-03-15T18:49:06+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Seguro de vi\u00f1edo, Juan Carlos Su\u00e1rez Qui\u00f1ones, coeficiente de rendimientos de cultivos herb\u00e1ceos, PIB Castilla y Le\u00f3n, Subdelegado del Gobierno en Le\u00f3n,","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/vi\u00f1edo_oteros.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/02\/vi\u00f1edo_oteros.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-12-03-2021#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 12\/03\/2021"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12170"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=12170"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12170\/revisions"}],"predecessor-version":[{"id":12171,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12170\/revisions\/12171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8595"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=12170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=12170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=12170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}