{"id":12322,"date":"2021-05-03T13:47:17","date_gmt":"2021-05-03T11:47:17","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=12322"},"modified":"2021-05-06T13:50:46","modified_gmt":"2021-05-06T11:50:46","slug":"la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion","title":{"rendered":"La C.H.D. saca a informaci\u00f3n el embalse de \u201clas Cuezas\u201d, y anuncia el fin del trasvase del Esla al Carri\u00f3n"},"content":{"rendered":"\n<h6>El Bolet\u00edn Oficial de la Provincia de Le\u00f3n de hoy lunes 3 de mayo publica un anuncio de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero por el que se somete a informaci\u00f3n p\u00fablica el anteproyecto de regulaci\u00f3n adicional de la cuenca del Carri\u00f3n mediante la construcci\u00f3n de los embalses de las Cuezas, y su estudio de impacto ambiental.<\/h6>\n<h6>Si bien el proyecto de construcci\u00f3n de dos embalses de 55 hect\u00f3metros c\u00fabicos de capacidad, en principio apenas tiene incidencia en el territorio de la provincia de Le\u00f3n, afectando muy ligeramente al municipio de Sahag\u00fan, la importancia real viene determinada porque se justifica <strong>\u201cpor la importante reducci\u00f3n de las aportaciones reguladas procedentes del sistema Esla a trav\u00e9s del canal del trasvase Cea Carri\u00f3n\u201d<\/strong>. En definitiva, <u>la modernizaci\u00f3n de los sistemas de riego<\/u> y el <u>aporte de estos embalses<\/u> cubrir\u00edan en todo o en parte las necesidades de los regad\u00edos del Carri\u00f3n en Palencia y Valladolid, por lo que ser\u00eda prescindible el trasvase que todos los a\u00f1os se hace de Le\u00f3n a Palencia.<\/h6>\n<h6>Si bien salvo los a\u00f1os de importantes sequ\u00edas el trasvase al Carri\u00f3n no ha supuesto desatender las necesidades de los regantes leoneses que aprovechan las aguas del pantano de Ria\u00f1o, de cara a un futuro, con la totalidad de los nuevos regad\u00edos de Payuelos en funcionamiento, pueden producirse episodios de falta de recursos que, de continuar el trasvase, perjudiquen a los regantes leoneses.<\/h6>\n<h6>ASAJA de Le\u00f3n no tiene opini\u00f3n sobre esta obra que afecta a las provincias de Valladolid y Palencia, y no entra a valorar si otras alternativas podr\u00edan ser m\u00e1s eficientes y menos costosas. Pero s\u00ed valora positivamente que se aporten soluciones a los problemas de los regantes de Palencia y Valladolid que le hagan prescindir del agua de Le\u00f3n, algo que ya est\u00e1 previsto recoja el Plan Hidrol\u00f3gico del Duero que se encuentra en fase de elaboraci\u00f3n (este asunto figuraba en el Esquema de Temas Importantes aprobado por el Consejo del Agua de la Cuenca del Duero el pasado diciembre).<\/h6>\n<p>ASAJA. Le\u00f3n, 3 de mayo de 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Bolet\u00edn Oficial de la Provincia de Le\u00f3n de hoy lunes 3 de mayo publica un anuncio de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero por el que se somete a informaci\u00f3n p\u00fablica el anteproyecto de regulaci\u00f3n adicional de la cuenca del Carri\u00f3n mediante la construcci\u00f3n de los embalses de las Cuezas, y su estudio de impacto [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":9025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La C.H.D. saca a informaci\u00f3n el embalse de \u201clas Cuezas\u201d, y anuncia el fin del trasvase del Esla al Carri\u00f3n - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"El Bolet\u00edn Oficial de la Provincia de Le\u00f3n de hoy lunes 3 de mayo publica un anuncio de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero por el que se somete a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La C.H.D. saca a informaci\u00f3n el embalse de \u201clas Cuezas\u201d, y anuncia el fin del trasvase del Esla al Carri\u00f3n - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El Bolet\u00edn Oficial de la Provincia de Le\u00f3n de hoy lunes 3 de mayo publica un anuncio de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero por el que se somete a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-03T11:47:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-06T11:50:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/obras_Payuelos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion\",\"name\":\"La C.H.D. saca a informaci\u00f3n el embalse de \u201clas Cuezas\u201d, y anuncia el fin del trasvase del Esla al Carri\u00f3n - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/obras_Payuelos.jpg\",\"datePublished\":\"2021-05-03T11:47:17+00:00\",\"dateModified\":\"2021-05-06T11:50:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"El Bolet\u00edn Oficial de la Provincia de Le\u00f3n de hoy lunes 3 de mayo publica un anuncio de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero por el que se somete a\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/obras_Payuelos.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/obras_Payuelos.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La C.H.D. saca a informaci\u00f3n el embalse de \u201clas Cuezas\u201d, y anuncia el fin del trasvase del Esla al Carri\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La C.H.D. saca a informaci\u00f3n el embalse de \u201clas Cuezas\u201d, y anuncia el fin del trasvase del Esla al Carri\u00f3n - ASAJA Le\u00f3n","description":"El Bolet\u00edn Oficial de la Provincia de Le\u00f3n de hoy lunes 3 de mayo publica un anuncio de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero por el que se somete a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion","og_locale":"es_ES","og_type":"article","og_title":"La C.H.D. saca a informaci\u00f3n el embalse de \u201clas Cuezas\u201d, y anuncia el fin del trasvase del Esla al Carri\u00f3n - ASAJA Le\u00f3n","og_description":"El Bolet\u00edn Oficial de la Provincia de Le\u00f3n de hoy lunes 3 de mayo publica un anuncio de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero por el que se somete a","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2021-05-03T11:47:17+00:00","article_modified_time":"2021-05-06T11:50:46+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/obras_Payuelos.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion","name":"La C.H.D. saca a informaci\u00f3n el embalse de \u201clas Cuezas\u201d, y anuncia el fin del trasvase del Esla al Carri\u00f3n - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/obras_Payuelos.jpg","datePublished":"2021-05-03T11:47:17+00:00","dateModified":"2021-05-06T11:50:46+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"El Bolet\u00edn Oficial de la Provincia de Le\u00f3n de hoy lunes 3 de mayo publica un anuncio de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero por el que se somete a","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/obras_Payuelos.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/06\/obras_Payuelos.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-c-h-d-saca-a-informacion-el-embalse-de-las-cuezas-y-anuncia-el-fin-del-trasvase-del-esla-al-carrion#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"La C.H.D. saca a informaci\u00f3n el embalse de \u201clas Cuezas\u201d, y anuncia el fin del trasvase del Esla al Carri\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12322"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=12322"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12322\/revisions"}],"predecessor-version":[{"id":12323,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12322\/revisions\/12323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/9025"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=12322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=12322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=12322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}