{"id":12497,"date":"2021-07-23T09:27:54","date_gmt":"2021-07-23T07:27:54","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=12497"},"modified":"2021-07-23T09:27:56","modified_gmt":"2021-07-23T07:27:56","slug":"con-los-astures","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures","title":{"rendered":"Con los astures"},"content":{"rendered":"\n<h6>La prensa econ\u00f3mica de esta semana anunciaba el placed del Gobierno de Espa\u00f1a para la fusi\u00f3n entre Unicaja Banco y Liberbank, un paso m\u00e1s en la concentraci\u00f3n de entidades financieras iniciado al estallar la crisis de dos mil ocho y consecuencia de ello el proceso de reestructuraci\u00f3n de las antiguas cajas de ahorro. Cuando de nuevo se cambien los r\u00f3tulos de ambas entidades fusionadas, los leoneses y los asturianos tendremos la misma entidad financiera de referencia\u00a0 de entre las\u00a0 que han recogido la herencia de las cajas de ahorro, y no s\u00e9 si esto servir\u00e1 para algo, pero al menos no nos cobrar\u00e1n comisiones en los cajeros cuando vayamos a sacar dinero en los desplazamientos a la playa de San Lorenzo en Gij\u00f3n. Por tirar de memoria de la historia reciente de este tipo de entidades econ\u00f3micas, no hace tantos a\u00f1os, en ese inicio de la reestructuraci\u00f3n de las cajas de ahorro, el modelo que propon\u00eda el Gobierno de Castilla y Le\u00f3n era fusionar todas o todas las posibles dentro de la autonom\u00eda para ser m\u00e1s fuertes y competir en la globalizaci\u00f3n. La primera fusi\u00f3n que se atragant\u00f3 fue la de Caja Espa\u00f1a y Caja Duero, dos marcas de las que ya casi nadie se acuerda, donde se exhib\u00edan fuerzas de Le\u00f3n y Salamanca con la interferencia del poder pol\u00edtico de Valladolid. En aquel momento, contra su partido en el \u00e1mbito auton\u00f3mico, el alcalde de la capital leonesa, Francisco Fern\u00e1ndez, propon\u00eda un giro en las fusiones planteado la de Caja Espa\u00f1a con Caja Asturias, y no s\u00e9 si lo hac\u00eda por el convencimiento de que aportaba sinergias, o por fastidiar la estrategia mayoritaria que lo era tambi\u00e9n de los suyos, de las estructuras de su partido, el PSOE, en Valladolid.\u00a0 Despu\u00e9s de que nada saliera como estaba previsto, despu\u00e9s de que el Banco de Espa\u00f1a y el Gobierno apartaran para un lado a las autonom\u00edas, y de que se sanearan con recursos p\u00fablicos unas y otras entidades para cubrir los descubiertos en los cr\u00e9ditos del sector del ladrillo, Caja Espa\u00f1a y Caja Asturias convergen en la uni\u00f3n de Unicaja Banco y Liberbank, el proyecto de Paco Fern\u00e1ndez hecho realidad.<\/h6>\n<h6>*Art\u00edculo de opini\u00f3n de Jos\u00e9 Antonio Turrado publicado en La Nueva Cr\u00f3nica del viernes 23 de julio de 2021.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La prensa econ\u00f3mica de esta semana anunciaba el placed del Gobierno de Espa\u00f1a para la fusi\u00f3n entre Unicaja Banco y Liberbank, un paso m\u00e1s en la concentraci\u00f3n de entidades financieras iniciado al estallar la crisis de dos mil ocho y consecuencia de ello el proceso de reestructuraci\u00f3n de las antiguas cajas de ahorro. Cuando de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":12498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Con los astures - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"La prensa econ\u00f3mica de esta semana anunciaba el placed del Gobierno de Espa\u00f1a para la fusi\u00f3n entre Unicaja Banco y Liberbank, un paso m\u00e1s en la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con los astures - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La prensa econ\u00f3mica de esta semana anunciaba el placed del Gobierno de Espa\u00f1a para la fusi\u00f3n entre Unicaja Banco y Liberbank, un paso m\u00e1s en la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-23T07:27:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-23T07:27:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/LAGO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures\",\"name\":\"Con los astures - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/LAGO.jpg\",\"datePublished\":\"2021-07-23T07:27:54+00:00\",\"dateModified\":\"2021-07-23T07:27:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"La prensa econ\u00f3mica de esta semana anunciaba el placed del Gobierno de Espa\u00f1a para la fusi\u00f3n entre Unicaja Banco y Liberbank, un paso m\u00e1s en la\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/LAGO.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/LAGO.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con los astures\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con los astures - ASAJA Le\u00f3n","description":"La prensa econ\u00f3mica de esta semana anunciaba el placed del Gobierno de Espa\u00f1a para la fusi\u00f3n entre Unicaja Banco y Liberbank, un paso m\u00e1s en la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures","og_locale":"es_ES","og_type":"article","og_title":"Con los astures - ASAJA Le\u00f3n","og_description":"La prensa econ\u00f3mica de esta semana anunciaba el placed del Gobierno de Espa\u00f1a para la fusi\u00f3n entre Unicaja Banco y Liberbank, un paso m\u00e1s en la","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2021-07-23T07:27:54+00:00","article_modified_time":"2021-07-23T07:27:56+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/LAGO.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures","name":"Con los astures - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/LAGO.jpg","datePublished":"2021-07-23T07:27:54+00:00","dateModified":"2021-07-23T07:27:56+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"La prensa econ\u00f3mica de esta semana anunciaba el placed del Gobierno de Espa\u00f1a para la fusi\u00f3n entre Unicaja Banco y Liberbank, un paso m\u00e1s en la","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/LAGO.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/LAGO.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/con-los-astures#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Con los astures"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12497"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=12497"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12497\/revisions"}],"predecessor-version":[{"id":12499,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12497\/revisions\/12499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/12498"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=12497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=12497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=12497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}