{"id":12522,"date":"2021-07-30T09:10:51","date_gmt":"2021-07-30T07:10:51","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=12522"},"modified":"2021-08-10T12:06:12","modified_gmt":"2021-08-10T10:06:12","slug":"las-seis-noticias-agrarias-de-la-semana-30-07-2021","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 30\/07\/2021"},"content":{"rendered":"\n<h2><strong>Comit\u00e9 ejecutivo de Asaja de Le\u00f3n, Aimcra, contrato tipo de compraventa de uva, Alfonso Fern\u00e1ndez Ma\u00f1\u00faeco, granjas av\u00edcolas, Ministerio de Trabajo<\/strong><\/h2>\n<ol>\n<li>\n<h6>Ayer viernes se reuni\u00f3 el <strong>Comit\u00e9 Ejecutivo de ASAJA de Le\u00f3n <\/strong>en la oficina de dicha organizaci\u00f3n en Santa Mar\u00eda del P\u00e1ramo. Este \u00f3rgano de direcci\u00f3n de la principal asociaci\u00f3n agraria de la provincia trat\u00f3 sobre la propuesta del Plan Estrat\u00e9gico de la PAC para Espa\u00f1a y su impacto en la agricultura y ganader\u00eda de la provincia. Se valor\u00f3 tambi\u00e9n el estado de las cosechas, el incremento de los costes de producci\u00f3n, y los bajos precios que se pagan en sectores como el vacuno de leche.<\/h6>\n<\/li>\n<li>\n<h6>Los agricultores remolacheros que entregan su ra\u00edz a la empresa Azucarera han recibi\u00f3 estos d\u00edas una carta de la asociaci\u00f3n <strong>AIMCRA<\/strong> pidiendo que confirmen su deseo de pertenecer o no a dicha asociaci\u00f3n. Quienes no manifiesten lo contrario, permanecer\u00e1n como socios de la misma y se comprometen a un pago de 11 c\u00e9ntimos de euro\u00a0 por cada tonelada de remolacha entregada, cantidad que descontar\u00e1 Azucarera de las liquidaciones de la remolacha.<\/h6>\n<\/li>\n<li>\n<h6>En el Bolet\u00edn Oficial del Estado del 28 de julio se ha publicado una Oren del ministerio de Agricultura por la que se homologa el <strong>contrato tipo de compraventa de uva<\/strong> con destino a su transformaci\u00f3n para vino, que regir\u00e1 durante las tres pr\u00f3ximas campa\u00f1as vitivin\u00edcolas. Recordar que todas las operaciones de compraventa de uva tienen que estar previamente amparadas por un contrato firmado entre el productor y la bodega, contrato que ha de recoger las relaciones contractuales, particularmente el volumen de compra, el precio, calidades y forma y fecha de pago.<\/h6>\n<\/li>\n<li>\n<h6>El presidente de la Junta de Castilla y Le\u00f3n, <strong>Alfonso Fern\u00e1ndez Ma\u00f1ueco<\/strong>, recibi\u00f3 el pasado mi\u00e9rcoles en la sede de Presidencia a las organizaciones agrarias de \u00e1mbito auton\u00f3mico para tratar sobre las cuestiones agroganaderas de mayor actualidad. Entre las cuestiones abordadas, destacar las negociaciones de la PAC, el encarecimiento de materias primas utilizadas en la agricultura, los bajos precios en determinados subsectores, los ataques al sector agrario por parte de determinados ministros del Gobierno de Espa\u00f1a, y la dotaci\u00f3n de recursos para acometer una verdadera modernizaci\u00f3n del campo.<\/h6>\n<\/li>\n<li>\n<h6>El Bolet\u00edn Oficial del Estado del 28 de julio ha publicado el Real Decreto 637\/2021, de 27 de julio, por el que se establecen las <strong>normas b\u00e1sicas de ordenaci\u00f3n de las granjas av\u00edcolas<\/strong>. El sector av\u00edcola es un subsector ganadero de gran importancia en Espa\u00f1a que, fruto de la evoluci\u00f3n, tanto de la normativa como de la sociedad, ha ido cambiando y diversificando su actividad en los \u00faltimos a\u00f1os de modo notable.<\/h6>\n<\/li>\n<li>\n<h6><strong>Una vez m\u00e1s, el campo espa\u00f1ol se ha visto se\u00f1alado por el ministerio de Trabajo<\/strong>, en un nuevo intento por criminalizar a los agricultores. La Ministra y Vicepresidenta Segunda, Yolanda D\u00edaz, acaba de anunciar un Plan de la Inspecci\u00f3n de Trabajo y Seguridad Social para perseguir a aquellas empresas que no garanticen la seguridad de los trabajadores frente a posibles golpes de calor. ASAJA rechaza en\u00e9rgicamente esta forma de proceder que refleja una completa desconfianza y un profundo desconocimiento del sector agrario.<\/h6>\n<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Comit\u00e9 ejecutivo de Asaja de Le\u00f3n, Aimcra, contrato tipo de compraventa de uva, Alfonso Fern\u00e1ndez Ma\u00f1\u00faeco, granjas av\u00edcolas, Ministerio de Trabajo Ayer viernes se reuni\u00f3 el Comit\u00e9 Ejecutivo de ASAJA de Le\u00f3n en la oficina de dicha organizaci\u00f3n en Santa Mar\u00eda del P\u00e1ramo. Este \u00f3rgano de direcci\u00f3n de la principal asociaci\u00f3n agraria de la provincia [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":12523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 30\/07\/2021 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Comit\u00e9 ejecutivo de Asaja de Le\u00f3n, Aimcra, contrato tipo de compraventa de uva, Alfonso Fern\u00e1ndez Ma\u00f1\u00faeco, granjas av\u00edcolas, Ministerio de Trabajo Ayer\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 30\/07\/2021 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Comit\u00e9 ejecutivo de Asaja de Le\u00f3n, Aimcra, contrato tipo de compraventa de uva, Alfonso Fern\u00e1ndez Ma\u00f1\u00faeco, granjas av\u00edcolas, Ministerio de Trabajo Ayer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-30T07:10:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-10T10:06:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/OFICINA-STA-MARIA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021\",\"name\":\"Las seis noticias agrarias de la semana - 30\/07\/2021 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/OFICINA-STA-MARIA.jpg\",\"datePublished\":\"2021-07-30T07:10:51+00:00\",\"dateModified\":\"2021-08-10T10:06:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Comit\u00e9 ejecutivo de Asaja de Le\u00f3n, Aimcra, contrato tipo de compraventa de uva, Alfonso Fern\u00e1ndez Ma\u00f1\u00faeco, granjas av\u00edcolas, Ministerio de Trabajo Ayer\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/OFICINA-STA-MARIA.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/OFICINA-STA-MARIA.jpg\",\"width\":2500,\"height\":1487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 30\/07\/2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 30\/07\/2021 - ASAJA Le\u00f3n","description":"Comit\u00e9 ejecutivo de Asaja de Le\u00f3n, Aimcra, contrato tipo de compraventa de uva, Alfonso Fern\u00e1ndez Ma\u00f1\u00faeco, granjas av\u00edcolas, Ministerio de Trabajo Ayer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 30\/07\/2021 - ASAJA Le\u00f3n","og_description":"Comit\u00e9 ejecutivo de Asaja de Le\u00f3n, Aimcra, contrato tipo de compraventa de uva, Alfonso Fern\u00e1ndez Ma\u00f1\u00faeco, granjas av\u00edcolas, Ministerio de Trabajo Ayer","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2021-07-30T07:10:51+00:00","article_modified_time":"2021-08-10T10:06:12+00:00","og_image":[{"width":2500,"height":1487,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/OFICINA-STA-MARIA.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021","name":"Las seis noticias agrarias de la semana - 30\/07\/2021 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/OFICINA-STA-MARIA.jpg","datePublished":"2021-07-30T07:10:51+00:00","dateModified":"2021-08-10T10:06:12+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Comit\u00e9 ejecutivo de Asaja de Le\u00f3n, Aimcra, contrato tipo de compraventa de uva, Alfonso Fern\u00e1ndez Ma\u00f1\u00faeco, granjas av\u00edcolas, Ministerio de Trabajo Ayer","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/OFICINA-STA-MARIA.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/07\/OFICINA-STA-MARIA.jpg","width":2500,"height":1487},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/las-seis-noticias-agrarias-de-la-semana-30-07-2021#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 30\/07\/2021"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12522"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=12522"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12522\/revisions"}],"predecessor-version":[{"id":12524,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12522\/revisions\/12524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/12523"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=12522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=12522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=12522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}