{"id":12667,"date":"2021-10-01T13:15:22","date_gmt":"2021-10-01T11:15:22","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=12667"},"modified":"2021-10-01T13:35:50","modified_gmt":"2021-10-01T11:35:50","slug":"alubias","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias","title":{"rendered":"Alubias"},"content":{"rendered":"\n<h6>Los a\u00f1os con septiembre lluvioso complican sobremanera las labores de recolecci\u00f3n de las alubias, y en el momento que no levanta y llueve durante varios d\u00edas consecutivos, lo normal es una p\u00e9rdida o depreciaci\u00f3n importante del producto. Cuando esto ocurre es el tiempo de los seguros, aunque su condicionado y las consecuentes peritaciones no suelen dejar conforme a casi nadie, pero eso es otro tema. Para las alubias que se han recogido o que todav\u00eda se van a recoger en buenas condiciones, el a\u00f1o actual deber\u00eda de ser de buenos precios, porque es lo que marcan los mercados internacionales, pero por el contrario al agricultor leon\u00e9s se le est\u00e1n comprando como otros a\u00f1os. Como otros a\u00f1os es pagar la alubia blanca, de ri\u00f1\u00f3n por ejemplo, en el entorno de un euro el kilo, y la alubia pinta, la que ahora m\u00e1s se siembra, a algo menos de euro. Precios bajos y complicaciones agron\u00f3micas son las razones por las cuales los agricultores huyen de este cultivo, como de algunos otros, y se aferran a sembrar todas sus fincas de ma\u00edz. Porque hay industriales agroalimenatarios en nuestra provincia que no entienden de compromiso con nuestra tierra, y tienen por deporte maltratar a los productores locales y entenderse con grandes entradores que proporcionan mercanc\u00eda de peor calidad producida en cualquier parte del mundo. Pienso yo que la legumbre, que no tienen otro proceso de transformaci\u00f3n distinto al de limpiarlas, seleccionarlas y meterlas en una bolsa, deber\u00edan de tener margen para, sin vend\u00e9rselas m\u00e1s caras al consumidor, poder remunerar mejor a qui\u00e9n las produce. Como pienso que deber\u00eda de exigirse un etiquetado claro que nos permitiera a los consumidores saber de d\u00f3nde es lo que compramos, y pienso que los consumidores deber\u00edamos de ser m\u00e1s exigentes al elegir el producto mirando algo m\u00e1s que el precio de las ofertas. L\u00e1stima que un producto de tanta calidad no est\u00e9 al alcance de todos los leoneses, y no lo est\u00e1 porque no nos lo ofrecen, o nos lo ofrecen adulterado, que es todav\u00eda peor. L\u00e1stima que para comer buenas alubias haya que tener un pariente agricultor.<\/h6>\n<h6>*Art\u00edculo de opini\u00f3n de Jos\u00e9 Antonio Turrado publicado en La Nueva Cr\u00f3nica del viernes 1 de octubre de 2021<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Los a\u00f1os con septiembre lluvioso complican sobremanera las labores de recolecci\u00f3n de las alubias, y en el momento que no levanta y llueve durante varios d\u00edas consecutivos, lo normal es una p\u00e9rdida o depreciaci\u00f3n importante del producto. Cuando esto ocurre es el tiempo de los seguros, aunque su condicionado y las consecuentes peritaciones no suelen [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":12671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alubias - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Los a\u00f1os con septiembre lluvioso complican sobremanera las labores de recolecci\u00f3n de las alubias, y en el momento que no levanta y llueve durante varios\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alubias - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Los a\u00f1os con septiembre lluvioso complican sobremanera las labores de recolecci\u00f3n de las alubias, y en el momento que no levanta y llueve durante varios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-01T11:15:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-01T11:35:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/10\/IMG_6230.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias\",\"name\":\"Alubias - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/10\/IMG_6230.jpg\",\"datePublished\":\"2021-10-01T11:15:22+00:00\",\"dateModified\":\"2021-10-01T11:35:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Los a\u00f1os con septiembre lluvioso complican sobremanera las labores de recolecci\u00f3n de las alubias, y en el momento que no levanta y llueve durante varios\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/10\/IMG_6230.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/10\/IMG_6230.jpg\",\"width\":2500,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alubias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alubias - ASAJA Le\u00f3n","description":"Los a\u00f1os con septiembre lluvioso complican sobremanera las labores de recolecci\u00f3n de las alubias, y en el momento que no levanta y llueve durante varios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias","og_locale":"es_ES","og_type":"article","og_title":"Alubias - ASAJA Le\u00f3n","og_description":"Los a\u00f1os con septiembre lluvioso complican sobremanera las labores de recolecci\u00f3n de las alubias, y en el momento que no levanta y llueve durante varios","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2021-10-01T11:15:22+00:00","article_modified_time":"2021-10-01T11:35:50+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/10\/IMG_6230.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias","name":"Alubias - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/10\/IMG_6230.jpg","datePublished":"2021-10-01T11:15:22+00:00","dateModified":"2021-10-01T11:35:50+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Los a\u00f1os con septiembre lluvioso complican sobremanera las labores de recolecci\u00f3n de las alubias, y en el momento que no levanta y llueve durante varios","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/10\/IMG_6230.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/10\/IMG_6230.jpg","width":2500,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/alubias#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Alubias"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12667"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=12667"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12667\/revisions"}],"predecessor-version":[{"id":12668,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/12667\/revisions\/12668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/12671"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=12667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=12667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=12667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}