{"id":13052,"date":"2022-02-17T10:18:35","date_gmt":"2022-02-17T09:18:35","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=13052"},"modified":"2022-02-17T10:18:36","modified_gmt":"2022-02-17T09:18:36","slug":"valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan","title":{"rendered":"Valladolid ya tiene nuevas normas urban\u00edsticas territoriales mientras en Le\u00f3n los trabajos no avanzan"},"content":{"rendered":"\n<h6>El 16 de febrero se publicaron las <strong>Normas Urban\u00edsticas<\/strong> <strong>Territoriales<\/strong> en la provincia de Valladolid, a las cuales se acogen los municipios que no tienen normas propias. En la provincia de Le\u00f3n se sigue un proceso similar, pero por razones desconocidas no se avanza en su aprobaci\u00f3n, con el consiguiente perjuicio para los vecinos de los pueblos y en particular agricultores y ganaderos. Los responsables de este retraso son la Diputaci\u00f3n, a trav\u00e9s del \u00e1rea de asistencia a municipios que dirige Mat\u00edas Llorente, y la Delegaci\u00f3n Territorial de la\u00a0 Junta en Le\u00f3n.<\/h6>\n<h6>ASAJA. Le\u00f3n, 17 de febrero de 2022<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El 16 de febrero se publicaron las Normas Urban\u00edsticas Territoriales en la provincia de Valladolid, a las cuales se acogen los municipios que no tienen normas propias. En la provincia de Le\u00f3n se sigue un proceso similar, pero por razones desconocidas no se avanza en su aprobaci\u00f3n, con el consiguiente perjuicio para los vecinos de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":13053,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Valladolid ya tiene nuevas normas urban\u00edsticas territoriales mientras en Le\u00f3n los trabajos no avanzan - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"El 16 de febrero se publicaron las Normas Urban\u00edsticas Territoriales en la provincia de Valladolid, a las cuales se acogen los municipios que no tienen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valladolid ya tiene nuevas normas urban\u00edsticas territoriales mientras en Le\u00f3n los trabajos no avanzan - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El 16 de febrero se publicaron las Normas Urban\u00edsticas Territoriales en la provincia de Valladolid, a las cuales se acogen los municipios que no tienen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-17T09:18:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-17T09:18:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/02\/OBRAS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan\",\"name\":\"Valladolid ya tiene nuevas normas urban\u00edsticas territoriales mientras en Le\u00f3n los trabajos no avanzan - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/02\/OBRAS.jpg\",\"datePublished\":\"2022-02-17T09:18:35+00:00\",\"dateModified\":\"2022-02-17T09:18:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"El 16 de febrero se publicaron las Normas Urban\u00edsticas Territoriales en la provincia de Valladolid, a las cuales se acogen los municipios que no tienen\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/02\/OBRAS.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/02\/OBRAS.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valladolid ya tiene nuevas normas urban\u00edsticas territoriales mientras en Le\u00f3n los trabajos no avanzan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valladolid ya tiene nuevas normas urban\u00edsticas territoriales mientras en Le\u00f3n los trabajos no avanzan - ASAJA Le\u00f3n","description":"El 16 de febrero se publicaron las Normas Urban\u00edsticas Territoriales en la provincia de Valladolid, a las cuales se acogen los municipios que no tienen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan","og_locale":"es_ES","og_type":"article","og_title":"Valladolid ya tiene nuevas normas urban\u00edsticas territoriales mientras en Le\u00f3n los trabajos no avanzan - ASAJA Le\u00f3n","og_description":"El 16 de febrero se publicaron las Normas Urban\u00edsticas Territoriales en la provincia de Valladolid, a las cuales se acogen los municipios que no tienen","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2022-02-17T09:18:35+00:00","article_modified_time":"2022-02-17T09:18:36+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/02\/OBRAS.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan","name":"Valladolid ya tiene nuevas normas urban\u00edsticas territoriales mientras en Le\u00f3n los trabajos no avanzan - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/02\/OBRAS.jpg","datePublished":"2022-02-17T09:18:35+00:00","dateModified":"2022-02-17T09:18:36+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"El 16 de febrero se publicaron las Normas Urban\u00edsticas Territoriales en la provincia de Valladolid, a las cuales se acogen los municipios que no tienen","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/02\/OBRAS.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/02\/OBRAS.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/valladolid-ya-tiene-nuevas-normas-urbanisticas-territoriales-mientras-en-leon-los-trabajos-no-avanzan#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Valladolid ya tiene nuevas normas urban\u00edsticas territoriales mientras en Le\u00f3n los trabajos no avanzan"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/13052"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=13052"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/13052\/revisions"}],"predecessor-version":[{"id":13054,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/13052\/revisions\/13054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/13053"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=13052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=13052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=13052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}