{"id":13238,"date":"2022-04-08T16:06:47","date_gmt":"2022-04-08T14:06:47","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=13238"},"modified":"2022-04-18T12:42:30","modified_gmt":"2022-04-18T10:42:30","slug":"las-seis-noticias-agrarias-08-04-2022","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022","title":{"rendered":"Las seis noticias agrarias \u2013 08\/04\/2022"},"content":{"rendered":"\n<h2><strong>Junta General de Accionistas de Agroseguro<\/strong>, <strong>devoluci\u00f3n del impuesto especial de hidrocarburos<\/strong>, <strong>subvenciones a ganaderos de vacuno de leche<\/strong>, <strong>ordenanza reguladora de las plantaciones de \u00e1rboles<\/strong>, <strong>pantanos leoneses<\/strong> y <strong>revisi\u00f3n de la Directiva de 2010 sobre Emisiones Industriales<\/strong><\/h2>\n<p>&nbsp;<\/p>\n\n\n\n<ol>\n<li>\n<h6>La <strong>Junta General de Accionistas de Agroseguro<\/strong> celebrada el d\u00eda 31 de marzo, ha aprobado las Cuentas Anuales y el Informe de Gesti\u00f3n del ejercicio 2021, tomando raz\u00f3n de nuevos crecimientos en el seguro agrario. La contrataci\u00f3n de los seguros agrarios combinados ha cerrado el a\u00f1o con unas primas imputadas al ejercicio de 799,7 millones de euros y\u00a0con un valor de producci\u00f3n asegurada que en 2021 ha vuelto a alcanzar una cifra r\u00e9cord en la historia del seguro agrario, con 15.590 millones, es decir, un 2,4% m\u00e1s que en el a\u00f1o anterior.<\/h6>\n<\/li>\n<li>\n<h6>Desde el pasado 1 de abril, y hasta finales de a\u00f1o, se puede solicitar la <strong>devoluci\u00f3n del impuesto especial de hidrocarburos<\/strong> sobre las compras de gas\u00f3leo agr\u00edcola consumido en el a\u00f1o 2021 en la explotaci\u00f3n. La devoluci\u00f3n es de 63,71 euros por cada mil litros consumidos. Los beneficiarios tienen que aportar n\u00famero de cuenta, matr\u00edcula de los veh\u00edculos que han consumido el gas\u00f3leo, y facturas de compra.<\/h6>\n<\/li>\n<li>\n<h6>El Bolet\u00edn Oficial de la Provincia de Le\u00f3n del mi\u00e9rcoles 6 de abril ha publicado las <strong>subvenciones a ganaderos de vacuno de leche<\/strong> que realicen el control lechero oficial y mantengan animales inscritos en el libro geneal\u00f3gico de la raza frisona parda. La ayuda es de 6 euros por animal y una cantidad fija de 350 euros por explotaci\u00f3n.<\/h6>\n<\/li>\n<li>\n<h6>El Ayuntamiento de Villaobispo de Otero, en la comarca de Astorga, ha aprobado una <strong>ordenanza reguladora de las plantaciones de \u00e1rboles<\/strong> en su t\u00e9rmino municipal, y lo hace para evitar perjuicios a los peque\u00f1os agricultores y ganaderos con plantaciones indiscriminadas de chopos a distancias m\u00ednimas de los linderos. Seg\u00fan la ordenanza que est\u00e1 sometida a informaci\u00f3n p\u00fablica, los \u00e1rboles de gran porte, como son los chopos, guardar\u00e1n una distancia m\u00ednima de 12 metros respecto a los colindantes.<\/h6>\n<\/li>\n<li>\n<h6>Con los datos proporcionados el 6 de abril por la Confederaci\u00f3n Hidrogr\u00e1fica del Duero, los <strong>pantanos leoneses<\/strong> de la Cuenca del Duero se encontraban al 83% de su capacidad. El pantano de Ria\u00f1o y el del Porma se encontraban en un estado \u00f3ptimo para iniciar la campa\u00f1a de riego, mientras que en el de Barrios de Luna y en el de Villameca la situaci\u00f3n no es tan optimista. Villameca acumula tan solo 11,4 hect\u00f3metros c\u00fabicos, lo que representan el 57,2% de su capacidad total.<\/h6>\n<\/li>\n<li>La Comisi\u00f3n Europea public\u00f3 esta semana una <strong>revisi\u00f3n de su Directiva de 2010 sobre Emisiones Industriales<\/strong>. Si bien solo las instalaciones ganaderas m\u00e1s grandes de la UE se consideraron bajo su alcance durante la \u00faltima d\u00e9cada, la revisi\u00f3n propuso multiplicar por casi 10 el n\u00famero de granjas de ganado vacuno, porcino y av\u00edcolas dirigidas a granjas familiares y categorizarlas como \u00abinstalaciones agroindustriales\u00bb. Esta revisi\u00f3n obligar\u00eda a miles de explotaciones ganaderas familiares a cumplir con un costoso protocolo de emisiones dise\u00f1ado principalmente para las grandes empresas.<\/li>\n<\/ol>\n<h6>\u00a0<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Junta General de Accionistas de Agroseguro, devoluci\u00f3n del impuesto especial de hidrocarburos, subvenciones a ganaderos de vacuno de leche, ordenanza reguladora de las plantaciones de \u00e1rboles, pantanos leoneses y revisi\u00f3n de la Directiva de 2010 sobre Emisiones Industriales &nbsp; La Junta General de Accionistas de Agroseguro celebrada el d\u00eda 31 de marzo, ha aprobado las [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":8828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias \u2013 08\/04\/2022 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Junta General de Accionistas de Agroseguro, devoluci\u00f3n del impuesto especial de hidrocarburos, subvenciones a ganaderos de vacuno de leche, ordenanza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias \u2013 08\/04\/2022 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Junta General de Accionistas de Agroseguro, devoluci\u00f3n del impuesto especial de hidrocarburos, subvenciones a ganaderos de vacuno de leche, ordenanza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-08T14:06:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T10:42:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/04\/109_0964.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022\",\"name\":\"Las seis noticias agrarias \u2013 08\/04\/2022 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/04\/109_0964.jpg\",\"datePublished\":\"2022-04-08T14:06:47+00:00\",\"dateModified\":\"2022-04-18T10:42:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Junta General de Accionistas de Agroseguro, devoluci\u00f3n del impuesto especial de hidrocarburos, subvenciones a ganaderos de vacuno de leche, ordenanza\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/04\/109_0964.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/04\/109_0964.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias \u2013 08\/04\/2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias \u2013 08\/04\/2022 - ASAJA Le\u00f3n","description":"Junta General de Accionistas de Agroseguro, devoluci\u00f3n del impuesto especial de hidrocarburos, subvenciones a ganaderos de vacuno de leche, ordenanza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias \u2013 08\/04\/2022 - ASAJA Le\u00f3n","og_description":"Junta General de Accionistas de Agroseguro, devoluci\u00f3n del impuesto especial de hidrocarburos, subvenciones a ganaderos de vacuno de leche, ordenanza","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2022-04-08T14:06:47+00:00","article_modified_time":"2022-04-18T10:42:30+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/04\/109_0964.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022","name":"Las seis noticias agrarias \u2013 08\/04\/2022 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/04\/109_0964.jpg","datePublished":"2022-04-08T14:06:47+00:00","dateModified":"2022-04-18T10:42:30+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Junta General de Accionistas de Agroseguro, devoluci\u00f3n del impuesto especial de hidrocarburos, subvenciones a ganaderos de vacuno de leche, ordenanza","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/04\/109_0964.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/04\/109_0964.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-08-04-2022#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias \u2013 08\/04\/2022"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/13238"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=13238"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/13238\/revisions"}],"predecessor-version":[{"id":13251,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/13238\/revisions\/13251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8828"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=13238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=13238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=13238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}