{"id":13483,"date":"2022-07-01T08:50:46","date_gmt":"2022-07-01T06:50:46","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=13483"},"modified":"2022-07-08T10:15:18","modified_gmt":"2022-07-08T08:15:18","slug":"las-seis-noticias-agrarias-de-la-semana-01-07-2022","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 01\/07\/2022"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Decreto Ley 2\/2022<\/strong>, <strong>Presidenta de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero, Cristina Dan\u00e9s<\/strong>, <strong>Modernizaci\u00f3n del regad\u00edo de los Sectores VI y VII del P\u00e1ramo Bajo<\/strong>, <strong>Bases reguladoras<\/strong>, A<strong>utorizaci\u00f3n para nuevas plantaciones de vi\u00f1edo en 2022<\/strong>, 648.691 solicitudes \u00fanicas de ayudas de la Pol\u00edtica Agraria Com\u00fan<\/h2>\n\n\n\n<ol>\n<li>La Junta ha aproado un <strong>Decreto Ley 2\/2022<\/strong> que, entre otras cuestiones, establece nuevos criterios para la autorizaci\u00f3n de energ\u00edas renovables como son las e\u00f3licas y las fotovoltaicas. No se autorizar\u00e1n estas instalaciones en tierras de regad\u00edo, y tambi\u00e9n recomienda que las l\u00edneas de evacuaci\u00f3n sean soterradas. Estas restricciones no son una m\u00ednima parte de lo que hab\u00edan solicitado las organizaciones agrarias, que con car\u00e1cter general ped\u00edan la protecci\u00f3n el suelo agr\u00edcola y el soterramiento de todas las l\u00edneas de evacuaci\u00f3n.<\/li>\n<\/ol>\n<ol start=\"2\">\n<li>La <strong>presidenta de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero, Cristina Dan\u00e9s<\/strong>, anunci\u00f3 la pasada semana que dejaba el cargo para el que la nombr\u00f3 el Gobierno hace cuatro a\u00f1os. Su mandato ha estado marcado por un posicionamiento favorable a los de los grupos conservacionistas y alejado de los intereses de los regantes como principales usuarios del agua. Su \u00faltimo fracaso fue enviar al Gobierno un proyecto de Plan Hidrol\u00f3gico del Duero para el periodo 2022-2027, con el rechazo mayoritario del Consejo del Agua que ella misma presid\u00eda.<\/li>\n<\/ol>\n<ol start=\"3\">\n<li>El ministerio de Agricultura ha informado que ha finalizado las obras de <strong>modernizaci\u00f3n del regad\u00edo de los Sectores VI y VII del P\u00e1ramo Bajo<\/strong>, unas obras en las que interviene tambi\u00e9n la Junta de Castilla y Le\u00f3n y donde los regantes aporta su parte mediante un pr\u00e9stamo que solicita la Comunidad de Regantes. Con esta actuaci\u00f3n se completa al modernizaci\u00f3n\u00a0 integral del regad\u00edo del P\u00e1ramo Bajo de Le\u00f3n y Zamora, que ocupa 24.204 hect\u00e1reas y beneficia a 6.701 propietarios de tierras, que algunos son agricultores y otros arrendatarios.<\/li>\n<\/ol>\n<ol start=\"4\">\n<li>El Bolet\u00edn Oficial de Castilla y Le\u00f3n del 29 de junio public\u00f3 una\u00a0 Orden que tiene por objeto establecer las <strong>bases reguladoras<\/strong> de las ayudas que convoque la Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural destinadas a los titulares de explotaciones de ganado bovino, ovino y caprino para la compra de animales que tenga por objeto la reposici\u00f3n de efectivos en aquellas explotaciones sujetas a programas de control y erradicaci\u00f3n de enfermedades de los rumiantes.<\/li>\n<\/ol>\n<ol start=\"5\">\n<li>El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n\u00a0 ha comunicado a las comunidades aut\u00f3nomas las superficies a conceder por cada solicitud de <strong>autorizaci\u00f3n para nuevas plantaciones de vi\u00f1edo en 2022<\/strong>, que suman un total de 946 hect\u00e1reas, de las que el 74 % corresponden a viticultores titulares de peque\u00f1as y medianas explotaciones. Por comunidades aut\u00f3nomas, Castilla-La Mancha es la que cuenta con mayor superficie de nueva plantaci\u00f3n, 508 hect\u00e1reas, seguida de Castilla y Le\u00f3n, con 129 y Catalu\u00f1a, con 112.<\/li>\n<\/ol>\n<ol start=\"6\">\n<li>Los agricultores y ganaderos espa\u00f1oles han presentado en el Fondo Espa\u00f1ol de Garant\u00eda Agraria (FEGA) un total de 648.691 solicitudes \u00fanicas de ayudas de la Pol\u00edtica Agraria Com\u00fan (PAC), para el a\u00f1o 2022, una vez finalizado el plazo para presentarlas. Estas solicitudes \u00fanicas incluyen tanto las ayudas directas como las medidas de desarrollo rural, que se conceden por superficie o por cabeza de ganado. Las ayudas directas suponen el pago de 4.856 millones de euros, que comenzar\u00e1n a abonarse a partir del pr\u00f3ximo 16 de octubre. Este a\u00f1o, las solicitudes de ayuda afectan a 22.250.998,79 hect\u00e1reas.<\/li>\n<\/ol>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decreto Ley 2\/2022, Presidenta de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero, Cristina Dan\u00e9s, Modernizaci\u00f3n del regad\u00edo de los Sectores VI y VII del P\u00e1ramo Bajo, Bases reguladoras, Autorizaci\u00f3n para nuevas plantaciones de vi\u00f1edo en 2022, 648.691 solicitudes \u00fanicas de ayudas de la Pol\u00edtica Agraria Com\u00fan La Junta ha aproado un Decreto Ley 2\/2022 que, entre otras [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":13485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 01\/07\/2022 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Decreto Ley 2\/2022, Presidenta de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero, Cristina Dan\u00e9s, Modernizaci\u00f3n del regad\u00edo de los Sectores VI y VII del P\u00e1ramo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 01\/07\/2022 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Decreto Ley 2\/2022, Presidenta de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero, Cristina Dan\u00e9s, Modernizaci\u00f3n del regad\u00edo de los Sectores VI y VII del P\u00e1ramo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-01T06:50:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-08T08:15:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/placas-solares.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022\",\"name\":\"Las seis noticias agrarias de la semana - 01\/07\/2022 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/placas-solares.jpg\",\"datePublished\":\"2022-07-01T06:50:46+00:00\",\"dateModified\":\"2022-07-08T08:15:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Decreto Ley 2\/2022, Presidenta de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero, Cristina Dan\u00e9s, Modernizaci\u00f3n del regad\u00edo de los Sectores VI y VII del P\u00e1ramo\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/placas-solares.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/placas-solares.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 01\/07\/2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 01\/07\/2022 - ASAJA Le\u00f3n","description":"Decreto Ley 2\/2022, Presidenta de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero, Cristina Dan\u00e9s, Modernizaci\u00f3n del regad\u00edo de los Sectores VI y VII del P\u00e1ramo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 01\/07\/2022 - ASAJA Le\u00f3n","og_description":"Decreto Ley 2\/2022, Presidenta de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero, Cristina Dan\u00e9s, Modernizaci\u00f3n del regad\u00edo de los Sectores VI y VII del P\u00e1ramo","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2022-07-01T06:50:46+00:00","article_modified_time":"2022-07-08T08:15:18+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/placas-solares.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022","name":"Las seis noticias agrarias de la semana - 01\/07\/2022 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/placas-solares.jpg","datePublished":"2022-07-01T06:50:46+00:00","dateModified":"2022-07-08T08:15:18+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Decreto Ley 2\/2022, Presidenta de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero, Cristina Dan\u00e9s, Modernizaci\u00f3n del regad\u00edo de los Sectores VI y VII del P\u00e1ramo","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/placas-solares.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/placas-solares.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-01-07-2022#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 01\/07\/2022"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/13483"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=13483"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/13483\/revisions"}],"predecessor-version":[{"id":13484,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/13483\/revisions\/13484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/13485"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=13483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=13483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=13483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}