{"id":13820,"date":"2022-11-11T10:35:17","date_gmt":"2022-11-11T09:35:17","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=13820"},"modified":"2022-11-22T09:43:25","modified_gmt":"2022-11-22T08:43:25","slug":"las-seis-noticias-agrarias-de-la-semana-11-11-2022","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 11\/11\/2022"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Sistemas Importantes del Patrimonio Agr\u00edcola Mundial<\/strong>, <strong>M\u00e9todo de Estimaci\u00f3n Objetiva del Impuesto Sobre la Renta<\/strong>, P<strong>roductos vitivin\u00edcolas<\/strong>, <strong>Ayudar a los productores a hacer frente al alza de precios de los fertilizantes<\/strong>, <strong>Embalses leoneses<\/strong>, <strong>Juan Garc\u00eda-Gallardo<\/strong><\/h2>\n\n\n\n<ol>\n<li>La Diputaci\u00f3n de Le\u00f3n, la Universidad y el Gobierno, se han apuntado el tanto de que la FAO haya incorporado a la monta\u00f1a de Le\u00f3n dentro de los <strong>Sistemas Importantes del Patrimonio Agr\u00edcola Mundial<\/strong> (Simpam). Lo que no han dicho es en qu\u00e9 se beneficia Le\u00f3n de esta declaraci\u00f3n, y sobre todo en qu\u00e9 se van a benefician los ganaderos que ocupan estos territorios.<\/li>\n<\/ol>\n<ol start=\"2\">\n<li>El Gobierno ha informado de un proyecto de Orden por la que se desarrolla para el a\u00f1o 2023 el <strong>M\u00e9todo de Estimaci\u00f3n Objetiva del Impuesto Sobre la Renta<\/strong> de las Personas F\u00edsicas y el R\u00e9gimen Simplificado del IVA. Seg\u00fan este proyecto, los agricultores y ganaderos que tributan por \u201cm\u00f3dulos\u201d podr\u00e1n deducir, tanto por las compras de 2022 como por las de 2023, el 35 del coste del gas\u00f3leo y el 15% del coste de los fertilizantes.<\/li>\n<\/ol>\n<ol start=\"3\">\n<li>Espa\u00f1a export\u00f3 durante la reciente campa\u00f1a 2021\/22\u00a0 cerrada a 30 de julio un total de 2.880,8 millones de litros de <strong>productos vitivin\u00edcolas<\/strong>, con un descenso en los vol\u00famenes expedidos fronteras afuera del 3,6%. No obstante, los mayores precios unitarios registrados, especialmente en los \u00faltimos meses de campa\u00f1a, han propiciado que en este periodo la facturaci\u00f3n exterior vitivin\u00edcola alcance los 3.377,2 millones de euros, un 6% m\u00e1s, dejando el precio medio del producto espa\u00f1ol en 1,17 euros por litro.<\/li>\n<\/ol>\n<ol start=\"4\">\n<li>La Comisi\u00f3n Europea\u00a0 propuso un conjunto de medidas para <strong>ayudar a los productores a hacer frente al alza de precios de los fertilizantes<\/strong> y tratar de reducir la dependencia de las importaciones, en el contexto de la escasez y el encarecimiento como consecuencia de la guerra en Ucrania. Enumera una serie de buenas pr\u00e1cticas para ayudar a los agricultores, que incluyen<strong>la posible activaci\u00f3n de la reserva de crisis<\/strong> -dotada de 450 millones de euros al a\u00f1o-, el recurso a las ayudas de Estado o dar prioridad a los productores de fertilizantes a la hora de usar el gas en caso de una interrupci\u00f3n del suministro.<\/li>\n<\/ol>\n<ol start=\"5\">\n<li>Los <strong>embalses leoneses<\/strong> de la Cuenca del Duero han mejorado ligeramente el volumen de agua debido a los efectos de las precipitaciones de las \u00faltimas semanas, aunque est\u00e1n todav\u00eda muy por debajo de las medias habituales por esta \u00e9poca. Acumulan 365 hect\u00f3metros c\u00fabicos, el 28% de su capacidad. El pantano de Ria\u00f1o acumula 220 hect\u00f3metros, 105 el del Porma, 38 el de Barrios de Luna y tan solo 1 hect\u00f3metro el de Villameca.<\/li>\n<\/ol>\n<ol start=\"6\">\n<li>El vicepresidente de la Junta de Castilla y Le\u00f3n, <strong>Juan Garc\u00eda-Gallardo<\/strong>, junto con el consejero de Agricultura, Ganader\u00eda y Desarrollo Rural, Gerardo Due\u00f1as, se reuni\u00f3 el 9 de noviembre, con el comisario europeo de Agricultura y Desarrollo Rural, Janusz Wojciechowski. Durante el encuentro, celebrado en la sede de la Comisi\u00f3n Europea en Bruselas, Garc\u00eda-Gallardo le hizo entrega de un\u00a0manifiesto en el que se describen las prioridades de actuaci\u00f3n planteadas desde la Junta en materia de agricultura en Castilla y Le\u00f3n, as\u00ed como las posibles formas de cooperaci\u00f3n y las iniciativas desarrolladas por el Gobierno auton\u00f3mico, especialmente por la Consejer\u00eda de Agricultura.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Sistemas Importantes del Patrimonio Agr\u00edcola Mundial, M\u00e9todo de Estimaci\u00f3n Objetiva del Impuesto Sobre la Renta, Productos vitivin\u00edcolas, Ayudar a los productores a hacer frente al alza de precios de los fertilizantes, Embalses leoneses, Juan Garc\u00eda-Gallardo La Diputaci\u00f3n de Le\u00f3n, la Universidad y el Gobierno, se han apuntado el tanto de que la FAO haya incorporado [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":13823,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 11\/11\/2022 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Sistemas Importantes del Patrimonio Agr\u00edcola Mundial, M\u00e9todo de Estimaci\u00f3n Objetiva del Impuesto Sobre la Renta, Productos vitivin\u00edcolas, Ayudar a los\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 11\/11\/2022 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Sistemas Importantes del Patrimonio Agr\u00edcola Mundial, M\u00e9todo de Estimaci\u00f3n Objetiva del Impuesto Sobre la Renta, Productos vitivin\u00edcolas, Ayudar a los\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-11T09:35:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-22T08:43:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/11\/fertilizante.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022\",\"name\":\"Las seis noticias agrarias de la semana - 11\/11\/2022 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/11\/fertilizante.jpg\",\"datePublished\":\"2022-11-11T09:35:17+00:00\",\"dateModified\":\"2022-11-22T08:43:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Sistemas Importantes del Patrimonio Agr\u00edcola Mundial, M\u00e9todo de Estimaci\u00f3n Objetiva del Impuesto Sobre la Renta, Productos vitivin\u00edcolas, Ayudar a los\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/11\/fertilizante.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/11\/fertilizante.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 11\/11\/2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 11\/11\/2022 - ASAJA Le\u00f3n","description":"Sistemas Importantes del Patrimonio Agr\u00edcola Mundial, M\u00e9todo de Estimaci\u00f3n Objetiva del Impuesto Sobre la Renta, Productos vitivin\u00edcolas, Ayudar a los","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 11\/11\/2022 - ASAJA Le\u00f3n","og_description":"Sistemas Importantes del Patrimonio Agr\u00edcola Mundial, M\u00e9todo de Estimaci\u00f3n Objetiva del Impuesto Sobre la Renta, Productos vitivin\u00edcolas, Ayudar a los","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2022-11-11T09:35:17+00:00","article_modified_time":"2022-11-22T08:43:25+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/11\/fertilizante.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022","name":"Las seis noticias agrarias de la semana - 11\/11\/2022 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/11\/fertilizante.jpg","datePublished":"2022-11-11T09:35:17+00:00","dateModified":"2022-11-22T08:43:25+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Sistemas Importantes del Patrimonio Agr\u00edcola Mundial, M\u00e9todo de Estimaci\u00f3n Objetiva del Impuesto Sobre la Renta, Productos vitivin\u00edcolas, Ayudar a los","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/11\/fertilizante.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/11\/fertilizante.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-11-11-2022#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 11\/11\/2022"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/13820"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=13820"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/13820\/revisions"}],"predecessor-version":[{"id":13822,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/13820\/revisions\/13822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/13823"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=13820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=13820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=13820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}