{"id":1392,"date":"2016-03-01T00:00:00","date_gmt":"2016-02-29T23:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2016\/03\/01\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche\/"},"modified":"2017-11-15T09:37:56","modified_gmt":"2017-11-15T08:37:56","slug":"convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche","title":{"rendered":"CONVOCATORIA DE MANIFESTACI&#211;N\/CONCENTRACI&#211;N DE GANADEROS DE VACUNO DE LECHE"},"content":{"rendered":"<h2>Acto de protesta ante las Cortes de Castilla y Le&#243;n (Plaza Cortes de Castilla y Le&#243;n n&#186; 1 &#8211; Valladolid), que tendr&#225; lugar el MARTES 8 DE MARZO A LAS 12 DEL MEDIOD&#205;A<\/h2>\n<p style=\"text-align: center;\">\n<span style=\"color:#006400;\"><strong>CONVOCATORIA DE MANIFESTACI&#211;N\/CONCENTRACI&#211;N DE GANADEROS DE VACUNO DE LECHE<\/strong><\/span><\/p>\n<p>\n&#160;<\/p>\n<p>\nLe&#243;n, 1 de marzo de 2016.<\/p>\n<p>\n&#160;<\/p>\n<p>\nEstimado\/a amigo\/a:<\/p>\n<p>\n&#160;<\/p>\n<p style=\"text-align: justify;\">\nLas organizaciones que llevamos a cabo el pasado verano la Marcha Blanca, junto a otras que no lo hicieron y pueden sumarse ahora, hemos convocado un <strong>acto de protesta ante las Cortes de Castilla y Le&#243;n (Plaza Cortes de Castilla y Le&#243;n n&#186; 1 &#8211; Valladolid), que tendr&#225; lugar el MARTES 8 DE MARZO A LAS 12 DEL MEDIOD&#205;A<\/strong>. Se pretende sensibilizar a todos los partidos pol&#237;ticos con representaci&#243;n parlamentaria de los graves problemas del sector de la leche de vacuno, para lo cual mantendremos una reuni&#243;n con los representantes de los mismos en las propias Cortes. Para que se nos tome en serio, es importante un amplio respaldo del sector, acudiendo a la concentraci&#243;n todos los profesionales que os dedic&#225;is a la producci&#243;n de leche.<\/p>\n<p style=\"text-align: justify;\">\nLos graves problemas del vacuno de leche son hoy la principal preocupaci&#243;n de nuestra organizaci&#243;n, por lo que no escatimamos esfuerzos para hacer llegar propuestas, si es posible conjuntas, a todos los estamentos de la administraci&#243;n, a las industrias y a las cadenas de distribuci&#243;n. En este sentido, hemos ejercido tambi&#233;n la responsabilidad de firmar distintos acuerdos con las administraciones apoyando medidas que, si bien son sensatas, no han dado el resultado satisfactorio de subir los precios.<\/p>\n<p style=\"text-align: justify;\">\nNuestra principal reivindicaci&#243;n es que el sector obtenga unos precios rentables en la venta de la leche, que pueda producir al menos lo que se produc&#237;a en 2015 cuando estaba vigente el sistema de cuotas, y no renunciamos al derecho de los ganaderos espa&#241;oles a producir toda la leche que se consumen en Espa&#241;a, evitando las importaciones que tanto da&#241;o nos hacen y que no aportan nada a la econom&#237;a de nuestro pa&#237;s.<\/p>\n<p style=\"text-align: justify;\">\nEn principio no hay previsto un desplazamiento en autob&#250;s, no obstante, para confirmar esto y alg&#250;n cambio que pueda haber de &#250;ltima hora, es bueno que te pongas en contacto con nosotros o con tu cooperativa el d&#237;a antes.<\/p>\n<p>\n&#160;<\/p>\n<p>\nEsperando vernos en el acto al que te convocamos, recibe un saludo.<\/p>\n<p>\n&#160;<\/p>\n<p>\n&#160;<\/p>\n<p align=\"center\">\nFdo: Jos&#233; Antonio Turrado<\/p>\n<p align=\"center\">\nSecretario general<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acto de protesta ante las Cortes de Castilla y Le&#243;n (Plaza Cortes de Castilla y Le&#243;n n&#186; 1 &#8211; Valladolid), que tendr&#225; lugar el MARTES 8 DE MARZO A LAS 12 DEL MEDIOD&#205;A<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CONVOCATORIA DE MANIFESTACI&#211;N\/CONCENTRACI&#211;N DE GANADEROS DE VACUNO DE LECHE - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Acto de protesta ante las Cortes de Castilla y Le&#243;n (Plaza Cortes de Castilla y Le&#243;n n&#186; 1 - Valladolid), que tendr&#225; lugar el MARTES 8 DE MARZO A LAS 12 DEL MEDIOD&#205;A\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONVOCATORIA DE MANIFESTACI&#211;N\/CONCENTRACI&#211;N DE GANADEROS DE VACUNO DE LECHE - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Acto de protesta ante las Cortes de Castilla y Le&#243;n (Plaza Cortes de Castilla y Le&#243;n n&#186; 1 - Valladolid), que tendr&#225; lugar el MARTES 8 DE MARZO A LAS 12 DEL MEDIOD&#205;A\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-29T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T08:37:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche\",\"name\":\"CONVOCATORIA DE MANIFESTACI&#211;N\/CONCENTRACI&#211;N DE GANADEROS DE VACUNO DE LECHE - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2016-02-29T23:00:00+00:00\",\"dateModified\":\"2017-11-15T08:37:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Acto de protesta ante las Cortes de Castilla y Le&#243;n (Plaza Cortes de Castilla y Le&#243;n n&#186; 1 - Valladolid), que tendr&#225; lugar el MARTES 8 DE MARZO A LAS 12 DEL MEDIOD&#205;A\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONVOCATORIA DE MANIFESTACI&#211;N\/CONCENTRACI&#211;N DE GANADEROS DE VACUNO DE LECHE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONVOCATORIA DE MANIFESTACI&#211;N\/CONCENTRACI&#211;N DE GANADEROS DE VACUNO DE LECHE - ASAJA Le\u00f3n","description":"Acto de protesta ante las Cortes de Castilla y Le&#243;n (Plaza Cortes de Castilla y Le&#243;n n&#186; 1 - Valladolid), que tendr&#225; lugar el MARTES 8 DE MARZO A LAS 12 DEL MEDIOD&#205;A","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche","og_locale":"es_ES","og_type":"article","og_title":"CONVOCATORIA DE MANIFESTACI&#211;N\/CONCENTRACI&#211;N DE GANADEROS DE VACUNO DE LECHE - ASAJA Le\u00f3n","og_description":"Acto de protesta ante las Cortes de Castilla y Le&#243;n (Plaza Cortes de Castilla y Le&#243;n n&#186; 1 - Valladolid), que tendr&#225; lugar el MARTES 8 DE MARZO A LAS 12 DEL MEDIOD&#205;A","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2016-02-29T23:00:00+00:00","article_modified_time":"2017-11-15T08:37:56+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche","name":"CONVOCATORIA DE MANIFESTACI&#211;N\/CONCENTRACI&#211;N DE GANADEROS DE VACUNO DE LECHE - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2016-02-29T23:00:00+00:00","dateModified":"2017-11-15T08:37:56+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Acto de protesta ante las Cortes de Castilla y Le&#243;n (Plaza Cortes de Castilla y Le&#243;n n&#186; 1 - Valladolid), que tendr&#225; lugar el MARTES 8 DE MARZO A LAS 12 DEL MEDIOD&#205;A","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/convocatoria-de-manifestacinconcentracin-de-ganaderos-de-vacuno-de-leche#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"CONVOCATORIA DE MANIFESTACI&#211;N\/CONCENTRACI&#211;N DE GANADEROS DE VACUNO DE LECHE"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1392"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=1392"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1392\/revisions"}],"predecessor-version":[{"id":1785,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1392\/revisions\/1785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=1392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=1392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=1392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}