{"id":1405,"date":"2015-12-02T00:00:00","date_gmt":"2015-12-01T23:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2015\/12\/02\/anticipo-de-1-000-euros-por-hectrea-de-remolacha\/"},"modified":"2017-11-15T09:38:12","modified_gmt":"2017-11-15T08:38:12","slug":"anticipo-de-1-000-euros-por-hectrea-de-remolacha","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha","title":{"rendered":"ANTICIPO DE 1.000 EUROS POR HECT&#193;REA DE REMOLACHA"},"content":{"rendered":"<h2>Azucarera Iberia ha anunciado que adelantar&#225; hasta 1.000 euros por hect&#225;rea  de remolacha cultivada a los agricultores que a 21 de diciembre no hayan entregado todav&#237;a ra&#237;z en las f&#225;bricas, situaci&#243;n en las que se encuentran todos los remolacheros leoneses<\/h2>\n<p style=\"margin-left: 36pt; text-align: center;\">\n<span style=\"color:#006400;\"><strong>ANTICIPO DE 1.000 EUROS POR HECT&#193;REA DE REMOLACHA&#160;<\/strong><\/span><\/p>\n<p style=\"margin-left: 36pt; text-align: justify;\">\n<strong>Azucarera Iberia<\/strong> ha anunciado que adelantar&#225; hasta 1.000 euros por hect&#225;rea&#160; de remolacha cultivada a los agricultores que a 21 de diciembre no hayan entregado todav&#237;a ra&#237;z en las f&#225;bricas, situaci&#243;n en las que se encuentran todos los remolacheros leoneses. Este pago se efectuar&#237;a el 31 de diciembre, y para ello han de comunicarlo a Azucarera antes del 15 del presente mes, utilizando un formulario electr&#243;nico de la aplicaci&#243;n de la web, o a trav&#233;s de las organizaciones profesionales agrarias. ASAJA recomienda hacer uso de esta medida, que en principio no tienen ning&#250;n inconveniente, tampoco de car&#225;cter fiscal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Azucarera Iberia ha anunciado que adelantar&#225; hasta 1.000 euros por hect&#225;rea  de remolacha cultivada a los agricultores que a 21 de diciembre no hayan entregado todav&#237;a ra&#237;z en las f&#225;bricas, situaci&#243;n en las que se encuentran todos los remolacheros leoneses<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ANTICIPO DE 1.000 EUROS POR HECT&#193;REA DE REMOLACHA - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Azucarera Iberia ha anunciado que adelantar&#225; hasta 1.000 euros por hect&#225;rea de remolacha cultivada a los agricultores que a 21 de diciembre no hayan entregado todav&#237;a ra&#237;z en las f&#225;bricas, situaci&#243;n en las que se encuentran todos los remolacheros leoneses\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ANTICIPO DE 1.000 EUROS POR HECT&#193;REA DE REMOLACHA - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Azucarera Iberia ha anunciado que adelantar&#225; hasta 1.000 euros por hect&#225;rea de remolacha cultivada a los agricultores que a 21 de diciembre no hayan entregado todav&#237;a ra&#237;z en las f&#225;bricas, situaci&#243;n en las que se encuentran todos los remolacheros leoneses\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-01T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T08:38:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha\",\"name\":\"ANTICIPO DE 1.000 EUROS POR HECT&#193;REA DE REMOLACHA - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2015-12-01T23:00:00+00:00\",\"dateModified\":\"2017-11-15T08:38:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Azucarera Iberia ha anunciado que adelantar&#225; hasta 1.000 euros por hect&#225;rea de remolacha cultivada a los agricultores que a 21 de diciembre no hayan entregado todav&#237;a ra&#237;z en las f&#225;bricas, situaci&#243;n en las que se encuentran todos los remolacheros leoneses\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ANTICIPO DE 1.000 EUROS POR HECT&#193;REA DE REMOLACHA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ANTICIPO DE 1.000 EUROS POR HECT&#193;REA DE REMOLACHA - ASAJA Le\u00f3n","description":"Azucarera Iberia ha anunciado que adelantar&#225; hasta 1.000 euros por hect&#225;rea de remolacha cultivada a los agricultores que a 21 de diciembre no hayan entregado todav&#237;a ra&#237;z en las f&#225;bricas, situaci&#243;n en las que se encuentran todos los remolacheros leoneses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha","og_locale":"es_ES","og_type":"article","og_title":"ANTICIPO DE 1.000 EUROS POR HECT&#193;REA DE REMOLACHA - ASAJA Le\u00f3n","og_description":"Azucarera Iberia ha anunciado que adelantar&#225; hasta 1.000 euros por hect&#225;rea de remolacha cultivada a los agricultores que a 21 de diciembre no hayan entregado todav&#237;a ra&#237;z en las f&#225;bricas, situaci&#243;n en las que se encuentran todos los remolacheros leoneses","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2015-12-01T23:00:00+00:00","article_modified_time":"2017-11-15T08:38:12+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha","name":"ANTICIPO DE 1.000 EUROS POR HECT&#193;REA DE REMOLACHA - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2015-12-01T23:00:00+00:00","dateModified":"2017-11-15T08:38:12+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Azucarera Iberia ha anunciado que adelantar&#225; hasta 1.000 euros por hect&#225;rea de remolacha cultivada a los agricultores que a 21 de diciembre no hayan entregado todav&#237;a ra&#237;z en las f&#225;bricas, situaci&#243;n en las que se encuentran todos los remolacheros leoneses","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/anticipo-de-1-000-euros-por-hectrea-de-remolacha#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"ANTICIPO DE 1.000 EUROS POR HECT&#193;REA DE REMOLACHA"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1405"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=1405"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1405\/revisions"}],"predecessor-version":[{"id":1798,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1405\/revisions\/1798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=1405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=1405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=1405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}