{"id":14063,"date":"2023-02-03T12:33:07","date_gmt":"2023-02-03T11:33:07","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=14063"},"modified":"2023-02-03T12:33:10","modified_gmt":"2023-02-03T11:33:10","slug":"tres-mil-empleos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos","title":{"rendered":"<strong>Tres mil empleos<\/strong>"},"content":{"rendered":"\n<p>Esta semana de calma clim\u00e1tica, salvo por las fuertes heladas, por otra parte normales para la \u00e9poca, la naturaleza est\u00e1 haciendo su trabajo y d\u00eda a d\u00eda contin\u00faa llenando de agua nuestros pantanos. Los de la Cuenca del Duero est\u00e1n ya a m\u00e1s del sesenta por ciento de su capacidad, lo que sumado a las aportaciones de los dos pr\u00f3ximos meses, garantiza la campa\u00f1a de riego, y quiz\u00e1s hasta se llenen y puedan quedar reservas para el a\u00f1o siguiente. Haciendo la cuenta de la vieja, que se dice, con el agua de nuestros pantanos se regar\u00e1n unas ciento veinte mil hect\u00e1reas, que a una media de cuarenta hect\u00e1reas por agricultor, significa que garantizan el empleo de unas tres mil personas o familias. Nuestros cuatro pantanos de la cuenca del Duero, sumado al de la del Sil, son la mayor factor\u00eda de empleo de la provincia, con gran diferencia, aunque todav\u00eda haya gente que cuestione la idoneidad de estas obras p\u00fablicas, y aunque nadie reflexione sobre lo que esto significa y sobre lo que significar\u00eda si no existieran, si generaciones anteriores no hubieran hecho nada, si por los r\u00edos siguiera corriendo el agua libremente y nuestros campos fueran un erial permanente. Pero los pantanos leones no solamente dan trabajo a tres mil agricultores, se lo dan a decenas de empleados de las comunidades de regantes y de las propias confederaciones hidrogr\u00e1ficas, se lo dan a los empleados de multitud de empresas proveedoras de servicios al campo, y se lo dan a los empleados de multitud de empresas que nos compran y transforman lo que producimos los agricultores y ganaderos. Por eso, porque del agua de los pantanos depende el porvenir de una buena parte de los habitantes de esta tierra, miramos tanto al cielo cuando comenzamos un oto\u00f1o seco y los embalses siguen vac\u00edos, y por eso, cuando se van llenado y las monta\u00f1as est\u00e1n blancas, se respira tranquilo y se piensa en preparar las tierras y sembrarlas.\u00a0 Invertir en la pol\u00edtica del agua, pensando en generar riqueza, siempre ha sido y seguir\u00e1 siendo decisi\u00f3n acertada, al margen de gobiernos y hasta de r\u00e9gimen.<\/p>\n<p><em>*Art\u00edculo de opini\u00f3n de Jos\u00e9 Antonio Turrado para La Nueva Cr\u00f3nica del viernes 3 de febrero de 2023.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta semana de calma clim\u00e1tica, salvo por las fuertes heladas, por otra parte normales para la \u00e9poca, la naturaleza est\u00e1 haciendo su trabajo y d\u00eda a d\u00eda contin\u00faa llenando de agua nuestros pantanos. Los de la Cuenca del Duero est\u00e1n ya a m\u00e1s del sesenta por ciento de su capacidad, lo que sumado a las [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":10985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tres mil empleos - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Esta semana de calma clim\u00e1tica, salvo por las fuertes heladas, por otra parte normales para la \u00e9poca, la naturaleza est\u00e1 haciendo su trabajo y d\u00eda a d\u00eda\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tres mil empleos - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Esta semana de calma clim\u00e1tica, salvo por las fuertes heladas, por otra parte normales para la \u00e9poca, la naturaleza est\u00e1 haciendo su trabajo y d\u00eda a d\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-03T11:33:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-03T11:33:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2020\/02\/PANTANO_RIA\u00d1O_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos\",\"name\":\"Tres mil empleos - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2020\/02\/PANTANO_RIA\u00d1O_2.jpg\",\"datePublished\":\"2023-02-03T11:33:07+00:00\",\"dateModified\":\"2023-02-03T11:33:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Esta semana de calma clim\u00e1tica, salvo por las fuertes heladas, por otra parte normales para la \u00e9poca, la naturaleza est\u00e1 haciendo su trabajo y d\u00eda a d\u00eda\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2020\/02\/PANTANO_RIA\u00d1O_2.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2020\/02\/PANTANO_RIA\u00d1O_2.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tres mil empleos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tres mil empleos - ASAJA Le\u00f3n","description":"Esta semana de calma clim\u00e1tica, salvo por las fuertes heladas, por otra parte normales para la \u00e9poca, la naturaleza est\u00e1 haciendo su trabajo y d\u00eda a d\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos","og_locale":"es_ES","og_type":"article","og_title":"Tres mil empleos - ASAJA Le\u00f3n","og_description":"Esta semana de calma clim\u00e1tica, salvo por las fuertes heladas, por otra parte normales para la \u00e9poca, la naturaleza est\u00e1 haciendo su trabajo y d\u00eda a d\u00eda","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2023-02-03T11:33:07+00:00","article_modified_time":"2023-02-03T11:33:10+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2020\/02\/PANTANO_RIA\u00d1O_2.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos","name":"Tres mil empleos - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2020\/02\/PANTANO_RIA\u00d1O_2.jpg","datePublished":"2023-02-03T11:33:07+00:00","dateModified":"2023-02-03T11:33:10+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Esta semana de calma clim\u00e1tica, salvo por las fuertes heladas, por otra parte normales para la \u00e9poca, la naturaleza est\u00e1 haciendo su trabajo y d\u00eda a d\u00eda","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2020\/02\/PANTANO_RIA\u00d1O_2.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2020\/02\/PANTANO_RIA\u00d1O_2.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tres-mil-empleos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Tres mil empleos"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14063"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=14063"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14063\/revisions"}],"predecessor-version":[{"id":14064,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14063\/revisions\/14064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/10985"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=14063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=14063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=14063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}